{"id":9334,"date":"2009-12-22T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=9334"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"Rafael_Romero9334","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/Rafael_Romero9334\/","title":{"rendered":"Rafael Romero"},"content":{"rendered":"<p>Pregunta.- Sr. Romero:\u00bfQue espera que haga la Bolsa el pr\u00f3ximo a\u00f1o? \u00bfMe da una recomendaci\u00f3n para invertir a medio plazo?<\/p>\n<p>Respuesta.- Nosotros esperamos una bolsa moderadamente alcista. Un objetivo razonable estar\u00eda en el entorno de los 13.500 en nuestro Ibex. A medio plazo, siempre recomendarle una cartera muy diversificada y con un porcentaje de liquidez para aprovechar posibles oportunidades. Los sectores m\u00e1s defensivos como el gas, electricidad, agua, energ\u00eda, telecomunicaciones, sanidad, etc.. pueden comportarse mejor este a\u00f1o.<\/p>\n<p>P.- Sr. Rafael Romero, ya se sabe la influencia con la que act\u00faan los EEUU en los valores del d\u00f3lar, \u00bfc\u00f3mo cree usted que tender\u00e1n los valores del d\u00f3lar a actuar? \u00bfSubir\u00e1n con respecto al euro o bajara a\u00fan m\u00e1s?<\/p>\n<p>R.- Es dificil prever la evoluci\u00f3n del d\u00f3lar. Sin duda los americanos les viene bien la debilidad que han mantenido durante este a\u00f1o 2009, en parte motivadas por los efectos en su econom\u00eda de la crisis adem\u00e1s del paso estrat\u00e9gico de muchos pa\u00edses asi\u00e1ticos y productores de petr\u00f3leo de diversificar sus divisas en otras monedas. Pero ahora act\u00faan otras fuerzas: debilidad del euro tras la crisis de la deuda en Grecia y que podr\u00eda acelerarse con otros pa\u00edses en situaci\u00f3n complicada, adem\u00e1s de una gradual recuperaci\u00f3n de la econom\u00eda en EEUU. En fin, creo que el d\u00f3lar est\u00e1 encontrando su sitio natural de cotizaci\u00f3n, que podr\u00eda estar entre 1.30 y 1.50 para este a\u00f1o 2010 <\/p>\n<p>P.- Ferrovial..\u00bfqu\u00e9 tal? \u00bfnos va a sorprender para bien o para mal?<\/p>\n<p>R.- Ferrovial tras la gran ca\u00edda del a\u00f1o 2008, en el 2009 solo ha tenido alegr\u00edas para los inversores, con una subida anual del 47%. Que BAA haya ganado el recurso contra la comision de competencia britanica sobre la venta de 3 aeropuertos en reino unido le deja en una buena posici\u00f3n. Por tanto por ese lado es positivo. Adem\u00e1s esperamos una muy buena contribuci\u00f3n de Cintra con nuevos proyectos, tanto para la construcci\u00f3n como posteriores concesiones. Esperamos que vuelva pronto a cotizar por encima de 10 euros. Es un valor a mantener, aunque le costar\u00e1 superar la zona de 8.50 euros.<\/p>\n<p>P.- Me comentan que el potencial de crecimiento de Solaria es incuestionable. \u00bfEst\u00e1 de acuerdo?<\/p>\n<p>R.- Me gusta su pregunta.\u00bfIncuestionable?? Quien le haya dicho eso no merece mucha m\u00e1s atenci\u00f3n. Resulta que casi nadie compra en bolsa, que el 87% de las recomendaciones de analistas es de VENDER !!!, resulta que es un sector con incertidumbres, que vive de las subvenciones&#8230; Mire usted, mire el potencial &#8220;bastante m\u00e1s seguro&#8221; de unas Iberdrola o Telef\u00f3nica y si le gusta el sector, que a m\u00ed tambi\u00e9n me gusta, busque un fondo de inversi\u00f3n que con una gesti\u00f3n profesionalizada analice y diversifique su riesgo en valores de todo el mundo. <\/p>\n<p>P.- Si le tocara el Gordo de hoy, y fuera usted lego en econom\u00eda como lo soy yo y quisiera invertir en algo que d\u00e9 rentabilidad sin tener que preocuparse de absolutamente nada&#8230; \u00bfC\u00f3mo y en qu\u00e9 invertir\u00eda el premio? <\/p>\n<p>R.- Magn\u00edfica cuesti\u00f3n&#8230; Si quiero vivir de unas rentas y el horizonte de inversi\u00f3n es a medio plazo, dejar\u00eda una parte en fondos de gesti\u00f3n alternativa (que intentan mejorar la rentabilidad de la liquidez en cuenta corriente) para posibles necesidades futuras de liquidez y el resto a bolsa, a valores muy s\u00f3lidos con rentabilidad por dividendo, que me dan m\u00e1s que la renta fija y tengo la posibilidad de encontrarme dentro de cinco a\u00f1os con mucho m\u00e1s capital. <\/p>\n<p>P.- Hace unos d\u00edas le\u00ed en un Blog, en referencia a un gr\u00e1fico de Gamesa con Candlestick, que era posible que el valor rebotara fuertemente al alza, \u00bfes esto posible? \u00bfQu\u00e9 le parece a usted? Gamesa es un valor del que hablan bien los analistas, y sin embargo, no parece que se halla apuntado al rally alcista del Ibex-35, \u00bfpodemos esperar un rally de Gamesa o seguiremos viendo como el valor cae aun cuando el Ibex sube? Gracias.<\/p>\n<p>R.- Empiezo por decirle que Gamesa la tengo en mi cartera, pero s\u00ed, la verdad es que solo da sustos este a\u00f1o. Por an\u00e1lisis t\u00e9cnico no percibo un cambio claro de la actual tendencia, aunque s\u00ed es verdad que no tiene mala pinta en candlestick diarios. Vamos a ver como termina la semana&#8230; Por el momento, la acci\u00f3n se siente m\u00e1s influida por los planes de renovables fturos en EEUU, su potencial de crecimiento en China (con un plan muy agresivo de crecimiento en renovables), as\u00ed como en la incertidumbre en Espa\u00f1a ante las recientes decisiones de proyectos. En definitiva, el valor es para mantener y si se compra, con la apuesta m\u00e1s de medio plazo que un simple rebote t\u00e9cnico.<\/p>\n<p>P.- Buenos d\u00edas Rafael, \u00bfQue recomendar\u00eda a un amigo con acciones en La Seda?<\/p>\n<p>R.- Pues tras seis meses sin cotizar y cuando empiecen ya veremos&#8230; pues sinceramente, que guarde las acciones en un caj\u00f3n y las deje en herencia a sus hijos. Quiz\u00e1s alg\u00fan d\u00eda valgan m\u00e1s. Da la impresi\u00f3n que las medidas que se est\u00e1n tomando los \u00faltimos meses van en buen sentido, pero su sector es muy, muy complicado. <\/p>\n<p>P.- Buenos d\u00edas. Estoy planteandome comprar CEPSA, \u00bfqu\u00e9 opina al respecto?<\/p>\n<p>R.- No se lo recomiendo. El valor est\u00e1 en manos de dos accionistas de referencia, una sociedad de Emiratos Arabes y la francesa Total. La evoluci\u00f3n de la acci\u00f3n tras la venta del paquete del Santander es lamentable, (-67%) porque nadie tiene inter\u00e9s en comprar, sobre todo un cliente institucional que son los que mueven los mercados. Comprese Repsol si le gusta el sector. <\/p>\n<p>P.- Le ruego su opini\u00f3n sobre Grifols, una empresa que los consensos la suponen con una subida de un 50% y siempre se ve parada en su cotizaci\u00f3n. Gracias<\/p>\n<p>R.- Revisando, veo que el consenso de analistas estiman su precio en el entorno de 16 euros (un potencial del 25%), pero no obstante no debe olvidar que es un valor m\u00e1s de refugio. Si la bolsa va bien, como ha ido este a\u00f1o, pues este valor se frena. Si entramos en una fase de ca\u00eddas, el valor aportar\u00e1 a las carteras institucionales la guinda m\u00e1s defensiva y se ver\u00e1 beneficiado. Si tiene las acciones, espere. Por el lado de sus resultados, la compa\u00f1\u00eda est\u00e1 mejorando sus ingresos y sus m\u00e1rgenes. las proyecciones son de que sigan mejorando.<\/p>\n<p>P.- \u00bfQu\u00e9 valores calificaria como seguros o solidos en el Ibex para los primeros meses de 2010?<\/p>\n<p>R.- Seguro no hay nada&#8230; pero s\u00f3lido es un adjetivo al que implicar\u00eda a la mayor\u00eda de los valores del Ibex. Si buscamos una &#8220;cartera s\u00f3lida&#8221;, hay que hacerla con valores s\u00f3lidos de diferentes sectores, para diversificar. No podr\u00eda faltar Telef\u00f3nica y BBVA, Ferrovial y Gamesa, Repsol por el lado de la energ\u00eda junto a Iberdrola y Enag\u00e1s en el sector el\u00e9ctrico, y apuestas a mejora de la econom\u00eda con Arcelor e Inditex. <\/p>\n<p>P.- Dispongo de acciones del Banco Popular y del BBVA. En este momento valen casi la mitad. \u00bfCu\u00e1nto tiempo tendr\u00e9 que esperar para no perder dinero en la venta? meses, a\u00f1os&#8230; \u00bfEs mejor cambiar algunas de ellas por otro tipo de empresa? o \u00bfes mejor vender y dar por perdida la inversi\u00f3n? Gracias<\/p>\n<p>R.- Lo de vender para comprar otra cosa, siempre es una opci\u00f3n que hay que valorar, pero hay implicaciones fiscales, de diversificaci\u00f3n de riesgos en la cartera, de potencialidad a medio plazo, de cobro de dividendos&#8230; Si solo tiene acciones del BBVA y Popular, pues no me parece una cartera adecuada. Los bancos seguir\u00e1n con problemas durante 2010 y con bastante probabilidad se comporten peor que otros sectores. Popular est\u00e1 peor que el BBVA por tener su negocio concentrado en Espa\u00f1a, que no hay que decir m\u00e1s como est\u00e1 en comparaci\u00f3n con otras zonas. Si usted apuesta a que la recuperaci\u00f3n econ\u00f3mica global ser\u00e1 m\u00e1s r\u00e1pida que en Espa\u00f1a, habr\u00eda que apostar por valores que tengan negocio global.<\/p>\n<p>P.- Buenos d\u00edas, Sr. Romero, \u00bfQue opini\u00f3n le merece las acciones del Grupo San Jos\u00e9 y las de Iberia? gracias. <\/p>\n<p>R.- Iberia no parece &#8220;t\u00e9cnicamente&#8221; un mal momento de compra para postar por una subida hasta zonas de 2.25, pero su sector todav\u00eda est\u00e1 en una situaci\u00f3n complicada. Compre con un stop-loss ajustado. Por el lado del Grupo San Jos\u00e9 no la sigo, y veo en bloomberg que ning\u00fan analista opina sobre el valor&#8230; Eso es sin\u00f3nimo de estar &#8220;abandonada&#8221; por el mercado. No tocar&#8230; <\/p>\n<p>P.- Buenos d\u00edas , \u00bfc\u00f3mo ve ustedel futuro de Banco Sabadell? Gracias<\/p>\n<p>R.- Le pasa igualmente que al Popular. Negocio orientado en Espa\u00f1a, que pasa por dificultades. La recuperaci\u00f3n del inicio del ejercicio se ha desinflado y as\u00ed seguir\u00e1. La banca no es el sector para estar en el 2010 y los grandes inversores ya han hecho su movimiento. <\/p>\n<p>P.- \u00bfQu\u00e9 previsiones hay para el Banco Popular?<\/p>\n<p>R.- Situaci\u00f3n complicada en bolsa mientras que la econom\u00eda en Espa\u00f1a no despierte. Las recuperaciones tampoco ser\u00e1n muy fuertes. Mejor no tocar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La salida de la crisis est\u00e1 sirviendo de impulso a los mercados. Con una rentabilidad de doble d\u00edgito en lo que llevamos de a\u00f1o, la Bolsa espa\u00f1ola est\u00e1 dando muchas alegr\u00edas a los inversores. El director de Inversiones de Unicorp Patrimonio, Rafael Romero, ha respondido a las dudas de los lectores sobre la futura tendencia de la renta variable.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-9334","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/9334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=9334"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/9334\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=9334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=9334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=9334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}