{"id":8067,"date":"2011-01-20T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=8067"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"Javier_Hoyos8067","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/Javier_Hoyos8067\/","title":{"rendered":"Javier Hoyos"},"content":{"rendered":"<p>Pregunta.- Hola Javi! Soy una habitual de Carusel. Quer\u00eda daros la enhorabuena porque poco a poco cada d\u00eda vais enganchando a m\u00e1s y m\u00e1s audiencia. Gracias a Garrido y Sampe leyendo nuestras chorradas de facebook y twitter. Gracias por hacernos part\u00edcipes. \u00bfCu\u00e1ndo te haces el twitter y el facebook t\u00fa eh? te queremos ahi!! un abrazo<\/p>\n<p>Respuesta.- Hola Chabe. Me alegro que te guste el programa y que percibas el cambio con la entrada permanente de cuanto nos cont\u00e1is a trav\u00e9s de Facebook, twitter y dem\u00e1s. Desde luego cada d\u00eda nos sentimos m\u00e1s a gusto y lo pasamos mejor. Eso suele ser garant\u00eda de que los oyentes tambi\u00e9n lo haceis. De todos modos seguiremos evolucionando. En cuanto al twitter, es inminente, el otro d\u00eda en Carrusel garantic\u00e9 mi entrada en cuanto superemos los 50.000 amigos. Un abrazo tambi\u00e9n para ti.<\/p>\n<p>P.- Buenas Javi! No crees que la liga ya se ha acabado?con este Bar\u00e7a es dificil pensar que vaya a perder puntos y aunque el Madrid le ganara en el Bernabeu le seguiria sacando uno&#8230; tu como lo ves?soy madridista y estoy muy desilusionado&#8230;gracias<\/p>\n<p>R.- Hola Nature. Suele ser malo quedarse con la foto fija del momento. Es verdad que a d\u00eda de hoy el Madrid no depende de si mismo despu\u00e9s del tropiezo de Almer\u00eda pero quien te dice que el Barcelona no va a pinchar. Ayer mismo el Betis hizo humano a los de Guardiola. Es verdad que se trataba de la Copa pero seguro que no les ha gustado perder. Si los dem\u00e1s te ven accesible, ya has perdido ese punto de superioridad. El problema es que me temo que quien va a pagar los platos rotos es el Racing este fin de semana. En cuanto al Madrid, no desesperes. Nos escuchamos.<\/p>\n<p>P.- Javier enhorabuena por el programa, me alegr\u00e9 mucho del resultado del \u00faltimo EGM, soy de los que siempre escuchar\u00e9 la Ser y ning\u00fan falso martir me har\u00e1 pasarme a otra y menos a la cope. Solo era para darte muchos \u00e1nimos a ti y a tu equipo, y para preguntarte como ves a mi equipo el Sevilla FC. Muchas GRACIAS.<\/p>\n<p>R.- Hola Pepe. Apoyos como el tuyo siguen haciendo que merezca la pena hacer radio en la SER. Te lo agradezco. En cuanto a tu Sevilla, llev\u00e1is un comienzo de a\u00f1o muy positivo. Sin ir m\u00e1s lejos, el martes en la Copa muy bien ante el Villarreal. Aunque no todo funciona, da la impresi\u00f3n de que el tono general ha mejorado mucho. Por cierto, el que est\u00e1 que se sale es el Gran Kanoute. Un abrazo amigo.<\/p>\n<p>P.- Muy buenas y enhorabuena con el programa. \u00bfC\u00f3mo os encontr\u00e1is despu\u00e9s de varios meses haci\u00e9ndolo? \u00bfC\u00f3mo os dicen desde arriba que van las audiencias? Gracias y enhorabuena<\/p>\n<p>R.- Hola Sergio. Estamos encantados. Creo que los componentes de este nuevo tiempo de Carrusel estamos acabando la &#8220;pretemporada&#8221; y ya somos capaces de marcar el ritmo. El tono y el buen rollo en antena saltan a la vista, creo. \u00a1Que buenos por cierto Zipi y Zape, Salinas y Benjam\u00edn anoche en el Betis-Barsa! De los datos ya sabes que estamos de nuevo en estudio de EGM y que el primero creo sinceramente que fue muy bueno ratificando la posici\u00f3n de liderazgo para este nuevo Carrusel de siempre. Nos seguimos escuchando.<\/p>\n<p>P.- javier crees que la politica del athletic de bilbao de tener solo jugadores vascos o formados en el pais vasco es positova en los momentos actuales. gracias<\/p>\n<p>R.- Hola Txomin. Un abrazo. Aunque no te oculto que he tenido diferentes posicionamientos en alg\u00fan momento, creo que en l\u00edneas generales es positivo pues ayuda a formar con m\u00e1s facilidad el sentimiento de grupo tan necesario para poder competir. Siempre digo que el f\u00fatbo,l es un estado de \u00e1nimo y creo que al Athletic le resulta m\u00e1s f\u00e1cil que a otros. Tambi\u00e9n es verdad que eso encarece a jugadores que en otra situaci\u00f3n no ser\u00edan tan costosos. De momento la cosa funciona. Que bonito Castro amigo.<\/p>\n<p>P.- Hola Javi, oigo mucho eso de que la Premier tiene m\u00e1s nivel que la liga espa\u00f1ola, sin embargo, viendo un partido del Manchester el otro d\u00eda, les costaba dar m\u00e1s de 4 pases rasos seguidos \u00bfCrees t\u00fa tambi\u00e9n que la Premier tiene m\u00e1s nivel, o crees como yo que simplemente es un f\u00fatbol con menos centro del campo y transiciones m\u00e1s cortas, y por tanto de ida y vuelta? Un saludo, enhorabuena por Carrusel.<\/p>\n<p>R.- Hola Alberto. Creo que son campeonatos bien diferentes. El f\u00fatbol espa\u00f1ol se distingue, m\u00e1s ahora que nunca, por el tratamiento del bal\u00f3n buscando con criterio a un compa\u00f1ero mientras en la Premier es verdad que las transiciones son m\u00e1s cortas. Precisamente por ello, esos partidos de ida y vuelta vertiginosa son muchas veces tan bonitos. Para mi Liga y Premier son los puntales del f\u00fatbol actual en el que bueno ser\u00e1 recordar que el campe\u00f3n del mundo llega desde el &#8220;toque&#8221;. Nos seguimos escuchando.<\/p>\n<p>P.- Hola Javier, me gustar\u00eda saber 2 cosas acerca de Carrusel, por un lado si Tornadijo va a regresar alg\u00fan d\u00eda a Zorrilla para narrar alg\u00fan partido del Valladolid,porque \u00faltimamente parece que est\u00e1 m\u00e1s en Sevilla y por otro lado me gustar\u00eda saber si Francisco Jos\u00e9 Delgado &#8220;Pacoj\u00f3&#8221;, va ser el narrador de los partidos del Atl\u00e9tico, puesto que Romero narra los del Real Madrid, espero que as\u00ed sea, ya que es un periodista que lleva muchos a\u00f1os en la SER, y creo que es muy buen narrador no s\u00f3lo de baloncesto, sino tambi\u00e9n de f\u00fatbol.Gracias y os escuchar\u00e9 en los pocos ratos que tenga libres.<\/p>\n<p>R.- Hola Rober. En referencia a la primera Torna es uno de los narradores clave de Carrusel y por ello se mueve por un mont\u00f3n de campos. Lo de Sevilla tiene mucho que ver con lo bien que debe tratarle Santi Ortega. En cuanto a Pacoj\u00f3 es un monstruo de la narraci\u00f3n, estoy totalmente de acuerdo contigo. Espero que tengas m\u00e1s tiempo libre y que nos sigamos escuchando.<\/p>\n<p>P.- Hola Javi, mi m\u00e1s sincera enhorabuena por tu gran Carrusel y por lo bien que te has adaptado. S\u00f3lo encuentro una pega al programa, que no se hace practicamente caso al f\u00fatbol internacional. Bruno es el chico de las estad\u00edticas pero es recomendable tener a un especialista de verdad s\u00f3lo para el f\u00fatbol internacional y seguramente en la Cadena Ser tendreis alguno que de m\u00e1s fuerza en este sentido a un Carrusel algo hu\u00e9rfano en esto. Saludos<\/p>\n<p>R.- Hola Bankero internacional. \u00a1Vaya nombre en este momento!. Me parece que el f\u00fatbol internacional es muy importante por elllo, aunque parece que deberemos mejorar a tenor de lo que me dices, hemos optado por seguir contando con el n\u00famero 1, Maldini, y apoyarle con otro estrella como Bruno que, como sabes, es adem\u00e1s quien hace ahora ese programazo llamado PLAY FUTBOL que puedes escuchar en la web de la Cadena Ser. De todos modos, tomo nota y tratar\u00e9 de mejorar ese asunto. Nos o\u00edmos y muchas gracias.<\/p>\n<p>P.- Claramente vais mejorando semana a semana. \u00bfC\u00f3mo llev\u00e1is toda la presi\u00f3n medi\u00e1tica negativa que hab\u00e9is tenido que soportar todo este tiempo? Javi, t\u00fa despu\u00e9s de cuatro meses de pelea(en el mejor sentido de la palabra) c\u00f3mo lo llevas? Un abrazo<\/p>\n<p>R.- Hola Pozas. Gracias por tu apoyo. Mira la verdad es que, sobre todo al comienzo, seguramente con l\u00f3gica por lo sucedido, tengo que reconocer que la presi\u00f3n era muy importante pero a mi como responsable del equipo me tocaba poner en marcha un nuevo tiempo del Carrusel de siempre y a eso me he dedicado. Estamos pas\u00e1ndolo cada d\u00eda mejor y sinceramente creo que se nota en antena donde casi sin darnos cuenta hemos incorporado un mont\u00f3n de novedades atendiendo a muchas de las promesas que hicimos a nuestra llegada. La mejora contin\u00faa en un Carrusel que no para y que quiere seguir haciendo honor a su historia pero en una permanente mirada al futuro. En cuanto a mi, lo llevo maravillosamente bien sobre todo porque se que al otro lado sois much\u00edsim@s los oyentes. Un abrazo.<\/p>\n<p>P.- A lo visto, madrid se quedara sin titulo.. chocando con un Barcelona que lo supera en todos sus juegos definitorios&#8230;Florentino asumira las consecuencias de sus malas (y caprichosas)decisiones y renunciara&#8230; o otra vez cumpara al entrenador&#8230; quizas haga algo nuevo este a\u00f1o&#8230; me supongo que obtar\u00e1 por votar a Valdano. Y prometera que otra supuesta ficha magica(Llorente si paga lo suficiente), (Rooney si quiere ayudar una vez m\u00e1s al manchester y pagarle a un jugador que ya resulta mas caro que su rendimiento en los proximos 2 o 3 a\u00f1os)&#8230;..Digame usted, su opinion. dimitira Florentino o solucion magica&#8230;<\/p>\n<p>R.- Hola Geronimo. A mi me parece que a\u00fan queda mucha Liga y todav\u00eda caben las sorpresas por dif\u00edcil que parezca. Dicho esto, me da la impresi\u00f3n que los \u00f3rdagos permanentes de Mourinho ante Florentino est\u00e1n creando un clima dif\u00edcil de superar si los resultados no le dan la vuelta. Es bueno reflexionar antes de tomar decisiones presionado porque el Barcelona sea mejor. Mou era la receta m\u00e1gica y no acaba de arrancar aunque ser\u00e1 bueno recordar que las trayectorias no cambian de la noche a la ma\u00f1ana. Eso si, m\u00e1s all\u00e1 de fichajes extraordinarios, le recuerdo al Madrid y a su entrenador que tiene una grand\u00edsima cantera a la que har\u00eda bien en mirar y apoyar. Un abrazo.<\/p>\n<p>P.- Yo no te pregunto nada. Te mando todo mi apoyo y que sepas que vales mucho. Me encanta oir voces claras y j\u00f3venes. Espero sigas mucho tiempo y seas agradecido. Nunca se debe morder la mano que te dio de comer.<\/p>\n<p>R.- Hola Lola de Zaragoza. Pues yo te contesto Gracias de coraz\u00f3n. En cuanto a lo segundo, quien me conoce sabe bien de mi fidelidad en un mundo en el que no siempre se encuentra. Puedes estar segura. Nos seguimos escuchando. Por cierto, \u00e1nimo al Zaragoza.<\/p>\n<p>P.- Hola Javier, voy a preguntarte acerca de un equipo que conoces bien, el Racing, \u00bfC\u00f3mo valoras la llegada del grupo inversor de Bahrein? Supongo que ayudar\u00e1 a la situaci\u00f3n econ\u00f3mica del Racing, pero, en mi opini\u00f3n, no s\u00e9 si a largo plazo esto va a ser beneficioso y el club realmente crecer\u00e1, y de paso preguntarte si sabes algo de los planes que tiene para el club dicho grupo inversor.Saludos <\/p>\n<p>R.- Hola Rober. Como seguramente conoces fui quien adelant\u00f3 la noticia que, creo sinceramente, es muy positiva para un Racing que es propiedad hasta el lunes de una empresa a la que hay que agradecer su apoyo pero que a estas alturas no tiene un clavel. Por ello la entrada de un nuevo propietario que, por lo que me cuentan, pretende hacer las cosas con criterio ha de ser bueno. Quiero creer que la llegada de Ali Syed puede ayudar al Racing, uno de los fundadores de la LIga y un cl\u00e1sico de primera a brillar m\u00e1s y mejor. En cuanto a planes concretos, me consta que la venta se ha acelerado para poder contratar alg\u00fan jugador que apuntale la plantilla en este mercado de invierno. Espero que den con la clave. Un abrazo amigo.<\/p>\n<p>P.- Hola Javier me encantar\u00eda preguntarle si el Bar\u00e7a necesita fichar por su corta plantilla.<\/p>\n<p>R.- Hola Samuel. Creo que aunque ha habido alg\u00fan error catedralicio, como dice Maldini en Carrusel, la pol\u00edtica de Guardiola y el Bar\u00e7a de afianzar s\u00f3lo aquello que no le da la cantera me encanta. La verdad es que no percibo esa necesidad a estas alturas. Un abrazo.<\/p>\n<p>P.- Buenas Javi, veo que Carrusel se supera semana tras semana, enhorabuena. Javi crees que la renovaci\u00f3n o no de Dani Alves por el Bar\u00e7a puede distraer u poco al equipo. Si la renovaci\u00f3n es al alza y se convierte en el 2 mejor pagado puede romper el equilibrio con el resto de jugadores?. Gracias y seguir as\u00ed.<\/p>\n<p>R.- Hola Manu. Es dif\u00edcil saber a ciencia cierta ese extremo pero no creo que Alves este de verdad dispuesto a romper su idilio barcelonista. Forzar para mejorar su contrato, es l\u00f3gico, creer que de verdad puedes llegar a romper, no lo creo y tampoco que vaya a distraerle. Un abrazo. Nos escuchamos.<\/p>\n<p>P.- Hoal Javi que tal ves al athletic este a\u00f1o?<\/p>\n<p>R.- Hola Gora Euskadi. Pues la verdad es que les veo bien, con una columna vertebral mucho m\u00e1s que razonable pero l\u00f3gicamente con alguna carencia. Sin entrar al por menor, echo en falta a un cerebro en el centro del campo que acompa\u00f1e al grand\u00edsimo Javi Mart\u00ednez as\u00ed como la excesiva dependencia de Fernando LLorente como elementos clave. De todos modos sigue estando al pie de Europa tras cerrar en Copa con un grand\u00edsimo papel ante el Bar\u00e7a.<\/p>\n<p>P.- ahora que estamos con el mundial de balonmano \u00bfno crees que seria necesario un equipo en madrid , tipo real madrid o atletico, para dar m\u00e1s rivalidad a esa liga y que apareciera en los medios mas?Porque aunque Ciudad Real esta dando mucho a este deporte falta la rivalidad madrid-barca. Y el papel de los nuestros en el mundial que te parece,.Un saludo y a seguir haciendo grande a carrusel y pensando en mejoras para entreternos a\u00fan m\u00e1s<\/p>\n<p>R.- Hola Cristobal. Como he dicho en varias ocasiones me encanta el balonmano que por cierto, practiqu\u00e9 sin gran \u00e9xito, y por ello estamos muy pendientes en Carrusel de lo que hace la selecci\u00f3n. Te digo que tengo p\u00e1lpito positivo esta tarde ante Francia. OJal\u00e1. En cuanto a la presencia de un equipo madrile\u00f1o en Asobal, estoy de acuerdo contigo en que ayudar\u00eda. Te puedo asegurar que seguimos currando para mejorar el Carrusel y para seguir pas\u00e1ndolo cada vez mejor. Por cierto, me encantar\u00eda poder dar &#8220;m\u00e1s bola&#8221; en Carrusel a los partidos de liga con unos horarios m\u00e1s l\u00f3gicos. Un abrazo.<\/p>\n<p>P.- \u00bfno piensas que los periodistas sobre todo de medios madrile\u00f1os est\u00e1is cayendo en las redes de Mouri\u00f1o y que se sirve de los medios para justificar el mal juego de su equipo ? <\/p>\n<p>R.- Hola amigo. No lo creo, pienso que Mou no acaba de dar con la tecla que permita al Madrid jugar bien de manera estable porque, entre otros, est\u00e1 empe\u00f1ado permanentemente en generar broncas absurdas muchas veces. Eso a veces distrae pero acaba cansando. Ha demostrado ser un gran entrenador por sus resultados pero le est\u00e1 costando ahora. Esperemos. Mientras, seguimos escuch\u00e1ndonos.<\/p>\n<p>P.- Que piensas sobre las quejas arbitrales del R. Madrid? Reclama malos arbitrajes continuados, \u00faltimo partido contra Almeria piden 3 posibles penaltis.( Recordemos partido de copa:Posible penalti a Ag\u00fcero, falta de X Alonso a Reyes al borde del area que supondr\u00eda su segunda amarilla, tarjeta roja no sacada a CR7 tras falta a Ujfalusi. No hubo queja por parte del R Madrid) Gracias.<\/p>\n<p>R.- Hola Davilo. Aprovecho tu pregunta para responder a las muchas que han llegado sobre este asunto. Soy bien claro: Yo creo que ni Madrid ni Barcelona tienen derecho a quejarse de las actuaciones arbitrales en general. Otra cosa es que que en situaciones concretas como el domingo en Almer\u00eda haya un claro perjuicio. Gracias a ti, nos seguimos escuchando. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Copa del Rey, Bar\u00e7a campe\u00f3n de invierno&#8230; Javi Hoyos hablar\u00e1 con vosotros en esta semana de los grandes acontecimientos deportivos<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-8067","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/8067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=8067"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/8067\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=8067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=8067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=8067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}