{"id":7388,"date":"2009-05-21T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=7388"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"Carlos_Boyero7388","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/Carlos_Boyero7388\/","title":{"rendered":"Carlos Boyero"},"content":{"rendered":"<p>Pregunta.- Hola Carlos, felicidades por los croissants de Cannes, me han parecido estupendos, sobre todo el de Lars Von Trier. C\u00f3mo se cabrearon los modernos con vosotros&#8230; \u00bfLe diste la hostia al final o no? jaja&#8230; Un fuerte abrazo!<\/p>\n<p>Respuesta.- Es algo peor que una pel\u00edcula infecta, es el enfermizo y sadomasoquista delirio de un tipo que est\u00e1 muy loco, convencido de que su impresentable provocaci\u00f3n constituye una obra de arte. Los modernos se merecen esta gratuita org\u00eda de automutilaciones. Que ellos disfruten viendo c\u00f3mo a una se\u00f1ora se corta el cl\u00edtoris o le destroza la polla a su marido. <\/p>\n<p>P.- Hola Carlos. \u00bfPodr\u00eda explicarme qu\u00e9 es eso de ver el cine sin prejuicios y de manera objetiva, como dice Almodovar? Me suena muy chistoso. Saludos<\/p>\n<p>R.- Yo tambi\u00e9n lo ignoro, pero cuando habla el Papa sus dogmas son cuesti\u00f3n de fe. Esta vez, Almod\u00f3var se ha equivocado en el amor infinito que van a profesar los espectadores franceses a &#8220;Los abrazos rotos&#8221;. Las cr\u00edticas de los peri\u00f3dicos &#8220;Le monde&#8221; y &#8220;Le Figaro&#8221; la han puesto a parir. Ser\u00e1 que de repente los franceses se han vuelto tan prejuiciosos y tan subjetivos como yo. <\/p>\n<p>P.- \u00bfEl mi\u00e9rcoles vas a estar en Roma? Tranquilo, que vas a ganar mucha pasta.<\/p>\n<p>R.- Ya me gustar\u00eda, pero no tengo entrada. Yo no tengo tan claro que vaya a ganar el Barcelona. El Manchester da mucho miedo. Pero ser\u00eda bonito que el equipo de Guardiola se llevara este a\u00f1o todos los t\u00edtulos. Ser\u00eda bueno para el f\u00fatbol y para la vida. <\/p>\n<p>P.- Buenos d\u00edas Carlos, \u00bfqu\u00e9 te parece la idea de Alex de la Iglesia de querer dirigir la Academia de Cine?Gracias y saludos<\/p>\n<p>R.- Nunca me imagin\u00e9 a \u00c1lex en esos cometidos tan acad\u00e9micos. No lo necesita. O sea, que tiene que creer que va a hacer algo positivo para el cine espa\u00f1ol. Jam\u00e1s he tenido relaci\u00f3n con la Academia ni con sus presidentes. Sospecho que la antipat\u00eda es mutua. Pero \u00c1lex de la Iglesia es un tipo con el que siempre me he llevado muy bien, alguien tan inteligente como divertido. Espero que ahora no cambie nuestra relaci\u00f3n. <\/p>\n<p>P.- \u00bfQu\u00e9 plan le seduce m\u00e1s? 1.-Tener un romance secreto con una vendedora de Mercedes con la que comparte psiquiatra. 2.- Tener como jefa a la doctora Cuddy, a quien adem\u00e1s puede vacilar a placer. 3.- Tener un cuarto secreto (que un t\u00edo te dio a cambio de que te encargues de su funeral) en el que fumar toda la mar\u00eda que desees mientras escuchas buenos discos y nadie del d\u00eda a d\u00eda puede estorbarte. Un saludo<\/p>\n<p>R.- No me tienta ninguna de las opciones, ya que mi vida afectiva y profesional funciona bastante bien desde hace tiempo. Pero disfruto mucho viendo todas esas opciones en las series maravillosas que se ha inventado HBO. <\/p>\n<p>P.- Se declara usted siempre de izquierdas y yo no soy qui\u00e9n para dudar de nada, pero ese ramalazo nihlista-individualista (san\u00edsimo) que le sale a menudo, recuerda mogoll\u00f3n a Max Striner. \u00bfLo conoce? \u00bfHa le\u00eddo algo? En caso de no conocerlo, no me diga eso de &#8220;no he leido nada, se\u00f1or Striner&#8221;. En este caso, el fulano lleva muchos a\u00f1os muerto. No es autobombo. Un saludo y gracias por muchas de las cosas que escribe.<\/p>\n<p>R.- Creo que se puede ser de izquierdas siendo nihilista e individualista. Las tres categor\u00edas entran en mi concepci\u00f3n del mundo. Tal vez usted y yo tengamos un concepto distinto de lo que significa ser de izquierdas. <\/p>\n<p>P.- Hola Carlos. Muchas veces intento ver una pelicula con mi novia pero por una cosa u otra siempre acabamos follando en el sofa. \u00bfNo te pasa algo parecido a menudo?<\/p>\n<p>R.- Procuro hacerlo antes para as\u00ed disfrutar relajadamente de ambas cosas. Deduzco que usted es muy joven felizmente, que no s\u00f3lo su amor es permanente, sino tambi\u00e9n sus erecciones. <\/p>\n<p>P.- Se\u00f1or Boyero, \u00bfser\u00eda posible que sus comentarios sobre el cine tuvieran menos dosis de esa avinagrada suficiencia que le hace parecer un or\u00e1culo infalible, poniendo en duda la seriedad de las opiniones de los que discrepan?<\/p>\n<p>R.- Imposible. \u00bfQu\u00e9 culpa tengo yo de que me hayan parido as\u00ed? <\/p>\n<p>P.- \u00bfD\u00f3nde se come mejor, all\u00ed en Francia o por aqu\u00ed en Espa\u00f1a?<\/p>\n<p>R.- Si tienes dinero, en ambos sitios. <\/p>\n<p>P.- Se\u00f1or Boyero, su careto me pone, \u00bfestoy enfermo?<\/p>\n<p>R.- Lo celebro, la bella tambi\u00e9n se sent\u00eda muy excitada con King Kong. Pero me comenta la persona que est\u00e1 transcribiendo este chat que es usted un se\u00f1or. Nuestro amor es imposible. <\/p>\n<p>P.- Buenos d\u00edas, Carlitos, \u00bfcu\u00e1l es la pelicula que m\u00e1s te ha sorprendido este a\u00f1o en Cannes? \u00bfY la que m\u00e1s te ha decepcionado?<\/p>\n<p>R.- Nuestra comunicaci\u00f3n va a ser imposible si me vuelve usted a llamar Carlitos. Pero esta ma\u00f1ana me siento generoso. No he visto hasta el momento ninguna obra maestra. Lo que m\u00e1s me ha interesado han sido las pel\u00edculas de Ang Lee, de Ken Loach, Michael Haneke, y una pel\u00edcula francesa de c\u00e1rceles que se titula &#8220;Un profeta&#8221;. La de Tarantino tambi\u00e9n se puede ver. Y fuera de concurso me han gustado mucho la de dibujos animados &#8220;Up&#8221; y una del cine independiente norteamericano que se llama &#8220;Precious&#8221;. Respeto mucho &#8220;\u00c1gora&#8221;, de Alejandro Amen\u00e1bar, pero esperaba algo m\u00e1s de ella. Decepciones no ha habido, ya que hay directores muy afamados de los que yo nunca espero nada bueno. Y, desgraciadamente, sigo sin equivocarme con ellos. <\/p>\n<p>P.- Tras la negativa de Wenger, \u00bfqu\u00e9 entrenador dar\u00e1 el s\u00ed al Madrid: Pellegrini, Mourinho o Hugo S\u00e1nchez? \u00bfT\u00fa a qui\u00e9n elegir\u00edas?<\/p>\n<p>R.- Pellegrini es el que m\u00e1s me gusta de los que usted cita. Pero como quiero creer en las utop\u00edas, a m\u00ed me har\u00eda feliz que Guardiola o Johan Cruyff entrenaran al Real Madrid. Algo tan deseable como imposible. <\/p>\n<p>P.- Buenos d\u00edas Carlos. Hoy sale en El Pa\u00eds que en 2008 se hicieron 173 pel\u00edculas en Espa\u00f1a, m\u00e1s que en EEUU. Muchas de ellas no se estrenaron, y otras fueron vistas por menos de 200 personas. Eso s\u00ed, todas ellas subvencionadas. \u00bfTanto poder tiene el lobby de los cineastas?<\/p>\n<p>R.- Esa es la prueba. Y ahora mucho m\u00e1s, ya que los productores han logrado colocar a su chica de ministra. <\/p>\n<p>P.- Muy buenas Carlos! Cu\u00e1l es tu m\u00e9todo para ver nos\u00e9cu\u00e1ntas pelis seguidas sin indigesti\u00f3n, mezclando anticristos con resnnais y con bastardos? Supongo que, siendo el enviado especial de El Pa\u00eds no hay forma de escapar, as\u00ed que cu\u00e9ntanos qu\u00e9 haces para procesarlo todo y mantener algo de serenidad al final del d\u00eda&#8230; <\/p>\n<p>R.- Estoy agotado f\u00edsica y mentalmente, me cuesta andar y caminar. No consigo dormir ni con somn\u00edferos. Llevo aqu\u00ed 10 d\u00edas y ya me siento demasiado mayor para estas cosas. Lo normal es que diga y escriba mogoll\u00f3n de tonter\u00edas. Me estoy planteando seriamente lo de ganarme la vida de otra forma. Y le juro que no soy fr\u00edvolo al afirmar esto. Mi problema es que siempre he hecho lo mismo a lo largo de mi vida. Mi problema es que no s\u00e9 hacer nada m\u00e1s. <\/p>\n<p>P.- \u00bfPor qu\u00e9 Aznar se empe\u00f1a en seguir martirizando nuestros sentidos con su presencia medi\u00e1tica?<\/p>\n<p>R.- A m\u00ed tambi\u00e9n me da mucha grima este se\u00f1or. Cuando gobernaba y ahora. Pero reconozco que a veces tiene gracia, como aquella vez en la que, con voz zarrapastrosa por el exceso et\u00edlico, afirmaba con chuler\u00eda paleol\u00edtica que ninguna ley le iba a obligar a \u00e9l a conducir sin haber tomado alcohol. Aznar encarna al facher\u00edo sin disfraces. Me cuesta mucho encontrar algo m\u00ednimamente fascinante en \u00e9l. Supongo que se ha hecho muy rico. Deber\u00eda conformarse con eso y no pasarse la vida dando la brasa a los que le birlaron las elecciones. O a la gente de su propio partido que intentan ser un poco m\u00e1s dem\u00f3cratas que \u00e9l. <\/p>\n<p>P.- Carlos, ha muerto Benedetti, ha muerto uno de los grandes, \u00bfqu\u00e9 te parece su obra? Creo que a partir de ahora se le empezar\u00e1 a valorar m\u00e1s. <\/p>\n<p>R.- Tiene poemas y novelas que me gustan, pero no soy un fan incondicional de su obra. Mi poeta sudamericano se llama C\u00e9sar Vallejo, no Benedetti. <\/p>\n<p>P.- Carlos, deber\u00edas haber ido a ver &#8220;Les abraces rotes&#8221; para contarnos qu\u00e9 dec\u00edan los otros cr\u00edticos de talla internacional de semejante tru\u00f1\u00edn con pelos y se\u00f1ales. Y otra cosa, Almod\u00f3var dice que prepara una de la Guerra Civil. \u00bfSabes si hab\u00eda travestis en aquella \u00e9poca? Abrazos sin romper. <\/p>\n<p>R.- Tiene usted una notable mala leche. Almod\u00f3var posee un talento extraordinario, y es el de vender inmejorablemente todo lo que hace. Imagino que lo de la memoria hist\u00f3rica le puede dar juego a se\u00f1or tan ancestralmente progresista. No me interesa ni el presente ni el futuro de Almod\u00f3var. S\u00ed algunas pel\u00edculas que ha hecho en el pasado, pero no muchas. <\/p>\n<p>P.- Muy buenas. He visto los v\u00eddeos desde Cannes, me parece que tiene un aspecto saludable. \u00bfSe encuentra mejor una vez abandonados viejos placeres?. Que valga la pena dejar los pesados compa\u00f1eros de viaje para llegar algo m\u00e1s lejos, y seguir leyendole por aqui o all\u00e1. <\/p>\n<p>R.- Me encanta que me vea usted tan saludable. Creo que disfrazo mis males cuando me toca por huevos hacer algo. Espero no perder el sentido de la profesionalidad. Los m\u00faltiples excesos de mi vida me est\u00e1n pasando factura. Y no me quejo, es l\u00f3gico. <\/p>\n<p>P.- Usted y Javier Mar\u00edas, adem\u00e1s de ser de la misma generaci\u00f3n y del Real Madrid, \u00bftienen algo m\u00e1s en com\u00fan? \u00bfSe conocen? \u00bfqu\u00e9 tal le cae? \u00bfle gustan sus libros? Gracias<\/p>\n<p>R.- Nos han presentado una vez. Sus art\u00edculos me parecen impagables. Tambi\u00e9n sus ensayos literarios sobre las cosas que ama. Con sus novelas, conecto menos. <\/p>\n<p>P.- Le compadezco Carlos por tener que sufrir tanta moderndez en Cannes. \u00bfCuando regresa a casa no se mete una sesi\u00f3n de desintoxicaci\u00f3n o catarsis con eternos ciclos de John Ford, Billy Wilder, Fritz Lang&#8230;para recuperar la estabilidad mental?<\/p>\n<p>R.- Por supuesto. Pero todav\u00eda me quedan 5 d\u00edas para el anhelado regreso a casa. Y tener que sufrir las pel\u00edculas de dos de los directores que m\u00e1s detesto: el chino Tsai Ming-Liang y el argentino Gaspar No\u00e9. <\/p>\n<p>P.- En el momento final, \u00bfcree que le pasar\u00e1n por la cabeza las diapositivas de su vida o ser\u00e1 un trance r\u00e1pido e intrascendete? Conoce la definici\u00f3n que hace C\u00e9line: &#8220;En el juego del hombre, el instinto de muerte, el instinto silencioso est\u00e1 colocado en el centro junto al ego\u00edsmo. Ocupa el lugar del cero en la ruleta. El casino gana siempre. La muerte tambi\u00e9n&#8221;<\/p>\n<p>R.- Eso lo escribi\u00f3 C\u00e9line en &#8220;Muerte a cr\u00e9dito&#8221;. Veo que compartimos id\u00e9ntico amor. Yo espero que en el momento de palmarla en la pel\u00edcula de mi vida s\u00f3lo aparezcan las cosas buenas. Ha habido muchas, tantas como malas. Pero no me miente usted a la muerte que ya ando yo con excesivas premoniciones. S\u00f3lo anhelo que sea r\u00e1pida. He visto sufrir enormemente a mucha gente que quer\u00eda. <\/p>\n<p>P.- \u00bfDe verdad hay un tipo transcribiendo el chat? Y yo pensaba que hab\u00eda exceso de funcionarios.<\/p>\n<p>R.- \u00bfTengo que volver a contar que yo no tengo ordenador, que escribo a mano en una libreta y dicto por tel\u00e9fono los art\u00edculos a las queridas secretarias? <\/p>\n<p>P.- Buenos d\u00edas Carlos. Alguna vez has comentado que tomas ansioliticos. Si no es demasiado preguntar, \u00bfa que es debido?. 1 saludo.<\/p>\n<p>R.- Tuve un largo calvario recorriendo cl\u00ednicas. Por alcoholismo, drogadicci\u00f3n, depresi\u00f3n, por las cosas que te puede imponer la vida. Desde entonces, ando empastillado. Mi mayor pavor cuando en los viajes no llega la maleta es no tener a mano el pastillero y tener problemas en otros para encontrar recetas m\u00e9dicas. Pero creo que a pesar de toda esa qu\u00edmica todav\u00eda no he perdido definitivamente la cabeza. Ese era el mayor de mis miedos. <\/p>\n<p>P.- Una pregunta, \u00bfBoyero es real o es un nuevo personaje de Muchachada Nui?<\/p>\n<p>R.- Es una mezcla. En realidad, soy Rouco Varela jugando a la trasgresi\u00f3n. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carlos Boyero, uno de los m\u00e1s populares e influyentes cr\u00edticos de cine y feroz columnista de televisi\u00f3n, de cine y de la vida en general ha charlado con los lectores sobre todo lo imaginable desde el Festival de Cannes. <\/p>\n<p>FOTO: BERNARDO P\u00c9REZ<br \/>\nARCHIVO DE ENTREVISTAS:<br \/>\n14 de mayo<br \/>\n7 de mayo &#8211; 30 de abril<br \/>\n23 de abril &#8211; 14 de abril<br \/>\n2 de abril &#8211; 26 de marzo<br \/>\n12 de marzo &#8211; 5 de marzo<br \/>\n26 de febrero &#8211; 12 de febrero<br \/>\n5 de febrero &#8211; 22 de enero<br \/>\n15 de enero &#8211; 18 de diciembre<br \/>\n11 de diciembre &#8211; 4 de diciembre<br \/>\n27 de noviembre &#8211; 20 de noviembre<br \/>\n13 de noviembre &#8211; 6 de noviembre<br \/>\n30 de octubre &#8211; 16 de octubre<br \/>\n9 de octubre &#8211; 25 de septiembre<br \/>\n18 de septiembre -04 de septiembre<br \/>\n28 de agosto &#8211; 17 de julio<br \/>\n10 de julio &#8211; 3 de julio<br \/>\n26 de junio &#8211; 19 de junio<br \/>\n12 de junio &#8211; 5 de junio<br \/>\n22 de mayo &#8211; 15 de mayo<br \/>\n8 de mayo &#8211; 24 de abril<br \/>\n17 de abril &#8211; 10 de abril<br \/>\n3 de abril &#8211; 13 de marzo<br \/>\n6 de marzo &#8211; 28 de febrero<br \/>\n14 de febrero &#8211; 08 de febrero<br \/>\n31 de enero &#8211; 24 de enero<br \/>\n17 de enero &#8211; 3 de enero<br \/>\n27 de diciembre &#8211; 20 de diciembre<br \/>\n13 de diciembre &#8211; 07 de diciembre<br \/>\n29 de noviembre &#8211; 22 de noviembre<br \/>\n15 de noviembre &#8211; 08 de noviembre<br \/>\n02 de noviembre -25 de octubre<\/p>\n<p>Carlos Boyero, en lalistaWIP.com<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-7388","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/7388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=7388"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/7388\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=7388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=7388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=7388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}