{"id":6926,"date":"2005-10-25T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=6926"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"Luis_Fernandez-Vega6926","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/Luis_Fernandez-Vega6926\/","title":{"rendered":"Luis Fern\u00e1ndez-Vega"},"content":{"rendered":"<p>Pregunta.- Hola. Estoy Operado de cataratas, y mi visi\u00f3n por la noche no es muy buena, asi como he perdido algo de vista cuando hay pocos contrastes. Hay alguna manera de mejorar mi vista?<\/p>\n<p>Respuesta.- Tendr\u00eda que saber qu\u00e9 tipo de lente le han puesto, qu\u00e9 graduaci\u00f3n ten\u00eda antes de la operaci\u00f3n y su edad. En funci\u00f3n de estas tres cosas podr\u00eda responderle.<\/p>\n<p>P.- \u00bfa que edad se puede operar de miopia y cual es el l\u00edmite en edad?<\/p>\n<p>R.- La edad m\u00ednima son los 20 a\u00f1os, una vez el defecto que se vaya a corregir est\u00e9 estabilizado. No existe tope de edad m\u00e1xima, aunque lo m\u00e1s normal es operar entre los 20 y 40 a\u00f1os.<\/p>\n<p>P.- Buenos d\u00edas. Soy mujer y estoy operada de miop\u00eda (content\u00edsima por cierto \ud83d\ude42 ). Me gustar\u00eda saber cu\u00e1l es el porcentaje de mujeres que sufren variaci\u00f3n de la graduaci\u00f3n durante el embarazo. Muchas gracias.<\/p>\n<p>R.- El porcentaje es muy peque\u00f1o si la miop\u00eda ya est\u00e1 estabilizada, a partir de los 20 \u00f3 21 a\u00f1os.<\/p>\n<p>P.- Doctor Fernadez -Vega , quisiera saber que es un glaucoma y en que consiste su cirujia, muchisimas gracias.<\/p>\n<p>R.- Un glaucoma es un aumento de la presi\u00f3n ocular del ojo que da\u00f1a el nervio \u00f3ptico. La intervenci\u00f3n consiste en facilitar una v\u00eda de desag\u00fce para el humor acuoso, que es el responsable del aumento de presi\u00f3n. La operaci\u00f3n se llama trabeculectom\u00eda.<\/p>\n<p>P.- Se puede eliminar el astigmatismo con cirugia,si asi fuere que posibilidades dr fracaso existen,y cuantas a favor.<\/p>\n<p>R.- El astigmatismo se puede eliminar con cirug\u00eda. Hasta 5 dioptr\u00edas se puede usar l\u00e1ser. Por encima de esa graduaci\u00f3n se usan otras t\u00e9cnicas siempre y cuando la c\u00f3rnea tenga una morfolog\u00eda normal.<\/p>\n<p>P.- Don Luis, \u00bf Es mejor utilizar gafas en vez de lentillas?<\/p>\n<p>R.- Ni es mejor ni es peor. Son elementos distintos. Para el ojo es lo mismo. Desde el punto de vista visual proporciona mejor visi\u00f3n la lentilla que la gafa, pero la decisi\u00f3n es algo muy personal.<\/p>\n<p>P.- Buenos d\u00edas, tengo 29 a\u00f1os y me han diagnosticado ojos secos de tipo evaporativo. \u00bftiene soluci\u00f3n o es una enfermedad cr\u00f3nica de por vida?. Por otro lado me gustar\u00eda saber si tiene riegos una blefaroplastia ya que debido a una blefaritis se me han deformado un poco los p\u00e1rpados. Muchas gracias.<\/p>\n<p>R.- El ojo seco no es una enfermedad grave. Hoy en d\u00eda existen muchos tratamientos, unos con l\u00e1grimas artificiales. Otris ocluyendo los puntos lagrimales y otros con medicaci\u00f3n por v\u00eda general. Depender\u00e1 de la gravedad del cuadro. Con respecto ala blefaroplastia si est\u00e1 bien realizada e indicada no tiene por qu\u00e9 tener riesgo mayor que cualquier intervenci\u00f3n quir\u00fargica.<\/p>\n<p>P.- Tengo una hija operada de cataratas desde los 11 meses de edad en un ojo. Actualmente (tiene 3 a\u00f1os), usa una lentilla y gafas para la visi\u00f3n de cerca. Cuando el ojo deje de crecer, \u00bfqu\u00e9 opciones tiene para darle la mejor calidad posible de visi\u00f3n: lente intraocular monofocal o multifocal, etc..?<\/p>\n<p>R.- Cuando llegue el momento oportuno lo mejor ser\u00eda poner una lente multifocal. En cualquier caso estos ojos suelen ser ojos vagos.<\/p>\n<p>P.- Me han dicho que tengo cataratas disrrefractivas, que la miop\u00eda me aumenta continuamente hasta que acabar\u00e1n teniendo que operarme, pero no encuentro nada de este tipo de cataratas en Internet; \u00bfme puede hablar de este tipo de cataratas?<\/p>\n<p>R.- Son cataratas llamadas cataratas de \u00edndice. Al endurecerse la catarata se va produciendo un aumento de la miop\u00eda. Son bastante frecuentes. Cuando produzcan una disminuci\u00f3n visual importante se deben operar.<\/p>\n<p>P.- Hola, \u00bfque factores influyen en la aparici\u00f3n de la miop\u00eda?\u00bf A partir de que grado de miop\u00eda se considera recomendable el uso de gafas todo el d\u00eda? Muchas gracias.Le\u00f3n.<\/p>\n<p>R.- Hay factores hereditarios y el esfuerzo continuado de acomodaci\u00f3n influyen. La gafa debe comenzar a usarse todo el d\u00eda cuando el paciente ya est\u00e1 inc\u00f3modo, lo que suele ocurrir a partir de una dioptr\u00eda o dioptr\u00eda y media.<\/p>\n<p>P.- Buenos d\u00edas, me gustar\u00eda saber cu\u00e1les son los posibles efectos secundarios m\u00e1s comunes en una operaci\u00f3n de miop\u00eda. Yo me oper\u00e9 hace 3 a\u00f1os y sufro bastante con la sequedad de ojos desde entonces. Gracias.<\/p>\n<p>R.- Los efectos secundarios son muy peque\u00f1os normalmente. Al principio puede haber un cierto grado de deslumbramiento dependiendo del n\u00famero de dioptr\u00edas qu etenga el paciente y de la t\u00e9cnica empleada. La sequedad tambi\u00e9n puede producirs elos primeros meses.<\/p>\n<p>P.- las lesiones de retina por alta miopia que arreglo tienen?<\/p>\n<p>R.- Poco arreglo en general. Si afectan a la zona central van a producir una disminuci\u00f3n de visi\u00f3n y s\u00f3lo en muy pocas ocasiones pueden tratarse con l\u00e1ser.<\/p>\n<p>P.- Hola muy buenas. Creo que hoy m\u00e1s que nunca pasamos mucho tiempo delante de un medio audiovisual, llamese televisor, ordenador PC&#8230;.me pregunto si este comportamiento afecta en gran medida a nuestra vision a corto, medio o largo plazo. \u00bfPuedo achacar a esto una hinchaz\u00f3n de los p\u00e1rpados, enrojecimiento de los ojos, o esto se deba m\u00e1s probablemente a otro tipo de causas como una alergia, o un sobreesfuerzo de los ojos por no utilizar las debidas lentes? \u00bfAlgun consejo de como cuidar nuestros ojos? Muchas gracias.<\/p>\n<p>R.- Normalmente no se producen estos problemas por el uso de medios audiovisuales, sino por otros motivos. Cuando uno est\u00e1 mucho tiempo viendo la televisi\u00f3n o trabajando frente a un ordenador disminuye la frecuencia del parpadeo por lo que es conveniente descansar periodicamente y utilizar l\u00e1grimas artificiales.<\/p>\n<p>P.- Mi hijo tiene unas peque\u00f1as lesiones en la retina perif\u00e9rica y me han recomendado el sellado con l\u00e1ser. Me gustar\u00eda saber que opini\u00f3n tiene el doctor sobre esta intervenci\u00f3n as\u00ed como si la misma resulta compleja. Muchas gracias por todo.<\/p>\n<p>R.- Hay que ver qu\u00e9 tipo de lesiones tiene porque ne muchos casos es innecesario, pero si se considera que se debe hacer la intervenci\u00f3n no es compleja.<\/p>\n<p>P.- MERECE LA PENA RETRASAR EL USO DE GAFAS PARA VISTA CANSADA . AUNQUE A VECES TENGAS QUE SEPARAR TANTO EL LIBRO QUE NO TE DAN LOS BRAZOS<\/p>\n<p>R.- No. No merece la pena pues no se obtiene ning\u00fan beneficio.<\/p>\n<p>P.- Hola. Tengo unasseis dioptr\u00edas en cada ojo. Si me operase, \u00bf se reducir\u00eda a cero las dioptr\u00edas ?. Y mi segunda pregunta es \u00bf la sensaci\u00f3n de tristeza en los ojos que se le quedan a los que llevan muchos a\u00f1os con gafas y despu\u00e9s se la quitan permancece para siempre. ?. Gracias.<\/p>\n<p>R.- S\u00ed se puede quedar a cero tras la intervenci\u00f3n. A veces se precisa un retoque. La sensaci\u00f3n de tristeza desaparece.<\/p>\n<p>P.- He operado a mi hijo de estrabismo horizontal y vertical, convergente. La operaci\u00f3n salio perfecta pero no el proceso de cicatrizacion. Ha perdido visi\u00f3n y ahora tiene estrabismo divergente (hacia fuera). Seguramente haya que operarle de los musculos oblicuos. Es normal y frecuente que ocurra esto?<\/p>\n<p>R.- Puede ocurrir que al cabo de un cierto tiempo precise un retoque sobre todo en caso de estrabismos complejos.<\/p>\n<p>P.- \u00bfRecomendar\u00eda operar un ojo vago?<\/p>\n<p>R.- Depende de cu\u00e1n vago sea el ojo, cu\u00e1l sea la causa y de c\u00f3mo est\u00e9 el otro ojo.<\/p>\n<p>P.- \u00bfEs cierto que los pacientes con ojos secos est\u00e1n desaconsejados para operarse con laser? Yo tengo papilas estacionarias y estar\u00eda interesada. Gracias!<\/p>\n<p>R.- Los ojos secos salvo que sean muy severos no contraindican la intervenci\u00f3n pues hay l\u00e1seres que utilizamos que no agravan el proceso.<\/p>\n<p>P.- Estimado Se\u00f1or, tengo varios puntitos en la vista, de esos que llaman moscas. \u00bfA qu\u00e9 se deben?\u00bfTiene arreglo?\u00bfpor qu\u00e9 los notos m\u00e1s cuando hay m\u00e1s luz en la sala? Muchas gracias<\/p>\n<p>R.- Se deben a peque\u00f1as a\u00f1teraciones del v\u00edtreo y el 99% d ela veces no tienen importancia. Se ve m\u00e1s frecuentemente sobre fondos blancos o cuando hay m\u00e1s luz. Tienen tendencia a disminuir por s\u00ed solos. Si van a m\u00e1s es necesario revisarlos.<\/p>\n<p>P.- por que tr\u00e1s operarme de miop\u00eda y astigamatismo no veo bien de cerca<\/p>\n<p>R.- Depende de la edad que tenga. Si tiene m\u00e1s de 43-44 a\u00f1os y se opera la miop\u00eda aparece la vista cansada.<\/p>\n<p>P.- hola doctor, mi problema es que tengo los ojos siempre muy rojos, llevo lentillas, me gustaria que me diera algun remedio para aliviarlo, me han dicho que el uso de colirios todos los dias puede ser perjudicial<\/p>\n<p>R.- Tiene mala soluci\u00f3n cuando hay esta predisposici\u00f3n. Conviene utilizar l\u00e1grimas artificiales frecuentes y disminuir el uso de lentillas todo lo posible. Se podr\u00eda valorar la intervenci\u00f3n de su defecto refractivo.<\/p>\n<p>P.- \u00bfQu\u00e9 puedo hacer para evitar un dolor de ojos considerable y la sensaci\u00f3n de que cada d\u00eda veo menos debido a la cantidad de horas que mi trabajo exige delante del ordenador? Gracias.<\/p>\n<p>R.- Primero hacerse una revisi\u00f3n oftalmol\u00f3gica incluyendo la toma de la presi\u00f3n ocular, descansar periodicamente del trabajo de la pantalla del ordenador, utilizar l\u00e1grimas artificales frecuente y ver si es necesaria o no una gafa.<\/p>\n<p>P.- En mi \u00f3ptica me han comentado la existencia de unas lentillas que te las pones por la noche, a la ma\u00f1ana siguiente te las sacas y la miop\u00eda ha desaparecido. El efecto dura todo el d\u00eda. \u00bfEsto es seguro? \u00bfRecomendable? \u00bfAlg\u00fan efecto secundario? Muchas gracias de antemano.<\/p>\n<p>R.- En mi opini\u00f3n no es recomendable y se han descrito \u00falceras corneales y otras alteraciones importantes por su empleo.<\/p>\n<p>P.- Hola, doctor. Dentro de unos d\u00edas tienen que practicarme una Dacriocistorrinostom\u00eda. La verdad es que tengo un poco de pavor a eso de que me taladren la nariz&#8230; \u00bfMe puede animar un poco?. Gracias<\/p>\n<p>R.- No le va a doler. Adem\u00e1s, normalemnte un porcentaje elevado de casos soluciona su problema de lagrimeo.<\/p>\n<p>P.- preparo oposiciones y estoy entre doce y trece horas diarias delante de los libros. Al finalizar el d\u00eda me duelen &#8220;literalmente&#8221; los ojos, no los p\u00e1rpados. \u00bfEs normal? Tengo miop\u00eda alta (7 dioptr\u00edas) y estudio indistintamente con gafas y lentillas.<\/p>\n<p>R.- Es normal que esto ocurra pues se produce fatiga visual aunque no es perjudicial para el ojo.<\/p>\n<p>P.- Quisiera saber soluci\u00f3n para los orzuelos enquistados .Y si hay soluciones a la isquemia producida en un ojo<\/p>\n<p>R.- Sobre los orzuelos enquistados la \u00fanica soluci\u00f3n es operarlos. Con respecto a la isquemia hay que ver en qu\u00e9 parte se ha producido y cual es la causa.<\/p>\n<p>P.- Hola. Me dijeron que tenia unas ulceras en el fondo del ojo que con el paso del tiempo podria producirme desprendimiento de retina. Me dieron laser para curarlo. Es podible que vuelvan a aparecer. Gracias.<\/p>\n<p>R.- Es posible, pero no es frecuente.<\/p>\n<p>P.- Para implantar la nueva lente que corrige la miop\u00eda y la presvicia que condiciones exige al paciente? edad, graducaci\u00f3n. Enhorabuena por la trayectoria profesional de su familia y suya. Muchas gracias. Marina Quind\u00f3s.<\/p>\n<p>R.- Muchas gracias. La edad, por encima de los 55 a\u00f1os y las dioptr\u00edas de miop\u00eda, por encima de las 3 \u00f3 4.<\/p>\n<p>P.- Hola, me operaron con \u00e9xito de una Pingu\u00e9cula hace unos 4 meses, \u00bfes efectivo tomar un suplemento vitam\u00ednico para evitar que se pueda reproducir?<\/p>\n<p>R.- No.<\/p>\n<p>P.- Buenos dias \u00bfcual puede ser la causa de una uveitis? \u00bfEs una enfermedad grave? \u00bfQu\u00e9 pasa si se repite?<\/p>\n<p>R.- Las uveitis tienen m\u00faltiples causas. Pueden ser secundarias a algyuna enfermedad general, alguna infecci\u00f3n etc. Se repiten con cierta frecuencia y es necesario tratar cada brote.<\/p>\n<p>P.- Buenas tardes, \u00bfson realmente eficaces los ejercicios oculares, para curar la miopia?, un saludo.<\/p>\n<p>R.- No sirve para nada. Hay que tener cuidado porque a veces s\u00f3lo enga\u00f1an al paciente.<\/p>\n<p>P.- buenos d\u00edas, mi pregunta es la siguiente \u00bfcada cu\u00e1nto tiempo es conveniente ir a hacerse una revisi\u00f3n oftalmol\u00f3gica? muchas gracias y un saludo.<\/p>\n<p>R.- Por encima de los 40 a\u00f1os se hace una revisi\u00f3n anual o bianual como m\u00e1ximo. Por debajo seg\u00fan se tenga un defecto en la graduaci\u00f3n o no. Si lo tiene se debe acudir con la misma frecuencia. Si no lo hay se puede demorar m\u00e1s.<\/p>\n<p>P.- Buenos D\u00edas. Yo tambi\u00e9n veraneo en Ceceda. Mi pregunta es: mi hija de cinco a\u00f1os tuvo una fuerte reacci\u00f3n al colirio ciclop\u00e9gico con el que le dilataron con tres a\u00f1os la pupila, \u00bftenemos que tener alg\u00fan tipo de cuidado especial?<\/p>\n<p>R.- No, porque son muy poco frecuentes las reacciones y normalmente sin importancia.<\/p>\n<p>P.- Buenos d\u00edas. Algunos amigos operados de miop\u00eda han tenido problemas de deslumbramiento nocturno \u00bftiene soluci\u00f3n o es para siempre? \u00bfes posible volver a operar la miop\u00eda si vuelve a aparecer pasados algunos a\u00f1os? \u00bfy las cataratas?. Muchas gracias?<\/p>\n<p>R.- Los deslumbramientos nocturnmos suelen desparecer despu\u00e9s de unos meses. Es posible volver a operar si vuelve a aparecer la miop\u00eda aunque depende de cada caso. Las cataratas una vez se operan no vuelven a salir m\u00e1s.<\/p>\n<p>P.- \u00bf Por qu\u00e9 muchisismos oftalmologos utilizan gafas y no se operan?<\/p>\n<p>R.- Porque depende de la edad del oftalm\u00f3logo. Si se operasen a partir de los 40 a\u00f1os necesitar\u00edan una gafa par acerca y eso no les interesa para su trabajo habitual.<\/p>\n<p>P.- hay algun alimento q ayude a cicatrizar las cicatrices de una poeracion laser?<\/p>\n<p>R.- No. Ning\u00fan alimento.<\/p>\n<p>P.- Estoy operado de cataratas en los dos ojos y tengo una correccion de miopia y de agtismatismo en el ojo izquierdo y aun asi en la noche y con luces estas me molestan haciendome un efecto de agtismatismo.\u00bfes normal esto despues de las operaciones que llevo?<\/p>\n<p>R.- Puede ser normal y depende de la lente que lleve puesta. En cualquier caso disminuir\u00e1 con el tiempo.<\/p>\n<p>P.- Buenos dias doctor, soy paciente de queratitis adenovirica desde hace 8 meses, operado de Lasik hace 9 a\u00f1os. Todavia no he recuperado la vision con las corneas limpias de infiltrados. Tengo miedo de no recuperar del todo la vision. Muchas gracias<\/p>\n<p>R.- La queratitis por adenovirus es muy pesada y tarda basrtante tiempo en resolverse aunque lo normal es qu eno deje practicamente secuelas.<\/p>\n<p>P.- una secreci\u00f3n de color blanco, producida por una bacteria (estreptococus dermis), tendr\u00eda soluci\u00f3n de cura por oftalmolog\u00eda o por dermatolog\u00eda. Me han tratado con diversos antibi\u00f3ticos y no ha servido para nada<\/p>\n<p>R.- Lo normal es que si es una secreci\u00f3n en la conjuntiva ocular es que sea tratada por un oftalm\u00f3logo aunque no siempre responde eficazmente al tratamiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfCu\u00e1ntos tipos de operaciones existen para eliminar la miop\u00eda? \u00bfLas cataratas se pueden curar sin cirug\u00eda? Si quiere resolver \u00e9stas y otras dudas sobre problemas oculares, consulte la charla con el jefe del servicio de oftalmolog\u00eda del Hospital Central de Asturias y director m\u00e9dico del Instituto Oftalmol\u00f3gico F\u00e9rn\u00e1ndez-Vega de Oviedo.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-6926","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/6926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=6926"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/6926\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=6926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=6926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=6926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}