{"id":3926,"date":"2009-08-25T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=3926"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"Isabel_Coixet3926","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/Isabel_Coixet3926\/","title":{"rendered":"Isabel Coixet"},"content":{"rendered":"<p>Pregunta.- Isabel, al parecer &#8220;Mapa de los sonidos de Tokio&#8221; podr\u00eda ser seleccionada por nuestra Academia de Cine para competir por el Oscar a la Mejor Pel\u00edcula De Habla No Inglesa, ya que est\u00e1 hablada mayoritariamente en japon\u00e9s y catal\u00e1n. \u00bfTe gustar\u00eda que esto ocurriese? \u00bfSue\u00f1as con la idea de ganar un Oscar? Mucha suerte.<\/p>\n<p>Respuesta.- Yo, por ahora, s\u00f3lo sue\u00f1o con que vaya un mont\u00f3n de gente a ver la peli, luego, lo dem\u00e1s, ya veremos&#8230;. ojal\u00e1!!<\/p>\n<p>P.- de qu\u00e9 te sientes m\u00e1s satisfecha? de que un p\u00fablico variopinto se identifique con un cine tan personal como el tuyo o de hacer el tipo de pel\u00edculas que a ti te interesan? y una pregunta m\u00e1s como si de un after pack se tratara &#8230; te atrever\u00e1s alg\u00fan d\u00eda con una comedia tipo w. allen?<\/p>\n<p>R.- Yo souy una persona insatisfecha por naturaleza, por otro lado me gusta mucho que la gente conecte y se identifique con mis historias&#8230;&#8230; Me atrever\u00eda mas con una comedia tipo Ben Stiller o Chistopher Guest que es mi h\u00e9roe!<\/p>\n<p>P.- La prensa espa\u00f1ola suele ser injusta con tus pel\u00edculas. Elegy fue muy bien recibida en Estados Unidos, pero aqu\u00ed dijeron que dividi\u00f3 a la cr\u00edtica norteamericana. En el caso de Mapa de los sonidos de Tokio, le\u00ed un art\u00edculo en un medio espa\u00f1ol que dec\u00eda que fue la peor recibida en Cannes. Sin embargo, en un medio franc\u00e9s se dijo que recibi\u00f3 una ovaci\u00f3n de 10 minutos. \u00bfQu\u00e9 ocurri\u00f3 realmente en el festival? \u00bfQu\u00e9 opinas de esta manipulaci\u00f3n informativa?<\/p>\n<p>R.- La ovaci\u00f3n de diez minutos a la pel\u00edcula se puede ver en youtube. Y te aseguro que no fue la pel\u00edcula peor recibida de la secci\u00f3n oficial!!Adem\u00e1s tuvmos el premio al mejor sonido en el Palmar\u00e9s oficial, cosa de la que NADIE en Espa\u00f1a se hizo eco&#8230; Me parece injusto pero ya hay tantas injusticias en la vida&#8230;. Creo que la prensa tiene derecho a decir lo que quiera en un art\u00edculo de opini\u00f3n pero cuando se trata de hechos y noticias, deber\u00edan contrastarlos. la vida es as\u00ed&#8230;.<\/p>\n<p>P.- Isabel, gracias a ti descubr\u00ed al gran Antony Hegarty (vocalista de Antony and the Johnsons) y se ha convertido en mi artista favorito. Tengo entendido que el excelente tema One Dove aparece en Mapa de los sonidos de Tokio. \u00bfC\u00f3mo es el proceso de selecci\u00f3n de canciones para tus pel\u00edculas? \u00bfSupervisas personalmente las bandas sonoras de tus films?<\/p>\n<p>R.- Antony es un aut\u00e9ntico genio, cuando escuch\u00e9 One dove me qued\u00e9 paralizada: era la canci\u00f3n que le faltaba a la pel\u00edcula.Selecciono muchas canciones al primcipio de cada pel\u00edcula y luego voy cambiando a medida que afinamos el montaje<\/p>\n<p>P.- Hola, siempre que voy a ver una pel\u00edcula tuya se me viene a la cabeza ese momento en el que recibiste el Goya y no pod\u00edas articular palabra. \u00fanicamente acertabas a decir &#8220;Ahhhh, ahhhh&#8221; Dime Isa, es una duda que muchos de tus fans tenemos \u00bfrealmente no sab\u00edas que decir, o es una pose que adoptas cuando recibes premios?<\/p>\n<p>R.- Yo soy una persona de una timidez enfermiza y la cosa social no se me d\u00e1 NADA bien. De verdad que no me esperaba ning\u00fan Goya y me qued\u00e9 totalmente en blanco. Lo juro por Zoolander.<\/p>\n<p>P.- Buenas tardes Isabel, \u00bfde d\u00f3nde y c\u00f3mo surge la idea de plasmar en cine los sonidos de Tokio? Gracias y much\u00edsima suerte con el estreno!.<\/p>\n<p>R.- Siempre me ha gustado jap\u00f3n y en uno de los \u00fatimos viajes me convencieron para ir al mercado de Tsujiki, el del pescado, all\u00ed estuve haciendo fotos y cuando intent\u00e9 hacer fotos a una chica muy guapa que estaba limpiando la sangre de unos atunes se mosque\u00f3 conmigo y me dijo que no. Luego de vuelta a casa, estuve pensando y fantaseando sobre esa chica y&#8230;as\u00ed empez\u00f3 todo<\/p>\n<p>P.- Me muero de ganas por ver la pel\u00edcula despu\u00e9s de haber seguido tu videoblog de rodaje&#8230; Mi pregunta es una tonter\u00eda pero no quiero dejar de hac\u00e9rtela \u00bfdesde cuando viene tu fascinaci\u00f3n por Tokyo? \u00bfes tan bestia el shock como dicen? Un beso y felicidades por tu trayectoria.<\/p>\n<p>R.- Creo que la fascinaci\u00f3n sobre Jap\u00f3n me viene de la adolescencia, cuando a los quince a\u00f1os le\u00ed un libro de Yasunari kavawata que se llama &#8220;La casa de las durmientes&#8221; , luego descubr\u00ed la comida, la m\u00fasica, el arte, Commme des gar\u00e7ons, Yamamoto, Murakami ( Haruki y Ryu), Ozu, Kore eda, Naomi Kawase. Y s\u00ed, el shock es bestia, Tokyo es una ciudad con muchas ciudades dentro, ahora hay billetes muy baratos, tienes que ir!<\/p>\n<p>P.- Isabel, como exitosa publicista que eres si tuvieras que convercernos para ver tu pel\u00edcula, \u00bfqu\u00e9 nos dir\u00edas?<\/p>\n<p>R.- Lo de la publicidad ya lo tengo un poco olvidado la verdad&#8230;. y encima soy la peor publicista de m\u00ed misma! Creo que es una pel\u00edcula que te propone un viaje sensorial a Tokyo con sonidos, olores, sabores, sexo y&#8230;melancol\u00eda. Ya ves que no la s\u00e9 vender.<\/p>\n<p>P.- \u00bfPor qu\u00e9 una chica tan dulce como Rinko Kikuchi querr\u00eda asesinar a Sergi L\u00f3pez por un pu\u00f1ado de yenes?<\/p>\n<p>R.- Es una sesina a sueldo. Y Rinko puede ser muy dulce pero&#8230;. puede ser una serpiente y de hecho ella ten\u00eda la imagen de una serpiente para inspirarse.<\/p>\n<p>P.- Isabel, te descubr\u00ed no hace tanto tiempo, fue con &#8220;Mi vida sin mi&#8221;, fue de esas pel\u00edculas que te hacen pensar acerca de la vida&#8230; \u00bfEres de las de vivir cada segundo como si fuera el \u00faltimo?<\/p>\n<p>R.- Lo intento, lo intento&#8230;pero a veces no me aplico el cuento y pierdo el tiempo miserablemente.<\/p>\n<p>P.- Hola Isabel, mi m\u00e1s cordial enhorabuena por tu peli. Espero poder verla este fin de semana. Me trag\u00e9 el makeoff en el blog y en cameraman con el ansia del hambriento. Me gustar\u00eda saber si te resulta complicado desprenderte del ambiente de tus proyectos una vez acabados y que haces para convatirlo. Gracias\/Joseba1<\/p>\n<p>R.- Me resulta MUY complicado. Ahora tengo una nostalgia de Tokyo brutal, s\u00f3lo estuve cinco meses pero de repente, hueles a soja y a wasabi y coger\u00edas inmediatamente el avi\u00f3n para volver&#8230;. aunque seguro que entonces me entrarr\u00eda nostalgia de otra cosa, un saludo Joseba<\/p>\n<p>P.- \u00bfC\u00f3mo le sienta que algunos la nombren como &#8220;gafapasta&#8221;?, \u00bfExiste de verdad el &#8220;gafapastismo&#8221; en Espa\u00f1a o cree que s\u00f3lo es un estereotipo sacado de un chiste malo?<\/p>\n<p>R.- Llevo gafas met\u00e1licas desde hace mucho tiempo y miope soy desde los cinco a\u00f1os ( las lentillas siempre se me han resistido) Qu\u00e9 le vamos a hacer, si te llaman as\u00ed pues te llaman as\u00ed. Tambien se dicen cosas mucho peores por ah\u00ed&#8230;lo de gafapasta es lo de menos!<\/p>\n<p>P.- Isabel, \u00bfte atrever\u00edas a dirigir un musical? Viendo n\u00fameros musicales como el del supermercado de Mi vida sin m\u00ed, no me cabe la menor duda de que es un g\u00e9nero que no se te resistir\u00eda. \u00a1An\u00edmate!<\/p>\n<p>R.- ME ENCANTARIA dirigir un musical tipo &#8220;Los paraguas de Cherburgo&#8221; que es una de mis pel\u00edculas favoritas ( y una de las pelis mas tristes de todos los tiempos)<\/p>\n<p>P.- Isabel, gracias por tus pel\u00edculas, por las l\u00e1grimas, por las risas, por esos momentos tan m\u00e1gicos en las salas de cine&#8230; \u00bfVolver\u00e1s a rodar en espa\u00f1ol?<\/p>\n<p>R.- Muchas gracias a t\u00ed por verlas! Y muy pronto voy a dirigir una pel\u00edcula en espa\u00f1ol, s\u00ed.<\/p>\n<p>P.- S\u00f3lo espero q esta \u00faltima pel\u00edcula me guste tanto como Elegy, con la q no pude dejar de llorar y llorar&#8230;Es ud. de l\u00e1grima f\u00e1cil??? Qu\u00e9 podr\u00eda hacerla llorar desconsoladamente???<\/p>\n<p>R.- S\u00ed, lo confieso , soy de l\u00e1grima f\u00e1cil, Me puede hacer llorar cualquier cosa, yo veo a alguien llorar y por empat\u00eda, empiezo a llorar yo&#8230;<\/p>\n<p>P.- \u00bfQu\u00e9 programa de televisi\u00f3n te gustar\u00eda dirigir? M\u00f3jate, no digas que s\u00f3lo te interesa el cine. Gracias<\/p>\n<p>R.- Muchachada NUi, soy gran fan&#8230;. Y True Blood me fascina!<\/p>\n<p>P.- Buenas tardes Isabel. El viernes sale a la venta en DVD su primera pel\u00edcula, &#8220;Demasiado viejo para morir joven&#8221;, \u00bfha participado en su edici\u00f3n? \u00bfincluye alg\u00fan extra interesante? \u00bfqu\u00e9 recuerdos le trae? Gracias y un saludo.<\/p>\n<p>R.- Sabes una cosa? No ten\u00eda ni idea que sal\u00eda, gracias por avisarme<\/p>\n<p>P.- \u00bfTe gusta promocionar tus pel\u00edculas en Espa\u00f1a? \u00bfQue tal llevas esa parte de tu trabajo? \u00bfHay alguna premi\u00e8re prevista en Barcelona? Un abrazo, me gustan mucho tus pel\u00edculas y tu naturalidad.<\/p>\n<p>R.- Yo creo que rodar pel\u00edculas es f\u00e1cil en comparaci\u00f3n con la promoci\u00f3n !! es un CO\u00d1AZO hablar de lo que hace uno, cuando est\u00e1 en la pantalla&#8230; por otro lado, est\u00e1 claro que la gente tiene derecho a preguntar y a saber ciertas cosas, intento tom\u00e1rmelo lo mejor que puedo. Gracias. Un abrazo para t\u00ed. isabel<\/p>\n<p>P.- Isabel, antes de nada enhorabuena por tu pel\u00edcula. Tal y como est\u00e1n las cosas, que sigas rodando las pel\u00edculas que quieres hacer, tener tu p\u00fablico y adem\u00e1s entrar a formar parte del &#8220;Club de Cannes&#8221;, ya es much\u00edsimo. En USA se est\u00e1 diciendo que el cine independiente est\u00e1 en crisis, &#8220;yes, the sky is definitely falling&#8221;, porque cada vez es m\u00e1s dif\u00edcil encontrar un p\u00fablico interesado en este tipo de pel\u00edculas. \u00bfQu\u00e9 piensas de esto? Gracias y enhorabuena!<\/p>\n<p>R.- Gracias, y s\u00ed realmente a m\u00ed tambien me parece un milagro poder seguir haciendo pel\u00edculas. Creo que todos hemos de ser conscientes que la manera de ver las pel\u00edculas ha cambiado. Yo lo soy&#8230;pero quiero hacer mas pel\u00edculas!!<\/p>\n<p>P.- Konichiwa Isabel-san (Hola Isabel).He estado siguiendo su blog en el mundo.es sobre la realizaci\u00f3n de su pel\u00edcula en Jap\u00f3n.Estoy con muchas ganas de ir a verla.Mi pregunta :\u00bfha tenido muchas dificultades con la barrera idiom\u00e1tica y cultural a la hora de realizar la pel\u00edcula?.Mucha suerte de un apasionado del cine japon\u00e9s.(J.A.F.S)<\/p>\n<p>R.- Creo que uno tiene que ir a Jap\u00f3n con la mente y el coraz\u00f3n abiertos y con voluntad de entenderse. Nuestro equipo lo ten\u00eda y nos llevamos maravillosamente con el equipo japon\u00e9s que era fabuloso.<\/p>\n<p>P.- Hola Isabel. El viernes te escuche en Radio 3 con Javier. Que maravilla, as\u00ed da gusto escuchar una &#8220;entrevista&#8221;. Por cierto, de la pel\u00edcula todo el mundo habla de las escenas del sexo, pero y la parte de la cocina?, debe de ser grandiosa cuando la califican como una de las mejores peliculas despu\u00e9s de Ratatuin. Y segundo, eso de realizar un documental del Mar de Ar\u00e1n?. Mucha suerte con la pel\u00edcula. Ah\u00ed estar\u00e9 el viernes.<\/p>\n<p>R.- Si, a Ferr\u00e0 Adri\u00e0 le gust\u00f3 mucho la pel\u00edcula si te sirve de referencia&#8230; Y tienes toda la raz\u00f3n. Todo el mundo dice que se pasan la pel\u00edcula follando pero no es verdad: se pasan la pel\u00edcula comiendo. El documental que he hecho es sobre la desaparici\u00f3n del mar de Aral en Uzbekist\u00e1n.<\/p>\n<p>P.- Hola, Isabel. Conecto (en lo personal) mucho con tu sentido del humor, me encanta tu obra. Kikuchi me parece una elecci\u00f3n muy acertada, \u00bfc\u00f3mo ha sido el trabajo con ella? Supongo que la qu\u00edmica con Sergi era esencial.<\/p>\n<p>R.- Qu\u00e9 bien que conectes con mi sentido del humor, la verdad es que tengo MUCHO sentido del humor y no soy una persona tan &#8220;megasensible&#8221; como algunos se empe\u00f1an en afirmar. Rinko es una actriz formidable y una mujer maravillosa. creo que hace una creaci\u00f3n muy dif\u00edcil y muy dura y ojal\u00e1 se lo reconoizcan&#8230;<\/p>\n<p>P.- Hola Isabel, siempre me he preguntado por qu\u00e9 tus trabajos, que a\u00fanan elogios de critica y p\u00fablico, no suelen aspirar a los Goya. \u00bfTanto importa que est\u00e9n rodados en ingl\u00e9s? Un abrazo!<\/p>\n<p>R.- Bueno, algunos Goya me han dado&#8230;. Y f\u00edjate esta pel\u00edcula ahora en japon\u00e9s&#8230;.<\/p>\n<p>P.- Hola Isabel, querr\u00eda saber qu\u00e9 opinas acerca de las ingentes subvenciones al cine espa\u00f1ol. Los directores se empe\u00f1an en hacer productos creativos personales que se sabe que no tienen posibilidad de venta, pero se hacen poruqe se subvenciona. \u00bfPor qu\u00e9 no se hace lo que los espectadores quieren ver? Dedicarse al cine \u00bfes un trabajo (oferta-demanda) o un hobby (oferta-subvenci\u00f3n)? No lo digo por tus pel\u00edculas, que personalmente me gustan, pero hay cada engendro&#8230; Muchas gracias y suerte.<\/p>\n<p>R.- Yo creo , y lo he dicho p\u00fablicamente( aunque creo que no me escuchan) que las subvenciones tienen que darse exclusivamente a operas primas, hay que ayudar a los que empiezan, una vez hecha la primera pel\u00edcula, me parece que, por mucho que nos pese, las restantes deber\u00edan regirse por la oferta y la demanda. Creo que hay otros sectores de la sociedad que necesitan mas que el cine el dinero del estado.<\/p>\n<p>P.- Hola Isabel, enhorabuena por tu nueva creaci\u00f3n. \u00bfQu\u00e9 es lo que te ha resultado m\u00e1s complicado durante el rodaje en \u00e9sta pel\u00edcula? Un saludo, Alex.<\/p>\n<p>R.- Fue complicado al principio pero una vez el equipo japon\u00e9s empez\u00f3 a darse cuenta que a nosotros nos gusta improvisar&#8230;. todo empez\u00f3 a ir mejor.Y elegir las canciones del karaoke semanal tambien fue dif\u00edcil: todo el mundo quer\u00eda cantar &#8220;Dancing queen&#8221;. Fue horrible.<\/p>\n<p>P.- \u00bfPr\u00f3xima parada?<\/p>\n<p>R.- Ay, no lo s\u00e9, igual estaci\u00f3n de cercan\u00edas&#8230;<\/p>\n<p>P.- Por lo poco que he podido ver de la pel\u00edcula en los trailers, parece que est\u00e1 m\u00e1s que latente la sombra del cine de Wong Kar Wai&#8230; \u00bfC\u00f3mo organiza un autor sus influecias? \u00bfCrees que puede volverse en contra de uno? \u00bfAcusas en tus procesos creativos el lastre de la sobrecarga referencial? Un saludo.<\/p>\n<p>R.- Tendr\u00e1s que ver la pel\u00edcula entera para ver si mi amigo Wong me ha influido&#8230; pero la sombra de Kore Eda tambien es alargada&#8230;<\/p>\n<p>P.- Buenas tardes. Tras la experiencia de dirigir y no escribir el gui\u00f3n de &#8220;Elegy&#8221;, ha vuelto a dirigir y escribir el gui\u00f3n de un largometraje en &#8220;Mapa de los sonidos de Tokio&#8221;. \u00bfQu\u00e9 conclusiones ha sacado como directora y como guionista?<\/p>\n<p>R.- Es MUCHO mas f\u00e1cil escribir y dirigir que solo dirigir, la verdad. Cuando has creado a los personajes es menos complicado saber exactamente c\u00f3mo se mueven, qu\u00e9 hacen, c\u00f3mo respiran<\/p>\n<p>P.- Hola Isabel, buenas tardes. \u00bfCu\u00e1l crees que es la causa para ti de que en Jap\u00f3n haya tantos suicidios, y sea el pa\u00eds con m\u00e1s ikikomoris (gente capaz de vivir en una habitaci\u00f3n de por vida, y a la vez sean serviciales, educados y aparentemente tan felices?<\/p>\n<p>R.- Creo que hay mucha presi\u00f3n para la juventud japonesa, tienen unos ideales muy estrictos a los que es dif\u00edcil llegar&#8230;<\/p>\n<p>P.- Hola Isabel!!!. Me encanta tu cine y te sigo desde antes de que saliera en las salas comerciales.Las dos primeras peliculas q vi tuyas fue en la videoteca de la facultad de Ciencias de la informaci\u00f3n de la Complutense en los descansos como premio entre examen y examen;-D. Soy tambi\u00e9n una apasionada de la cultura oriental y en concreto de Jap\u00f3n y lo japones, y quer\u00eda preguntarte \u00bfPor qu\u00e9 Mapa de los Sonidos de Tokio? \u00bfQu\u00e9 tiene Tokyo que no tienen otras ciudades no s\u00f3lo del mundo sino de Jap\u00f3n? \u00bfQu\u00e9 tiene Tokyo que te hizo elegirla para esta nueva historia y conflicto entre personajes?.Un besazo enorme de una Madrile\u00f1a desde Dubl\u00edn;-D.Ana;-d<\/p>\n<p>R.- Hola Ana: Tokyo no es una ciudad , son mil ciudades en una, y ese contraste entre lo tradicional , lo pop, el zen, las chicas de Harajuku y los otakus la hace muy muy estimulante. Me encanta Dublin, by the way. Un abrazo Isabel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras su paso por Cannes, por fin se estrena en los cines Mapa de los sonidos de Tokio, la \u00faltima pel\u00edcula de Isabel Coixet. Rinko Kikuchi da vida a una chica solitaria que trabaja en una lonja de pescado y espor\u00e1dicamente es asesina a sueldo. Le encargan matar a Sergi L\u00f3pez. Secretos, mentiras y sexo con la capital japonesa como fondo.<br \/>\nEl videoblog de Isabel Coixet<br \/>\nEl d\u00eda a d\u00eda del rodaje<br \/>\nTr\u00e1iler de Mapa de los sonidos de Tokio<br \/>\n\u00danase al grupo de los encuentros<br \/>\nde elmundo.es en Facebook<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-3926","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/3926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=3926"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/3926\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=3926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=3926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=3926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}