{"id":3800,"date":"2009-11-23T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=3800"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"Chenoa3800","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/Chenoa3800\/","title":{"rendered":"Chenoa"},"content":{"rendered":"<p>Pregunta.- Hola mi ni\u00f1a, ante todo decirte que el jueves nos vemos aqui en Tenerife, y tengo tanto que decirte, que cuando te tenga delante no te dire nada de los nervios, seguro, jeje. \u00bfTe gusta estar pendiente de las ventas del disco? nos vemos Cristina.<\/p>\n<p>Respuesta.- Intento que no me influya a la hora de estar con tanto trabajo, aunque los resultados de este disco est\u00e1n perfectos y estoy muy contenta.<\/p>\n<p>P.- Chenoa, eres una mujer encantadora pero eres de hor\u00f3copo C\u00e1ncer como mi hermano y los C\u00e1ncer suelen ser impulsivos, un poco aneurados y de un grano haceis una monta\u00f1a, es decir, veis a veces el vaso medio vacio. Te idenfificas? C\u00f3mo te definir\u00edas? Marta.<\/p>\n<p>R.- No con todo, pero s\u00ed en parte. Jiji.<\/p>\n<p>P.- Una buena cul\u00e9 como t\u00fa (vale, tambi\u00e9n bermellona, pero con tu corazoncito blaugrana), \u00bfcon cu\u00e1l de las bellezas del Bar\u00e7a se quedar\u00eda? \u00bfPiqu\u00e9, M\u00e1rquez, Vald\u00e9s o Guardiola? Yo con Piqu\u00e9, lo tengo clar\u00edsimo. \u00bfQu\u00e9 esperas del partido del domingo? \ud83d\ude1b Mucha suerte con el disco!!!<\/p>\n<p>R.- Yo me quedo con Guardiola. Me parece un t\u00edo magn\u00edfico. Del partido espero que sea muy entretenido y ganemos.<\/p>\n<p>P.- que lugar del mundo te gustaria conocer en tus proximas vacaciones??? enhorabuena por tu trabajo, sinceramente diste un paso adelante, muy bueno! turista<\/p>\n<p>R.- \u00bfVacaciones? \u00bfQu\u00e9 es eso?<\/p>\n<p>P.- Hola Chenoa!! Para cuando nuevo single? Queremos que nos des ca\u00f1a!! ver una Chenoa guerrera \ud83d\ude1b<\/p>\n<p>R.- Seguramente impulsaremos el tema de Buenas noticias y lo promocionaremos como merece.<\/p>\n<p>P.- Siempre te defines como letrista, pero sabes tocar alg\u00fan instrumento? \u00bfCu\u00e1l? \u00bfA qu\u00e9 nivel? Si es as\u00ed, a ver si te animas en alg\u00fan conci. Por cierto, queremos m\u00e1s conciertos jeje.<\/p>\n<p>R.- Toco un poco de piano, estudi\u00e9 solfeo y flauta jijij. Por ahora no me veo tocando en un concierto.<\/p>\n<p>P.- Buenas tardes artista, \u00bfqu\u00e9 crees que te distingue de los dem\u00e1s cantantes? Un beso, whitecloud20<\/p>\n<p>R.- No me gusta comparar artistas. Yo hago las cosas a mi manera y a partir de ah\u00ed la gente decide.<\/p>\n<p>P.- chenoa te queremos mucho yo y hija de 6 a\u00f1os que baila tu musica cuando la pongo \u00bftengo una curiosidad he visto que llevas con vos siempre una cadenita que a veces te volteas la he visto en fotos es especial para ti un amuleto? VENTE PRONTO A AMERICA UN BESO DOBLE<\/p>\n<p>R.- Un besito para las dos. S\u00ed llevo un amuleto o protecci\u00f3n. Ya sabes, las envidias son muy malas.<\/p>\n<p>P.- Muy buenas!!! c\u00f3mo estamos?? lo primero felicitarte por este gran trabajo y por la l\u00ednea Tweety \ud83d\ude09 mi pregunta es \u00bfen tantos a\u00f1os que llevas ya en el mundo de la m\u00fasica, qu\u00e9 es lo que m\u00e1s te gusta de \u00e9l? Gracias porque a los que te seguimos desde hace 8 a\u00f1os, aun nos sigues dejando con la boca abierta y porque a los esc\u00e9pticos se la has cerrado \ud83d\ude09 Gracias por atendernos siempre tan amablemente!!! Un besazo artista!!! (Ana M&#038;M Madrid)<\/p>\n<p>R.- Lo que m\u00e1s me sigue gustando es estar en concierto. Y lo dem\u00e1s lo llevo con filosof\u00eda.<\/p>\n<p>P.- Con toda la promocion que tienes encuentras tiempo para hacer cosas normales como por ejemplo ir al cine? Sabemos que te gusta la saga de Crep\u00fasculo, has ido a ver la peli de Luna Nueva? Si no has ido te recomendamos que vayas bien acompa\u00f1ada, que es muy romanticonaa Un beso de Laura de Mallorca, Silvia de Madrid y Anaa de Barcelona(las angeles de charlie, tu guitarrista)<\/p>\n<p>R.- No tengo tiempo para hacer cosas normales. Me encantar\u00eda ver Luna nueva y si no me la comprar\u00e9. Ya os contar\u00e9.<\/p>\n<p>P.- \u00a1Hola Chenoa! Me ha encantado el homenaje a MJ en los conciertos de presentaci\u00f3n y me gustar\u00eda saber por qu\u00e9 has escogido Beat it. Besos desde Galicia. Vanessa(athenea07) Santiago de Compostela.<\/p>\n<p>R.- Me encanta esa canci\u00f3n. Y, siendo honesta, cualquiera sirve porque todas son buenas.<\/p>\n<p>P.- hola amor como estas? mi pregunta es los duos de tus discos los eliges tu o la discografica? y otra curiosidad que tengo te molesta que un fan en privado te llame laura? te quiero mi ni\u00f1a! besitos!!<\/p>\n<p>R.- Los d\u00faos los elijo yo, como la mayor\u00eda de las cosas. Gracias a Dios, cuento con la confianza de mi equipo. Que me llamen Laura no es que sea una molestia, es que simplemente me presento como Chenoa, con lo cual nunca doy pie a que se me llame Laura.<\/p>\n<p>P.- hola Chenoa , gracias por tu musica mi pregunta es \u00bfcuando vienes a latinoamerica?saludos desde Per\u00fa<\/p>\n<p>R.- Espero ir pronto y le debo una visita a Per\u00fa. Besitos enormes.<\/p>\n<p>P.- \u00bfque se siente al ver tantas cabezas juntas en un concierto?? madre m\u00eda&#8230;\u00bfque subid\u00f3n no?<\/p>\n<p>R.- Pues eso, mucho subid\u00f3n. Y muchas ganas de pasarlo bien. Acabo de venir de M\u00e1laga con la banda y estamos supercontentos.<\/p>\n<p>P.- has notado la crisis??<\/p>\n<p>R.- S\u00ed, pero no soy yo la que se vaya a quejar. No creo que tenga ese papel.<\/p>\n<p>P.- Es este el disco que estabas esperando hacer!?? Mucha suerte artista!<\/p>\n<p>R.- No lo s\u00e9. Pero, desde luego, ha quedado como yo quer\u00eda.<\/p>\n<p>P.- Con quien se identifica m\u00e1s Chenoa de las archiconocidas chicas de sexo en Nueva York, y porqu\u00e9. Besitos!<\/p>\n<p>R.- Me identifico mucho con Carrie por no aprender nunca del amor.<\/p>\n<p>P.- Chenoa enhorabuena por este gran cd que nos has regalado a todos, Hace unos dias te vi en el FNAC de Sevilla haciendo un concierto ac\u00fastico, pocos pueden hacer lo que tu tan sola acompa\u00f1ada por una guitarra. En este FNAC ocurri\u00f3 una an\u00e9cdota graciosa pues un Se\u00f1or a mitad del ac\u00fastico te pidoo ser la protagonista de un corto. \u00bf Has estudiado la propuesta?, ? te parece interesante? , Imagino que es una de las cosas mas priginales que te han pasado\u00bf no?. Un beso, guapa.<\/p>\n<p>R.- La verdad es que fue muy original y s\u00e9 que se ha puesto en contacto con mi oficina. Ya os ir\u00e9 contando.<\/p>\n<p>P.- \u00bfQue libro est\u00e1s leyendo actualmente?<\/p>\n<p>R.- El \u00faltimo de Millenium.<\/p>\n<p>P.- es cierto que no tienes cuenta de facebook o es una trola que me col\u00f3 lotto hace un par de meses? es que ambos tenemos de amigos en comun dos perfiles tuyos y cuando le pregunt\u00e9 cual de las dos eras tu me dijo que ninguna,que no tenias y que no me creyese esas cosas, pero estoy convencida de lo contrario ya que si no el tampoco los tendria agregados ni mi amiga nuria alsina ni nadie&#8230; besos muy grandes<\/p>\n<p>R.- Tengo cuenta de Facebook oficial.<\/p>\n<p>P.- Hola Has recibido alguna proposici\u00f3n para posar desnuda, lo har\u00e1s en un futuro, lo descartas?<\/p>\n<p>R.- S\u00ed he recibido. Constantes proposiciones. Yo nunca descarto nada, pero por respeto a los m\u00edos no lo veo.<\/p>\n<p>P.- Hola Chenoa, el otro d\u00eda me dijeron en la disquera de M\u00e9xico que tu cd llegaba a mi pais en febrero, seg\u00fan veo la canci\u00f3n &#8221; volverte a ver&#8221; a la que tu pusiste la voz esta siendo muy exitosa en mi pais y el videoclip tiene ya mas de un millon de visitas en youtube , la ponen mucho en radios y en una telenovela muy vista. \u00bf Incluiras este tema en &#8221; dasafiando la gravedad&#8221; o sera la misma edici\u00f3n que ya esta a la venta en Espa\u00f1a? Besos en M\u00e9xico te queremos y esperamos pronto.<\/p>\n<p>R.- Espero ir a M\u00e9xico en breve. Me encanta que la canci\u00f3n Volverte a ver funcione tan bien. No creo que est\u00e9 dentro de Desafiando la gravedad.<\/p>\n<p>P.- hola amor en el chat anterior dijiste que cuando estas mal te ocultas para que nosotros los chenoistas no nos preguntemos que te pasa o sea para que no nos preocupemos pero eso no siempre es asi porque tu cara es el espejo del alma y sabemos o al menos yo se cuando estas mal y cuando estas bien te tenemos o al menos yo caladisima ejejjee mi pregunta es \u00bfte molesta que los fans nos preocupemos por ti ya no solo profesional si no tambien personalmente? \u00bfte molesta que a veces seamos un poco mamis o papis contigo? que conste que lo hacemos porque te queremos al menos por mi parte es asi. te quiero besitos. guille (guilluelas)<\/p>\n<p>R.- No me molesta, pero a veces me gusta guardarme las cosas para m\u00ed.<\/p>\n<p>P.- \u00bfcomo decides el track-list de las giras? Me imagino que los singles son intocables, pero hace pupita que dejes de cantar &#8220;Camina&#8221;, en directo es&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;..SUBLIME.<\/p>\n<p>R.- Obviamente, tiene que haber una armon\u00eda en un show y no todas las canciones cuadran en el repertorio. Me encanta Camina. Ya veremos. Igual cae.<\/p>\n<p>P.- \u00bfComo te gustan los hombres fisicamente? n\u00f3tese que pregunto fisicamente porque he leido demasiadas entrevistas tuyas como para saber que me contestar\u00e1s que su conversaci\u00f3n&#8230;:P<\/p>\n<p>R.- Me gusta su conversaci\u00f3n. Y si est\u00e1n buenos, mejor. Jejej<\/p>\n<p>P.- Un refr\u00e1n que te haya servido de algo&#8230;<\/p>\n<p>R.- Ande yo caliente y r\u00edase la gente.<\/p>\n<p>P.- \u00bfVes los videos que hay sobre ti en youtube? \u00bfsueles &#8220;chequear&#8221; tus directos, o no te gusta verte?<\/p>\n<p>R.- Si tengo tiempo, veo alg\u00fan v\u00eddeo que otro.<\/p>\n<p>P.- Chenoa porque tardo tanto en sonar tu disco en los 40 principales , es verdad que estas vetada?<\/p>\n<p>R.- Jajaja. No, no estoy vetada en los 40, al contrario. Siempre me han apoyado mucho y esa es la raz\u00f3n por la cual Duele suena en Los 40.<\/p>\n<p>P.- CHENOA HAS IDO A LA BODA DE ALGUNO DE TUS CHENOISTAS?<\/p>\n<p>R.- No he tenido oportunidad, pero un d\u00eda me encontr\u00e9 a unos novios que iban al banquete y eran cheno\u00edstas. Hab\u00eda hecho una fiesta tem\u00e1tica y cada mesa era de un cantante: Tina Turner, Los Beatles y la mesa presidencial era la de Chenoa. QU\u00e9 grandes.<\/p>\n<p>P.- Chenoa, lo primero de todo, enhorabuena por este CD, que me parece de lejos el mejor de tu carrera. Sabemos que te has implicado al 110% en las letras de 9 de los temas del disco, pero \u00bfhasta qu\u00e9 punto te has implicado en lo puramente musical (melod\u00eda, arreglos, producci\u00f3n&#8230;)? \u00bfHay alguna canci\u00f3n cuya autor\u00eda (letra + m\u00fasica) sea 100% tuya? Saludos y felicidades por el disco! Pedro<\/p>\n<p>R.- No. Obviamente siempre he ido con mis dos novios, Yoel Henr\u00edquez y Mauricio Gasca. Los tres hemos hecho Desafiando la gravedad.<\/p>\n<p>P.- Hola Chenoa. \u00bfC\u00f3mo se lleva el que te critiquen por que pareces una mujer segura e independiente que no pega con los canones tradicionales de &#8220;mujer florero&#8221;? Creo, que hoy en d\u00eda, hay mujeres como t\u00fa, que tienen \u00e9xito en sus trabajos, y a pesar de todo, son criticadas porque todo se sigue viendo desde una visi\u00f3n demasiado masculina. Sigue as\u00ed de guerrera y gracias por ser as\u00ed!!!!<\/p>\n<p>R.- No lo llevo, simplemente esas cr\u00edticas se quedan en el camino. No me interesa gastar mi energ\u00eda con gente poco tolerante.<\/p>\n<p>P.- Chenoa, \u00bftendremos nueva web con foro, blog, &#8230; o tenemos que conformarnos con la de Universal? Besos. .JaviaN.<\/p>\n<p>R.- Por ahora, utilizamos la de de Universal y el foro de Univisi\u00f3n.<\/p>\n<p>P.- \u00bfCu\u00e1ndo y por qu\u00e9 se pone melanc\u00f3lica Chenoa?<\/p>\n<p>R.- Cuando hay luna llena me pongo mel\u00e1ncolica.<\/p>\n<p>P.- \u00a1Hola Chenoa! \u00bfQu\u00e9 significa el sol que llevas tatuado en la nuca? Con lo miedica que eres&#8230;, \u00bfc\u00f3mo se te pas\u00f3 la idea por la cabeza? Isa<\/p>\n<p>R.- El sol es el contrapunto a mi lado m\u00e1s lun\u00e1tico y pens\u00e9 que eso me dar\u00eda equilibrio, pero encuentro que estoy igual de loca. Jijiji<\/p>\n<p>P.- Ya tienes estructurada la gira?. Nos puedes adelantar donde ser\u00e1 el inicio ?. A ver si esta vez es un lugar que nos pille bien a todos, que Roquetas esta un pelin lejos jaja. Enhorabuena por el discazo. Mary<\/p>\n<p>R.- Todav\u00eda no tenemos nada. Estamos estructurando el show para que lo pas\u00e9is superbien.<\/p>\n<p>P.- \u00a1Hola Chenoa! \u00bfQue balance haces hasta el momento de los conciertos de presentaci\u00f3n y de las firmas de discos? \u00a1Muchos besos! Vanessa (athenea07) Santiago de Compotela.<\/p>\n<p>R.- Todo ha ido de maravilla, mejor de lo que me esperaba. Y eso me produce mucha satisfacci\u00f3n.<\/p>\n<p>P.- Siempre me ha llamado la atenci\u00f3n saber de d\u00f3nde sac\u00e1is tiempo las artistas en plena promoci\u00f3n de un CD para estar siempre a punto, en especial en lo que se refiere a la engorrosa tarea de la depilaci\u00f3n. \u00bfEres m\u00e1s de cera, de m\u00e1quina depilatoria, crema? \u00bfNos puedes dar alg\u00fan consejo a quienes tampoco encontramos tiempo para dedicar a nosotras mismas durante la semana? Besos y salud!!<\/p>\n<p>R.- No te contar\u00e9 como me depilo. Jiji. Pero bueno, siempre nos queda la noche para hacer alg\u00fan arreglillo.<\/p>\n<p>P.- Buenos d\u00edas, casi tardes. \u00bfC\u00f3mo le gusta a una chica sexy e interesant como t\u00fa que le entre un desconocido?<\/p>\n<p>R.- Me encanta que sea original y que sea divertido.<\/p>\n<p>P.- Hola Chenoa, tengo una hija de 5 a\u00f1os que se llama Sara, y me esta pregutando todos los dias, si vas a sacar ropa para ni\u00f1os de Tweety? nos vemos el jueves Cristina Tenerife.<\/p>\n<p>R.- S\u00ed, tenemos l\u00ednea infantil en menor escala. La puedes encontrar en El corte ingl\u00e9s.<\/p>\n<p>P.- por que cuando eres&#8221;corista&#8221; en tus cancioens pones&#8230;corista:chenoa y cuando eres letrista pones :Laura? xd me llamo la atencion. Un besoooooo Gijon t espera<\/p>\n<p>R.- El orden de los factores no altera el producto. Soy la misma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desafiando la gravedad es su nuevo trabajo. La cantante encara el \u00e1lbum m\u00e1s maduro de su carrera componiendo \u00edntegramente el disco junto a sus productores y escribiendo sobre temas que nunca se hab\u00eda atrevido a tocar. Duele es su primer single. Chenoa vuelve a sonar.<br \/>\n\u00danase al grupo de los encuentros<br \/>\nde elmundo.es en Facebook<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-3800","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/3800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=3800"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/3800\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=3800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=3800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=3800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}