{"id":3626,"date":"2010-04-22T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=3626"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"Edurne3626","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/Edurne3626\/","title":{"rendered":"Edurne"},"content":{"rendered":"<p>Pregunta.- Felicidades Edurne por este nuevo disco, ya ten\u00edamos ganas de escucharte con canciones nuevas. \u00bfCu\u00e1l es tu canci\u00f3n favorita del disco? La m\u00eda es Alguien como t\u00fa, aunque todas son muy buenas. Besos!!!<\/p>\n<p>Respuesta.- Muchas gracias. La verdad es que es una pregunta dif\u00edcil porque me encantan todas las canciones del disco, pero si tengo que decir alguna, ser\u00eda Oigo mi coraz\u00f3n.<\/p>\n<p>P.- Hola guapa! Tu primer single es Soy como soy, bueno, y, \u00bfcomo eres?<\/p>\n<p>R.- Soy una chica muy alegre, muy positiva con mucho sentido del humor, trabajadora y muy normal.<\/p>\n<p>P.- Edurne, \u00bfc\u00f3mo llevas que anoche media Espa\u00f1a te viese el trasero en el programa de baile? El vestido era tan corto&#8230;<\/p>\n<p>R.- No ensayamos con el vestuario de la gala y este tipo de cosas no se pueden controlar. Anoche lo pas\u00e9 un poco mal, pero luego no le d\u00ed importancia.<\/p>\n<p>P.- Hola guap\u00edsima, desde que saliste de Operaci\u00f3n Triunfo tuviste que luchar con mil encasillamientos.. que si &#8220;chica OT&#8221; luego &#8220;chica FHM&#8221; y siempre has conseguido que te acaben valorando por tu m\u00fasica \u00bfte llegaron a preocupar esas etiquetas? Besos y suerte con el disco!!<\/p>\n<p>R.- En un principio s\u00ed, pero luego como he ido trabajando much\u00edsimo, por suerte, y no he parado, la gente ha empezado ha valorarme musicalmente y ven esas otras cosas como un complemento.<\/p>\n<p>P.- Enhorabuena por el disco y por tu participaci\u00f3n en MQB, estoy segura de que ganar\u00e1s. Sigues pas\u00e1ndote por Collado Villalba? Eres un orgullo para todos! Un beso y mucha suerte.<\/p>\n<p>R.- Much\u00edsimas gracias. Por Villalba s\u00ed que sigo pasando, sobre todo los fines de semana. Siempre que tengo un d\u00eda libre no lo dudo y me bajo a mi pueblo. Un besito.<\/p>\n<p>P.- Hola Edurne, hasta que no escuch\u00e9 Amores Dormidos no comenc\u00e9 a estar pendiente de tu m\u00fasica.. me encanta!! \u00bfte gustar\u00eda que fuera la canci\u00f3n por la que te recordaran? Besos!!<\/p>\n<p>R.- No me importar\u00eda. Espero que me recuerden por muchas otras m\u00e1s, pero la verdad es que Amores dormidos ha sido uno de mis grandes \u00e9xitos. Es una canci\u00f3n que me encanta.<\/p>\n<p>P.- Hola Edurne, esta pregunta es de parte de la gente que esta en el foro oficial. Has pensado en incluir en el repertorio de la gira la balada de Cruce??Danos alguna sorpresilla en los conciertos porfaa. Con la letra de &#8230;voy tarde y sin avisar, espera PACIENTE&#8230; parece que estuvieses advirtiendonos lo que esta pasando con el videoclip xDD. P.D.: entra algun dia en el foro, que hacee mogollon que no entras yaa!!!<\/p>\n<p>R.- Es verdad que no entro, perdonadme. A ver si saco un huequito pronto. \u00daltimamente no tengo tiempo ni para comer ni dormir (jajaja). Lo de cantar el tema de Cruce no lo hab\u00eda pensado, pero con la cantidad de canciones que tengo en estos cuatrodiscos, no creo que la vaya a cantar. Y el videoclip, de verdad que espero que en esta semana pod\u00e1is verla.<\/p>\n<p>P.- Buenos d\u00edas Edurne! Me encantaste en el musical de Grease, hiciste ver a mucha gente que no s\u00f3lo eres una cara bonita que canta como los \u00e1ngeles y por ello me alegr\u00e9 much\u00edsimo. Espero que podamos seguir vi\u00e9ndote en muchos trabajos de ese estilo. \u00bfTienes planes para m\u00e1s musicales o televisi\u00f3n o cine&#8230;? Gracias y suerte con tu nuevo \u00e1lbum! Un beso!<\/p>\n<p>R.- S\u00ed que en un futuro me encantar\u00eda volver a hacer un musical. Ha sido una experiencia inolvidable en mi vida. Pero, de momento, prefiero seguir centrada en la m\u00fasica, en las giras de conciertos con discos que me gusten tanto como Nueva piel.<\/p>\n<p>P.- Hola Edurne. \u00bfC\u00f3mo te sientes cuando en MQB te gana Bel\u00e9n Esteban cuando objetivamente tu bailas 100.000 veces mejor?<\/p>\n<p>R.- Cada de uno de los que participamos querr\u00edamos ganar siempre, pero al final gane el que gane se va a destinar a una ONG. Quiero ganar y me dejo la piel cada semana as\u00ed que os pido que me vot\u00e9is porfa. Lo que importan son los votos de los espectadores.<\/p>\n<p>P.- Con quien te gustaria hacer un duo? Un beso guapa!<\/p>\n<p>R.- Me encantar\u00eda con Mika. Creo que el estilo de m\u00fasica es muy parecido y es un d\u00fao que podr\u00eda ser muy potente. Un beso.<\/p>\n<p>P.- Edurne, \u00bfQue nos puede contar sobre la gira? \u00bfHay mas fechas confirmadas a parte de la de Madrid? \u00bfHaras mas firmas de discos? Un besito desde Alicante.<\/p>\n<p>R.- Empezar\u00e9 a preparar la gira cuando acabe el programa porque ahora mismo no tengo tiempo. Hay muchas reservas de fechas que ir\u00e1n anunci\u00e1ndose en mi web (www.edurneweb.com).<\/p>\n<p>P.- \u00bfTe ves haciendo carrera en el cine? \u00bfHa habido ya alguna oferta?<\/p>\n<p>R.- Me encantar\u00eda hacer cine. Es una de las cosas que me faltan por hacer y alguna que otra oferta s\u00ed que ha habido&#8230;<\/p>\n<p>P.- \u00bf Quien crees que ganara MQB ?<\/p>\n<p>R.- Espero ganar yo. \u00a1Apoyadme!<\/p>\n<p>P.- Hola Edurne!! Enhorabuena por el disco, la verdad es que me encanta y me parece que gana mucho con cada escucha! Mi pregunta es con respecto a con qui\u00e9nes de tu edici\u00f3n de OT mantienes relaci\u00f3n?? Y mantienes relaci\u00f3n con gente de otras ediciones?? Un besazo!<\/p>\n<p>R.- Intento seguir el contacto con casi todos mis compa\u00f1eros, pero es dif\u00edcil porque cada uno ha seguido su camino y vivimos en sitios diferentes, pero una llamadita nunca falta.<\/p>\n<p>P.- Hola Edurne!antes de nada decirte que para mi eres la cantante mas completa del panorama espa\u00f1ol que tu voz me impresiona cada vez que escucho tus discos que no para de hacerlo..jeje! \u00bfTienes pensado ir a latinoamerica?\u00bfQu\u00e9 disco o qu\u00e9 canci\u00f3n prefieres para empezar a promocionarte por alli? Soy de Ecuador y pienso enviar Nueva piel para que lo escuche mi familia!Bss wapa. Para mi eres la mejor!.Jorge El xico q te grita en MQB jeje<\/p>\n<p>R.- Un besito, Jorge, gracias por gritarme tanto, me animas mucho. Me encantar\u00eda poder ir a Latinoam\u00e9rica. Espero poder tener oportunidad con este disco. Hay muchas canciones con las que me gustar\u00eda empezar a sonar all\u00ed.<\/p>\n<p>P.- Hola Edurne, escuch\u00e9 que llevas semanas recorriendo Inglaterra para prepararte y conocer nuevos estilos musicales \u00bfqu\u00e9 tal ha resultado la experiencia? Besos!!<\/p>\n<p>R.- Estuve tres meses en Londres el verano pasado y aprovech\u00e9 para ver conciertos, conocer a gente, reforzar el ingl\u00e9s, estudiar clases de canto y todo lo he aprovechado para este nuevo disco. Una experiencia inolvidable.<\/p>\n<p>P.- edurne.. cual es tu rutina diaria para estar siempre estupenda? aparte del baile, baile y mas que baile&#8230; jajaja!! besitos y mucha suerte con nueva piel, es genial!<\/p>\n<p>R.- Sobre todo comer equilibradamente, beber mucha agua y sobre todo ser feliz. Lo de intentar ser feliz es fundamental.<\/p>\n<p>P.- Ya son unos cuantos a\u00f1os de carrera art\u00edstica &#8230; parece mentira c\u00f3mo pasa el tiempo de r\u00e1pido &#8230; En todos estos a\u00f1os, \u00bfCu\u00e1l ha sido el mejor y cu\u00e1l el peor momento profesionalmente hablando?<\/p>\n<p>R.- Lo mejor: poder tener cuatro discos y estar en una compa\u00f1\u00eda discogr\u00e1fica importante. Lo peor: perder el anonimato.<\/p>\n<p>P.- \u00bfEs cierta esa leyenda urbana de que te ofrecieron ser la vocalista de la Oreja de Van Gogh cuando se fue Amaia?<\/p>\n<p>R.- M\u00e1s que una leyenda fue una broma que hicieron el d\u00eda de los inocentes en Anda ya, un programa de Los 40.<\/p>\n<p>P.- Edurne, \u00bfTe gustar\u00eda ir alg\u00fan d\u00eda a Eurovisi\u00f3n?<\/p>\n<p>R.- En este momento no est\u00e1 en mi cabeza, pero quiz\u00e1 en un futuro&#8230; \u00bfQui\u00e9n sabe?<\/p>\n<p>P.- hola edurne soy cristina que tal eres la mejor y cantas muy bien te veo todos los miercoles en mas que baile y bailas muy bien \u00bfedurne cuando puedo ver el videoclips de soy como soy?. un beso de cristina<\/p>\n<p>R.- Est\u00e1 a punto de salir. Espero que te guste.<\/p>\n<p>P.- Ahora que la Liga est\u00e1 tan apretada, \u00bfDe que equipo eres?. Gracias Edurne, un saludo!<\/p>\n<p>R.- Reconozco que el Bar\u00e7a esta siendo el mejor este a\u00f1o, pero yo soy del Madrid.<\/p>\n<p>P.- \u00bfCrees que el f\u00edsico en fundamental para tener una carrera exitosa en el mundo de la m\u00fasica? Un beso enorme.<\/p>\n<p>R.- No. Creo que el f\u00edsico es fundamental si te quieres dedicar a ser modelo, pero si eres cantante, por mucha cara bonita que tengas si no cantas bien, no hay nada que hacer.<\/p>\n<p>P.- Mi canci\u00f3n favorita tambi\u00e9n es &#8220;Oigo mi coraz\u00f3n&#8221;. \u00bfLas canciones de tu disco, y en especial esta, son adaptaciones del ingl\u00e9s o est\u00e1n compuestas en espa\u00f1ol con productores espa\u00f1oles?<\/p>\n<p>R.- Son canciones compuestas por ingleses, suecos y otros extranjeros y se han adaptado al espa\u00f1ol.<\/p>\n<p>P.- \u00bfQu\u00e9 m\u00fasica lleva Edurne en su MP3?<\/p>\n<p>R.- De todo. Pero sobre todo chicas: Beyonc\u00e9, Pink, Lady Gaga, Pixie Lott, Anastacia&#8230;<\/p>\n<p>P.- Muy buenas. \u00bfSe pueden hacer verdaderos amigos dentro del mundo de la m\u00fasica? Desde fuera, tengo la impresi\u00f3n de que es un mundo bastante competitivo. Un besazo enorme.<\/p>\n<p>R.- Hay de todo un poco, como en todos los sitios, pero por supuesto que se pueden hacer amigos, de hecho tengo a bastantes amigos dentro del mundo de la m\u00fasica.<\/p>\n<p>P.- !Buenos d\u00edas, cosa guapa!Ahora todo va bien y trabajo (bendito trabajo) no te falta. Todo son buenas cr\u00edticas y tienes el apoyo de todo el mundo, pero cuando las cosas no van tan bien &#8230; \u00bfEn qu\u00e9 o en qui\u00e9n te refugias?\u00bfTienes alg\u00fan lugar especial en el que te guste perderte para meditar y poder salir de los baches? Un besazo enorme y toda la suerte del mundo. David.<\/p>\n<p>R.- Si tengo un d\u00eda triste me gusta estar en el jard\u00edn en mi casa de la sierra o mirar el cielo por las noches para ayudarme a estar relajada y pensar y reflexionar.<\/p>\n<p>P.- Vas a terminar veterinaria?<\/p>\n<p>R.- Es algo que me encantar\u00eda, pero de momento prefiero seguir mi carrera discogr\u00e1fica. Es dif\u00edcil llegar hasta donde estoy y quiero aprovecharlo.<\/p>\n<p>P.- hola Edurne \u00bfcomo es tu pr\u00edncipe azul?<\/p>\n<p>R.- Sobre todo que tenga mucho sentido del humor. Eso es fundamental.<\/p>\n<p>P.- Hola guap\u00edsima. He comprado &#8220;Nueva Piel&#8221; y te felicito porque desde la 1\u00aa a la \u00faltima canci\u00f3n me encanta, no puedo dejar de oirlo. Te veo tambi\u00e9n en MQB cada mi\u00e9rcoles y bailas de esc\u00e1ndalo, superior; en fin eres una inspiraci\u00f3n para m\u00ed. Va la pregunta: Supongo que a medida que pasa el tiempo te est\u00e1s haciendo m\u00e1s y m\u00e1s famosa, \u00bfc\u00f3mo lo llevas? \u00bfTe llega a agobiar?. Besos.<\/p>\n<p>R.- Es algo que llevo bastante bien. No he cambiado nada de mi vida por este tema. S\u00e9 que forma parte de mi trabajo. Que la gente me muestre el cari\u00f1o que me tiene lo agradezco, por lo que lo llevo muy bien.<\/p>\n<p>P.- \u00bf Que champu usas realmente ?.<\/p>\n<p>R.- Uso muchos. Tambi\u00e9n te digo que cuando hice el anuncio de Herbal Essences siempre usaba ese champ\u00fa. La verdad es que me gusta cambiar.<\/p>\n<p>P.- Hola Edurne! Soy un gran admirador tuyo de Matar\u00f3 (Barcelona) y me gustar\u00eda saber si tienes previsto o te han propuesto participar en alg\u00fan otro musical. Me gustar\u00eda mucho volver a verte sobre el escenario de un teatro porqu\u00e9 considero tienes muy buenas aptitudes para la interpretaci\u00f3n&#8230; y porqu\u00e9 no decir tambi\u00e9n para el baile! Nos has dejado a todos boquiabiertos! Dani<\/p>\n<p>R.- Me han propuesto varios musicales (el de Los 40, Hoy no me puedo levantar en Barcelona y Chicago para hacer de Roxy este verano), pero de momento estoy inmersa en mi nuevo disco y la gira del verano.<\/p>\n<p>P.- Hola Edurne! \u00bfTienes cosquillas? \u00bfD\u00f3nde tienes m\u00e1s? Un abrazo enorme desde Valencia!<\/p>\n<p>R.- Tengo, pero no muchas. Te voy a confesar que en las rodillas es donde m\u00e1s tengo.<\/p>\n<p>P.- Hola. Te vi en la Sala Sol hace unos a\u00f1os y en persona eres a\u00fan m\u00e1s guapa, \u00bferes mucho de salir por ah\u00ed de fiesta hasta las tantas o prefieres otros planes?. Besos.<\/p>\n<p>R.- Muchas gracias. La verdad es que no soy mucho de fiestas. No me gusta estar en sitios donde no pueda hablar con mis amigos. Prefiero quedar m\u00e1s en casa y estar cenando tranquilamente.<\/p>\n<p>P.- Hola guap\u00edsima! \u00bfA qui\u00e9n conociste personalmente en la gala de los 20 a\u00f1os de T5? Tal vez, El Duque, o Indhira? \u00bfQui\u00e9n te cay\u00f3 mejor o peor? Un beso! Nico (Granada)<\/p>\n<p>R.- Conoc\u00ed a El Duque y tengo que decir que es maj\u00edsimo, muy normal. Lo pas\u00e9 muy bien esa noche.<\/p>\n<p>P.- Hola hermosura!! \u00bfQu\u00e9 opinas sobre las votaciones del jurado en MQB, crees que lo hacen valorando el baile? Sabiendo la popularidad que tiene Bel\u00e9n, \u00bfPiensas que finalmente se har\u00e1 justicia con el ganador de la edici\u00f3n? Un beso! Nico (Granada)<\/p>\n<p>R.- Ahora ya no vota el jurado, pero nos valora el baile, lo que me parece fundamental para poder mejorar. Espero que finalmente el ganador de esta edici\u00f3n sea alguien que se lo curre de verdad y se lo merezca.<\/p>\n<p>P.- Edurne, \u00bfest\u00e1s contenta de c\u00f3mo est\u00e1 yendo el CD hasta ahora? un besazo, nunca cambies \ud83d\ude00<\/p>\n<p>R.- S\u00ed, de momento no me puedo quejar. Tal y como est\u00e1n las cosas, est\u00e1 yendo bastante bien.<\/p>\n<p>P.- \u00bfC\u00f3mo fue parodiar &#8220;Colgado en tus manos&#8221; con Jos\u00e9 Mota, Edurne? Me re\u00ed mucho.<\/p>\n<p>R.- Yo me re\u00ed much\u00edsimo m\u00e1s. Con Jos\u00e9 siempre he tenido muy buena relaci\u00f3n y cuenta conmigo para estas cosas. Creo que todos estamos de acuerdo que la canci\u00f3n ha sido un poco cansina y me pareci\u00f3 muy divertido hacer esta parodia.<\/p>\n<p>P.- Edurne guap\u00edsima, adel\u00e1ntanos algo de la portada de FHM por favor! que ya en nada sale y no sabemos nada de nada, danos una peque\u00f1a pista o dinos algo, por peque\u00f1o que sea por favor! jajajaj un beso artista!<\/p>\n<p>R.- No puedo decir nada. Lo que s\u00ed te puedo avanzar es que ha sido una de las mejores sesiones de fotos de mi vida.<\/p>\n<p>P.- \u00bfQue cancion de tus cuatro discos es la que mas te emociona?<\/p>\n<p>R.- Ahora mismo dir\u00eda Sin f\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soy como soy es el primer single su cuarto \u00e1lbum, Nueva piel. Un estilo diferente con pop electr\u00f3nico y dance con canciones directas para triunfar en las pistas de baile. Este nuevo disco de Edurne llega tras su gira por toda Espa\u00f1a protagonizando el musical Grease como Sandy.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-3626","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/3626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=3626"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/3626\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=3626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=3626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=3626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}