{"id":3544,"date":"2010-06-11T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=3544"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"David_Cortina3544","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/David_Cortina3544\/","title":{"rendered":"David Cortina"},"content":{"rendered":"<p>Pregunta.- Hasta que valor piensa usted que bajar\u00e1 el IBEX? He escuchado previsiones pesimistas que lo sit\u00faan por debajo de los 6.000 puntos durante el 2010.<\/p>\n<p>Respuesta.- En mi opini\u00f3n es dif\u00edcil que el Ibex llegue a esos niveles, que no los hemos visto siquiera cuando estaba en riesgo el sistema financiero internacional , creo recordar que lleg\u00f3 a niveles de 6.700. Los niveles de ca\u00edda los ir\u00e1 marcando los diferenciales con el bono alem\u00e1n y los CDS de la deuda soberana, pero creo que se est\u00e1n tomando medidas importantes para controlar y reducir el d\u00e9ficit p\u00fablico de los pa\u00edses m\u00e1s endeudados y que deber\u00edamos ir viendo una reducci\u00f3n en los spread de deuda. No creo sinceramente que el IBEX baje mucho m\u00e1s de los niveles de 8.000 puntos , a no ser que hubiera un default en alguna deuda soberana.<\/p>\n<p>P.- Buenos d\u00edas, se\u00f1or Cortina, cree usted que es un buen momento para entrar en Gas Natural? cual es su valoraci\u00f3n sobre la compa\u00f1\u00eda por favor y que nivel de entrada elegir\u00eda para entrar en el valor?. Muchas gracias<\/p>\n<p>R.- Yo creo que niveles por debajo de los 12 euros es un nivel claro de compra. El mercado en mi opini\u00f3n ha penalizado en exceso tanto el riesgo financiero como el riesgo operativo de la compa\u00f1\u00eda, a pesar de sus s\u00f3lidos resultados publicados en un dif\u00edcil entorno macroecon\u00f3mico.La compa\u00f1\u00eda est\u00e1 cumpliendo su plan de reestructuraci\u00f3n finnaciera : plan de desinversiones por importe de 3,7bn frente a los 3bn previstos, colocaci\u00f3n exitosa de bonos por 7bn con un cup\u00f3n medio del 4,66%, y la refinanciaci\u00f3n de su deuda. Por tanto no creo que tenga problemas para hacer frente a sus pr\u00f3ximos vencimientos de deuda ( 513mn en 2010, 971mn en 2011 y 2370mn en 2012 ) , m\u00e1s de la mitad con vencimiento superior a 2015, y con la presentaci\u00f3n de su plan estrat\u00e9gico previsto para antes del verano, podr\u00eda servir para despertar el inter\u00e9s inversor en un valor cuyo negocio est\u00e1 autorregulado y que tiene un a rentab x divid superior al 6 %. Yo lo tendr\u00eda en mi cartera.-<\/p>\n<p>P.- BUENOS D\u00cdAS DAVID, \u00bfES BUEN MOMENTO PARA ENTRAR EN FCC? \u00bfY ARCELOR? GRACIAS<\/p>\n<p>R.- FCC es un valor que se relaciona con la obra p\u00fablica y el mercado lo ha penalizado fuertemente por las medidas del gobierno encaminadas a reducir el gasto p\u00fablico. Yo creo que los niveles de 18 euros deben servir de soporte al valor y que para una inversi\u00f3n superior a dos a\u00f1os puede dar una buena rentabilidad, pero que el mercado en los momentos actuales prefier otros sectores con mayor visibilidad en el medio plazo. Respecto a ARCELOR , es un buen valor , muy ligado a recuepraci\u00f3n econ\u00f3mica internacional y que a los precios actuales de 23 euros me parece una buena oportunidad de inversi\u00f3n, a pesar de que el mercado est\u00e9 penalizando que las medidas de control de gasto p\u00fablico puedan dificultar esa recuperaci\u00f3n.<\/p>\n<p>P.- Buenos dias David, me gustaria invertir en Telefonica e Iberdrola, las dos tienen una buena rentabilidad por dividendo, me parecen companias con solidos fundamentales, etc&#8230; pero desde el punto de vista tecnico necesitaria que me aconsejases, es momento de entrar? Que niveles tengo que vigilar? Muchas gracias Jose<\/p>\n<p>R.- Son dos de los grandes valores de la bolsa espa\u00f1ola que deben estar normalemnet en cualquier cartera de renta variable, y que compensan la ca\u00edda de su negocio dom\u00e9stico con su alta exposici\u00f3n geogr\u00e1fica internacional, por lo que deber\u00edan tener un mejor comportamiento que sus comparables. Niveles de entrada , para TEF 14,80-15 EUROS y para IBERDROLA 4,80- 5,10 euros. Yo particularmente creo que est\u00b4na cotizando a precios muy atractivos para una inversi\u00f3n a medio plazo y que su alta renatb x dividendo sostenible, justifica esa inversi\u00f3n .gracias.-<\/p>\n<p>P.- David , buenos dias , quisera saber que consideracion tienes para invertir a dos a\u00f1os. Es mejor la rv o la rf corporativa?. Muchas gracias<\/p>\n<p>R.- Yo creo que despu\u00e9s del fuerte castigo sufrido por los grandes valores de la Bolsa , es m\u00e1s atractiva la renta variable , d\u00f3nde podemos encontrar muy buenos valores con rentab x didv cercanas o sueriores al 10 % ( TEF, BME, los dos grandes bancos, Eetc&#8230; ). gracias.<\/p>\n<p>P.- \u00bfNo parece arriesgado invertir ahora, sin esperar a la gran subasta de deuda de Julio?<\/p>\n<p>R.- para invertir con mayor seguridad sin duda ser\u00eda conveniente esperar a la subasta de deuda de julio de m\u00e1s de 20.000 mn euros; no obstante la seguridad va relacionada directamente con los precios. Estamos viendo una recuperaci\u00f3n fuerte de los mercados motivada por la buena acogida de la subasta de ayer del Tesoro espa\u00f1ol y por las declaraciones de TRICHET asegurando la liquidez al sistema financieor con subastas a 3 meses por importe ilimitado. En la medida que la subasta de julio se coloque y se haga a tipos den inter\u00e9s razonables el mercado puede seguir recuperando niveles anteriores, y sin duda es un riesgo el tomar posiciones antes de la subasta de julio , pero tambien la publicaci\u00f3n de resultados mpresariales del 2T10 puede servir de catalizador a los mercados. gracias<\/p>\n<p>P.- \u00bfQu\u00e9 cree que va a suceder con las acciones de Prisa?\u00bfY con las de Campofr\u00edo?<\/p>\n<p>R.- En mi opini\u00f3n PRISA es un valor de riesgo con un alto endeudamiento que parece que lo peor ha podido pasar con las desinversiones que est\u00e1 llevando a cabo,y que recientemente hemos conocido su inter\u00e9s en comprar LE MONDE, con lo que parece que la situaci\u00f3n financiera de la compa\u00f1\u00eda est\u00e1 dando s\u00edntomas de recuperaci\u00f3n. Campofr\u00edo es un valor defensivo, l\u00edder en su sector, con el importante inconveniente de su falta de liquidez, y que creo que a los precios actuales de los blue chips , cualquiera de ellos es m\u00e1s interesante que este tipo de valores peque\u00f1os para poder entrar y salir en momentos de alta volatilidad como los qu estamos viendo en los mercados.<\/p>\n<p>P.- \u00bfQu\u00e9 tal ve la inversi\u00f3n en Sacyr en estos precios con un horizonte de 2-3 a\u00f1os?<\/p>\n<p>R.- Esta semana est\u00e1 cotizando en los m\u00ednimos de los \u00faltimos a\u00f1os, lo que demuestra las dificultades de la compa\u00f1\u00eda en el sectior en que se encuentra; creo necesario que reduzca su alto endeudamiento y una de las opciones m\u00e1s probables es su desinversi\u00f3n en REpsol, lo que dar\u00eda un gran respiro a la compa\u00f1\u00eda , que es la m\u00e1s dependiente del sector inm obiliario y constructor, cuya recuperaci\u00f3n no va a ser f\u00e1cil durante esos 2 o 3 a\u00f1os que plantea. Creo que hay opciones con menos riesgo y m\u00e1s visibilidad en ese plazo:<\/p>\n<p>P.- \u00bfC\u00f3mo ve a Almirall? Compr\u00e9 al superar los 10E, \u00bfpuedo esperar recuperar lo invertido?<\/p>\n<p>R.- Es un sector defensivo, que est\u00e1 cotizando cerca de los m\u00ednimos y que se ha visto penalizado por la reforma sanitaria y la situaci\u00f3n actual de los mercados. Es un buen valor a medio y largo plazo, que es posible que recupere esos niveles de compra aunque creo el mercado antes deber\u00eda recuperarse los grandes valores con alta capitalizaci\u00f3n y fuerte exposici\u00f3n internacional.-<\/p>\n<p>P.- mi pregunta es por estos valores . nh hoteles , jazztel y zeltia. los he comprado el lunes y ya le le gano un poquito. lo mantengo porque esto es un rebote tecnico o las dejo. un saludo.<\/p>\n<p>R.- Yo mantendr\u00eda esos valores porque ha comprado a buenos precios y a medio plazo deber\u00edan recuperar bastante m\u00e1s. El caso de JAZZ es uno de los beneficiados de la crisis y podemos verlo cotizar cerca de los 3 euors otra vez, NHH yo no lo vender\u00eda por debajo de 3 euros y ZEL a medio plazo es un valor con potencial de revalorizaci\u00f3n aunque para un perfil de alto riesgo. gracias.<\/p>\n<p>P.- Quer\u00eda comprar acciones de Amadeus. \u00bfQu\u00e9 le parece?<\/p>\n<p>R.- Ha tenido un estreno en BOLSA espectacular y recientemente ha recibido fuertes recomendaciones de compra por analistas internacionales con precio objetivos de 16 euros. Yo ser\u00eda prudente y creo que hay opciones m\u00e1s baratas como TEF , los dos bancos o energ\u00e9ticas y con una atractiva rentab x divi.<\/p>\n<p>P.- Desde su punto de vista, la recuperacion de la Bolsa se debe a una verdadera recuperacion economica o a los bajisimos tipos de interes del BCE ? No le parece que los altos precios del oro parecen indicar lo segundo ?<\/p>\n<p>R.- Los altos precios del oro hacen desconfiar de la recuperaci\u00f3n econ\u00f3mica internacional y por tanto de las Bolsas,y la recuperaci\u00f3n de la Bolsa se debe en gran parte a las declaraciones de TRICHET asegurando la liquidez con subastas a 3 meses en Julio , Agosto y Septiembre, a la revisi\u00f3n al alza para el crecimiento en Europa, fuerte crecimiento de las exportaciones en China y a la demanda de deuda espa\u00f1ola producida ayer, unido a los posibles movimientos corporativos en el sector financiero espa\u00f1ol. Esta recuperaci\u00f3n se tiene que confirmar con las pr\u00f3ximas subastas de deuda espa\u00f1ola y con la publicaci\u00f3n de resultados empresariales del 2T10.<\/p>\n<p>P.- Buenos d\u00edas, c\u00faal es su impresi\u00f3n sobre Acerinox?. Estoy interesado en el sector y no se si este valor refleja bien la tenencia del mismo. Me podr\u00eda orientar?. Gracias<\/p>\n<p>R.- Acerinox, aprob\u00f3 mantener el dividendo de 0,45 euros con cargo al 2009 a pesar de tener el peor a\u00f1o de su historia y coment\u00f3 que conf\u00eda en una fuerte recuperaci\u00f3n de la demanda para el 2SEl comportamiento del valor deber\u00eda ir mejorando a lo largo del a\u00f1o, apoyado en una mejora de la utilizaci\u00f3n de capacidad, junto con las subidas de los precios del trimestre superiores al 5% sobre el 1T10 tanto en Norteam\u00e9rcica como en Europa, con estimaciones de EBITDA de m\u00e1s de 160mn frente a los 61mn del 1TPor otro lado, la exposici\u00f3n de ACX al mercado norteamericano superior al 40 % le har\u00e1 tener un mejor comportamiento frente a sus competidores europeos. Mi recomendaci\u00f3n es de compra.<\/p>\n<p>P.- buenos dias David, tengo unas grifols compradas a finales del a\u00f1o pasado entorno a los 12 euros&#8230;con el tema este de la compra de Talecris y el profit warning de Baxter..el valor ha ca\u00eddo bastante&#8230;Me recomienda mantenerlas?? Gracias<\/p>\n<p>R.- La operaci\u00f3n de compra de TALECRIS, realizada por GRIFOLS tiene sentido financiero simpre que las sinergias anunciadas se concreten, que ser\u00edan de aprox 230mn$ .Desde el punto de vista estrat\u00e9gico plantea muchas dudas por varios motivos: alto precio pagado ( prima del 70% ), fuerte endeudamiento, peso en USA del 60 % que es el mercado que menos se espera que crezca y con amenaza de precios y las reformas sanitarias pueden penalizarla.Creo que hay opciones m\u00e1s intersantes en el mercado y con menor riesgo como he mencionado anteriormente. gracias.-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director de contrataci\u00f3n de renta variable de Banif Banca Privada, David Cortina, aclara sus dudas sobre las perspectivas del mercado espa\u00f1ol y de sus valores en plena tormenta burs\u00e1til.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-3544","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/3544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=3544"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/3544\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=3544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=3544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=3544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}