{"id":3412,"date":"2010-11-03T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=3412"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"Diego_Vasallo3412","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/Diego_Vasallo3412\/","title":{"rendered":"Diego Vasallo"},"content":{"rendered":"<p>Pregunta.- Daria todo lo que tengo, y si me tocase la loteria invertiria todo en que mi hija de 2 a\u00f1os pudiera ir un dia a un concierto de Duncan, de los que tanto su padre disfrutaba durante tantos a\u00f1os. \u00bf hay alguna posibilidad de que mi hija pueda disfrutarlo? Fernando de Zaragoza. Tu nuevo disco cuenta que estara en mi coleccion<\/p>\n<p>Respuesta.- REalmente esta dificil, no somos muy dados a la nost\u00e1lgia y creo que tanto Mikel como yo estamos muy metidos en nuestras propias carreras en solitario, con lo cual veo complicado una reunificaci\u00f3n del grupo.<\/p>\n<p>P.- Hola Diego! En un art\u00edculo publicado recientemente en el Diario Vasco, sobre tu nuevo disco, indicaban la capital murciana al lado de tu fecha de nacimiento. Imagino que ser\u00eda una errata, pero.. \u00bf\u00bferes de Murcia?? Mucha suerte con el disco! Mariajo.<\/p>\n<p>R.- Efectivamente es un error, soy de San Sebasti\u00e1n del 2 del 4 del 66<\/p>\n<p>P.- Hola Diego, enhorabuena por el disco. De nuevo a la altura de tu obra. \u00bfte has planteado hacer una gira solo con guitarra, en plan trovador? Hay muchas ganas de verte en directo, muchas.<\/p>\n<p>R.- Si que me lo he planteado alguna vez, pero mis limitaciones como instrumentista hacen que todav\u00eda prefiera acompa\u00f1arme de algunos m\u00fasicos, pero no lo descarto para un futuro. En cualquier caso mi intenci\u00f3n es que haya algunos conciertos en directo, probablemente a partir de enero.<\/p>\n<p>P.- Buen d\u00eda. Habr\u00e1 un segundo disco con Roger Wolfe? Como se gest\u00f3 el priimer disco?? y por qu\u00e9??<\/p>\n<p>R.- No se si alguna vez se dar\u00e1 la circunstancia de que podamos volver a trabajar juntos. Fue una colaboaraci\u00f3n muy especial que surgio un poco por casualidad a raiz de un encuentro que tuvimos en un recital de poes\u00eda que \u00e9l di\u00f3 en San Sebasti\u00e1n. Estuvimos en contacto despu\u00e9s de eso y se nos ocurri\u00f3 la idea de hacer alg\u00fan trabajo conjunto. La verdad es que nos llev\u00f3 bastante tiempo darle forma y es un disco del que me siento especialmente contento.<\/p>\n<p>P.- Diego, actualizar\u00e1s algo m\u00e1s tu p\u00e1gina para que podamos estar m\u00e1s informados de tus discos, conciertos y exposiciones?? gracias.<\/p>\n<p>R.- Si, estoy en ello, aunque siempre voy un poco retrasado en lo que se refiere a noticias, pero procuro que no pase demasiado tiempo sin actualizarse. Podeis encontrarla en la direcci\u00f3n: www.diegovasallo.info<\/p>\n<p>P.- \u00bfque te parece el \u00faltimo disco de tu amigo Erentxun? \u00bfcrees que est\u00e1ias ahor mas cerc musicalmente que incluso en los \u00faltimos a\u00f1os de Duncan Dhu??<\/p>\n<p>R.- Es un disco que me gusta especialmente, creo que es de los mejores de su discograf\u00eda. Lo he escuchado bastante \u00faltimamente y quiz\u00e1 yo no veo tan claro que estemos tan cercanos musicalmente, sigo viendo diferencias en cuanto a las influencias musicales aunque es verdad que quiz\u00e1 haya m\u00e1s puntos en com\u00fan que en otros discos de Mikel.<\/p>\n<p>P.- &#8220;Cien gaviotas que hoy a\u00fan no s\u00e9 donde van&#8221; (Disco: Criaturas &#8211; Canci\u00f3n: Diez a\u00f1os) \u00bfYa lo sabes? Un abrazo desde Madrid.<\/p>\n<p>R.- Pues no, sigo sin saber donde van despu\u00e9s de tantos a\u00f1os, igual que sigo sin saber a d\u00f3nde me conducir\u00e1n los pr\u00f3ximos discos.<\/p>\n<p>P.- \u00bfQu\u00e9 tal, Diego? \u00bfC\u00f3mo te expresas mejor, a traves de la pintura o de la m\u00fasica? Un saludo.<\/p>\n<p>R.- Son disciplinas muy diferentes y aunque \u00faltimamente he estado m\u00e1s dedicado a la pintura, la m\u00fasica, y sobre todo el grabar discos, es algo a lo que estoy demasiado acostumbrado como para pensar en dejarlo, aunque algunas veces he tenido dudas sobre si continuar componiendo canciones. La pintura requiere mucha dedicaci\u00f3n, casi exclusiva, y no siempre es f\u00e1cil compaginar las dos actividades, aunque lo intento.<\/p>\n<p>P.- Enrique Urquijo, Quique Gonz\u00e1lez. Por temas diferentes ha habido acercamientos entre tu m\u00fasica y la suya&#8230; \u00bfAfinidades estil\u00edsticas? \u00bfAmistad? \u00bfAdmiraci\u00f3n mutua? \u00bfDe d\u00f3nde nace tu relaci\u00f3n con esos dos grandes? Gracias<\/p>\n<p>R.- Yo creo que si hay ciertas afinidades tanto musicales como a nivel de textos. Enrique para mi es un referente de la m\u00fasica en castellano, y Quique me parece un grand\u00edsimo m\u00fasico que veo que su obra crece disco a disco. En cualquier caso es posible que participemos de alguna especie de visi\u00f3n de las canciones y del mundo en general que no esta demasiado lejos unas de las otras.<\/p>\n<p>P.- Felicidades por el nuevo disco Diego. Con 2 escuchas que le he dado creo que puede ser tu mejor disco junto con Canciones de Amor Desafinado. Canciones en ruinas es un disco oscur\u00edsimo, triste, conmovedor, sobrecogedor&#8230; Sin embargo, pese a la tristeza, la \u00faltima canci\u00f3n abre la puerta a la esperanza&#8230; vuelve un poco de lo que perd\u00ed. \u00bfPremeditado? \u00bfHay esperanza?<\/p>\n<p>R.- Estoy de acuerdo en que es un disco bastante oscuro que refleja probablemente los \u00faltimos a\u00f1os de mi vida, pero si, yo creo que siempre hay una puerta abierta a la luz y las canciones tristes tienen tambi\u00e9n su propia belleza y su propia luz, que a veces reconforta mucho.<\/p>\n<p>P.- De la \u00e9poca de duncan dhu quedan Miguel Bos\u00e9, Alaska y poco m\u00e1s&#8230;..porqu\u00e9 crees que s\u00f3lo unos pocos perduran en el tiempo\u00bf No te da miedo en estos tiempos de crisis sacar nuevo disco\u00bf para cu\u00e1ndo un concierto en Madrid\u00bf Laura<\/p>\n<p>R.- Yo creo que es bastante normal que sobre todo los grupos en alg\u00fan momento de su trayectoria tomen la decisi\u00f3n de terminar con el proyecto. En cuanto a lo de sacar nuevos discos, al menos en mi caso, se trata m\u00e1s de una necesidad creativa y se que es un momento especialmente dificil en el aspecto comercial, pero yo creo que si necesitas sacar canciones al final tienen que salir por alg\u00fan lado, y por eso yo creo que seguimos grabando discos. Espero que de aqui a unos meses podamos tener alguna actuaci\u00f3n en algun local peque\u00f1o de Madrid.<\/p>\n<p>P.- Hola Diego, soy Sara\u00ed, de M\u00e9xico. Te llegaron dos cartas m\u00edas hace poco. Aprovecho este medio para saludarte y felicitarte porque este nuevo trabajo es algo NUEVO, siempre me sorprendes. Y preguntarte: \u00bfCu\u00e1les son los criterios que usas para elegir a quienes colaboran contigo, tanto en lo musical como en lo pl\u00e1stico?<\/p>\n<p>R.- En cuanto a colaboradores me guio mucho por la intuci\u00f3n y el feeling que establezco con ellos, hay algunos que llevan conmigo bastante tiempo, como por ejemplo Suso Saiz o Joserra Semperena, y hay otros que se van incorporando con el paso del tiempo, en caulquier caso son colaboraciones que me enriquecen, tanto a mi, como creo que a mis discos.<\/p>\n<p>P.- Hablando de conciertos a los que has asistido, d\u00ednos cu\u00e1l fue el \u00faltimo al que asististe, si tienes planes de ir a alguno en el futuro cercano y para finalizar, cu\u00e1l fue el concierto que m\u00e1s te ha impresionado de todos a los que has ido. Un saludo, Diego.<\/p>\n<p>R.- El \u00faltimo concierto que realmente me impact\u00f3 fue una actuaci\u00f3n de Ana Moura que v\u00ed en San Sebasti\u00e1n, una voz realmente espectacular, y una actuaci\u00f3n \u00edntima y realmente delicada. Ese ha sido el \u00faltimo que realemente me ha dejado un verdadero buen recuerdo. Tambi\u00e9n me gust\u00f3 mucho el concierto que di\u00f3 Mikel Erentxun en el teatro Victoria Eugenia de San Sebasti\u00e1n hace unos meses.<\/p>\n<p>P.- Hola Diego, ya tengo ganas de tener el CD en mis manos, pero mi pregunta es: \u00bfPorqu\u00e9 el t\u00edtulo de &#8220;Canciones en Ruinas&#8221;? Besos Mari<\/p>\n<p>R.- El t\u00edtulo hace referencia tanto a mi \u00faltima etapa personal de los \u00faltimos a\u00f1os, en los cuales escrib\u00ed estas canciones, y tambi\u00e9n a la b\u00fasqueda de dejar las canciones lo m\u00e1s desnudas posible yendo un poco a la esencia y quitando todo artificio que me resulta innecesario, es decir, dejando las canciones casi en su esqueleto.<\/p>\n<p>P.- \u00bfPor qu\u00e9 hay un nivel tan bajo en la m\u00fasica espa\u00f1ola actual?<\/p>\n<p>R.- No lo se, yo creo que hay de todo, tampoco creo que todo sea malo, creo que sigue habiendo cosas interesantes, aunque es verdad que cada vez, quiz\u00e1 haya una banalizaci\u00f3n mayor en cuanto a la m\u00fasica de consumo se refiere, pero siempre surgen peque\u00f1as joyas de vez en cuando.<\/p>\n<p>P.- \u00bfQu\u00e9 cambi\u00f3 Suso Saiz en tu forma de grabar discos?<\/p>\n<p>R.- Mucho. Me ense\u00f1\u00f3 a quitarme muchos prejuicios a la hora de entrar en un estudio, y tambi\u00e9n a jugar con la improvisaci\u00f3n y dejar que las cosas fluyan y surgan de una manera natural, sin forzarlas. Le debo mucho en muchos aspectos<\/p>\n<p>P.- \u00bfM\u00fasica o pintura?<\/p>\n<p>R.- Las dos cosas son disciplinas que me interesan much\u00edsimo y que me producen el mismo intenso placer.<\/p>\n<p>P.- He leido que tienes miedo a los conciertos, al contacto con la gente, \u00bfes por eso que no actuaste en la grabacion de Mikel hace dos a\u00f1os en el victoria eugenia y si lo hiciste sin gente? Un beso guapooo<\/p>\n<p>R.- Es verdad que llevo muchos a\u00f1os apartado de los escenarios y eso produce cierto respeto a la hora de plantearte volver, y si, en cuanto al concierto de Mikel, prefer\u00eda hacer algo especial, diferente, y al mismo tiempo asegurarme que iba a quedar al nivel que yo esperaba.<\/p>\n<p>P.- Hola Diego. La canci\u00f3n favorita de mi novia Lidia y mia es Juegos de amor. \u00bfDe que habla exactamente esa canci\u00f3n? Donosti2004<\/p>\n<p>R.- La canci\u00f3n habla de una relaci\u00f3n que tuve por aquella \u00e9poca y como an\u00e9cdota hay una adaptaci\u00f3n cambiando partes de la letra y la orientaci\u00f3n musical que aparece en el disco Las huellas borradas con el nuevo t\u00edtulo de Donde cruza la frontera.<\/p>\n<p>P.- \u00bfQu\u00e9 opinas del reggeton y de Lady GaGa?<\/p>\n<p>R.- Estoy totalmente desconectado de estos estilos y dir\u00eda que los desconozco por completo. No estoy muy interesado en este tipo de m\u00fasica.<\/p>\n<p>P.- Teniendo tanta importancia la letra en tus discos, \u00bfqu\u00e9 compones antes, m\u00fasica o letra? \u00bfEres consciente de que mucha gente es muy fan de tu forma de escribir (esa mezcla de pesimismo y nostalgia siempre reconfortante)?<\/p>\n<p>R.- Suelo componer casi siempre primero la m\u00fasica, y luego adapto la letra a la m\u00e9trica que me dicta la propia melod\u00eda. Me alegra que los textos lleguen al coraz\u00f3n de alquien y quiz\u00e1 que les haga sentir alg\u00fan peque\u00f1o momento de placer.<\/p>\n<p>P.- \u00bfHabr\u00eda posibilidad de un disco Mikel Erentxun &#038; Diego Vasallo (es decir que no se llamara Duncan Dhu), como hicieron hace un par de a\u00f1os por ejemplo Mark Olson &#038; Gary Louris (antes The Jayhawks), con lo que os une ahora aunque lejos de Duncan?<\/p>\n<p>R.- Lo veo dificil, tanto Mikel como yo estamos muy inmersos en nuestros respectivos proyectos y sinceramente no soy muy partidario de volver a retomar proyectos musicales que ya dieron todo lo que tenian que dar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presenta Canciones en ruinas, un disco producido por \u00e9l mismo y por Suso Saiz, en el que ofrece nueve canciones ac\u00fasticas. Una de las canciones del disco del ex Duncan Dhu es una versi\u00f3n de un tema de los Smiths. La portada est\u00e1 ilustrada con un cuadro suyo. Diego Vasallo est\u00e1 de vuelta en la m\u00fasica.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-3412","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/3412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=3412"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/3412\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=3412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=3412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=3412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}