{"id":10981,"date":"2012-10-29T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=10981"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"Havalina10981","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/Havalina10981\/","title":{"rendered":"Havalina"},"content":{"rendered":"<p>Pregunta.- Despu\u00e9s de dos discazos, \u00bfc\u00f3mo sois capaces de seguir siendo tan buenos? A ver si os pas\u00e1is por Asturias que siempre se nos olvida!<\/p>\n<p>Respuesta.- No podemos evitar ser tan buenos, pero por si acaso seguimos practicando. Asturias mola y caer\u00e1 m\u00e1s, que ya hemos estado varias veces<\/p>\n<p>P.- Aunque sea un poco extra\u00f1a,esta es mi pregunta. Sois un gran grupo. \u00bfPor qu\u00e9 no colgais vuestras obras en la red para que la gente pueda tocarlas en sus casa?<\/p>\n<p>R.- Las afinaciones son un l\u00edo y llevar\u00eda mucho tiempo, del cual no disponemos, por desgracia, pero hay algunos locos por ah\u00ed que se sacan los temas a o\u00eddo y los cuelgan en YouTube. Manuel dice que cuando aprendi\u00f3 a tocar la guitarra, no hab\u00eda internet y se sacaba las canciones de o\u00eddo, lo cual era un ejercicio maravilloso. Si quieres, m\u00e1ndanos un mail y te pasamos las afinaciones de los temas.<\/p>\n<p>P.- Hola \u00bfCre\u00e9is que este \u00faltimo disco, con sonidos un poco menos oscuros, y m\u00e1s accesible para &#8220;todos los p\u00fablicos&#8221; os puede llevar a la primera l\u00ednea del indie nacional?<\/p>\n<p>R.- La primera l\u00ednea del indie nacional tiene tanta gente que ya no cabe nadie m\u00e1s. No tenemos demasiadas expectativas, hacemos lo que nos gusta, y si le gusta cada d\u00eda a m\u00e1s gente, mucho mejor.<\/p>\n<p>P.- Aunque ya hab\u00e9is hablado alguna vez de influencias como The Cure, Soundgarden, Kyuss o Sonic Youth, y en el tiempo hay muy poco margen entre Muse y Havalina, \u00bfha influido algo el grupo de Matt Bellamy en el sonido de Havalina? Asi lo parece, sobre todo en &#8220;Imperfecci\u00f3n&#8221; y &#8220;H&#8221;. Un saludo.<\/p>\n<p>R.- Digamos que s\u00ed. Muse tiene un directo brutal, y son tres tipos sonando muy grande y muy limpio a la vez, y eso es una gran fuente de inspiraci\u00f3n para nosotros.<\/p>\n<p>P.- Hola chicos, lo primero felicitaros por el concierto del pasado viernes en sala begood de barcelona, fue increible, las nuevas canciones sonaron impecables \ud83d\ude09 Respecto a &#8220;H&#8221; el llevar ya m\u00e1s de diez a\u00f1os como formaci\u00f3n os ha influenciado en la contundencia y planteamiento de los temas formando un nexo d uni\u00f3n com\u00fan entre ellos&#8230; \u00bfes como si nos estuvierais narrando una historia con final incierto?<\/p>\n<p>R.- Pues s\u00ed, puedes decir que cada disco es un nuevo cap\u00edtulo, y nunca sabes c\u00f3mo puede terminar la cosa&#8230; Y la experiencia siempre ayuda a la hora de conseguir un sonido contundente, sin duda.<\/p>\n<p>P.- Despu\u00e9s de darle vueltas a posibles preguntas intelectuales y dem\u00e1s, s\u00f3lo me queda la que m\u00e1s me obsesiona, \u00bfque pedal usas para sacarle ese sonido apisonadora a un fender? que le vamos a hacer, la cabra tira al monte. Un saludo y gracias por vuestra m\u00fasica<\/p>\n<p>R.- No es un pedal, es afinar la guitarra muy grave y tocarla con dos cojones. \ud83d\ude42<\/p>\n<p>P.- Me gustar\u00eda felicitar a Ignacio por prestar voz y composici\u00f3n a &#8220;El estruendo&#8221;, en cuanto al proceso creativo d los temas \u00bfqu\u00e9 hay de visceral, improvisado e impulsivo? \u00bfHay partes o temas en concreto que os hayan salido directamente de las entra\u00f1as?<\/p>\n<p>R.- Nos basamos mucho en la improvisaci\u00f3n para finalizar los temas en el local, a partir de las ideas que llegan de cada uno. S\u00ed hay partes m\u00e1s viscerales, como el caso de Animal Despierto, que surge de un riff totalmente improvisado en los directos de la gira anterior&#8230; Ignacio te da las gracias a ti, y el se\u00f1or que vende los discos tambi\u00e9n por comprarlo&#8230;<\/p>\n<p>P.- \u00bfEn qu\u00e9 estilo de m\u00fasica os clasificar\u00edais?<\/p>\n<p>R.- Psychokillerdreamrockversotrankerfullequipped<\/p>\n<p>P.- \u00bfCreeis que con \u00e9ste trabajo con el que afortunadamente estais teniendo m\u00e1s presencia en los medios, se va a hacer eco de vuestro excelente directo y tendreis m\u00e1s presencia en salas y festivales este pr\u00f3ximo a\u00f1o?. Para mi deber\u00edais ser grupo de culto mayoritario en \u00e9ste pa\u00eds, sobretodo porque cre\u00e1is un puente d conexi\u00f3n impecable y equilibrado entre el indie &#8211; rock que ning\u00fan otro grupo sabe mantener&#8230;<\/p>\n<p>R.- Hola Teresa, cu\u00e1nto tiempo! Gracias por los elogios, Estamos totalmente de acuerdo contigo excepto en que si somos de culto no somos mayoritarios. O s\u00ed, no s\u00e9. Ojal\u00e1 tengas raz\u00f3n y el pr\u00f3ximo verano seamos cabeza de cartel en todos los festivales. Menos en uno&#8230;<\/p>\n<p>P.- Manu\u00e9l, \u00bfvienes de familia de artistas?<\/p>\n<p>R.- Mi t\u00edo \u00c1ngel Luis Cabezal\u00ed lleva desde hace 20 a\u00f1os la direcci\u00f3n del coro de Fuenteheridos, provincia de Huelva. Aparte de actuar en todas las comuniones, bodas, etc. del pueblo, suelen actuar por otros lugares de Andaluc\u00eda, en TV, y cosas as\u00ed. Aparte de eso, en general los Cabezal\u00ed son gente bastante musical.<\/p>\n<p>P.- \u00bfNo est\u00e1is cansados de que se remarque constantemente que vuestros nuevos trabajos est\u00e1n cantados en castellano y no en ingl\u00e9s?.<\/p>\n<p>R.- No, no estamos cansados. Pero siendo el cuarto disco es un tema que ya no deber\u00eda llamar tanto la atenci\u00f3n, tienes raz\u00f3n.<\/p>\n<p>P.- Enhorabuena por lograr hacer m\u00fasica durante una d\u00e9cada. \u00bfSe puede vivir de la m\u00fasica actualmente? Atreveos a dar un consejo a los\/las que estamos empezando&#8230;<\/p>\n<p>R.- Se puede pero es extremadamente dif\u00edcil. Se necesita mucho trabajo, mucho talento, mucha suerte y mucha paciencia para conseguirlo. <\/p>\n<p>P.- \u00bfPrefer\u00eds el CD convencional o las nuevas plataformas de m\u00fasica tipo Spotify? Geeenial el \u00faltimo disco<\/p>\n<p>R.- Lo estamos discutiendo entre nosotros y no nos ponemos de acuerdo. Cada cosa tiene lo suyo. Por calidad, mejor el CD o el vinilo (que adem\u00e1s tiene mucho encanto), y por versatilidad y posibilidades, Spotify.<\/p>\n<p>P.- Primero mi enhorabuena y agradecimiento por vuestro trabajo, hac\u00eda tiempo que no me convenc\u00eda tanto un grupo nacional. Mi pregunta es: siendo sinceros \u00bfsiempre hab\u00e9is sabido el camino a recorrer con Havalina para llegar donde est\u00e1is hoy o es una mezcla de trabajo, talento y algo de suerte?<\/p>\n<p>R.- Gracias! Creemos que m\u00e1s bien lo segundo. Sobre todo de trabajo, y a ver si nos llega un poquito m\u00e1s de suerte y lo rematamos. \ud83d\ude42<\/p>\n<p>P.- El otro d\u00eda en Para Todos La 2 os presentaron como &#8220;Jabalina&#8221;, \u00bfno os molesta que sean tan poco profesionales con vosotros? o ya est\u00e1is curados de espanto.Saludos y enhorabuena por vuestra m\u00fasica<\/p>\n<p>R.- No nos molesta excesivamente, pero s\u00ed que nos gustar\u00eda que lo pronunciaran como es. &#8220;H&#8221; muda. Que corra la voz.<\/p>\n<p>P.- \u00bfDe verdad no hab\u00e9is pensado en llevar un 2\u00ba guitarrista en la nueva gira para mejorar las canciones en directo?.<\/p>\n<p>R.- De verdad. No. Nos gusta lo que sucede siendo los tres.<\/p>\n<p>P.- \u00bfQu\u00e9 relaci\u00f3n tiene la banda con Maika Makovski?<\/p>\n<p>R.- Ay si yo te contara&#8230;<\/p>\n<p>P.- \u00bfPor qu\u00e9 no habeis incluido en el disco &#8220;Compa\u00f1ia de Sue\u00f1os&#8221;? con lo que me gusta! \u00a1Un beso a los tres!<\/p>\n<p>R.- Para que tuvieras la oportunidad de hacer un v\u00eddeo \u00fanico, especial y exclusivo&#8230; \ud83d\ude09 Un beso para ti!<\/p>\n<p>P.- \u00bfQu\u00e9 planes hay para 2013? \u00bfSalir fuera de Espa\u00f1a de gira quiz\u00e1s?<\/p>\n<p>R.- Seguir tocando, mucho, y ya veremos d\u00f3nde. De momento se ha comentado el tema de salir, pero no hay nada confirmado&#8230;<\/p>\n<p>P.- Con una m\u00e1quina tan engrasada como Havalina \u00bfse &#8220;sobrevive&#8221; de la m\u00fasica o lo justo para bocata, ca\u00f1a y gasolina? <\/p>\n<p>R.- Lo justo para que no nos cueste dinero, y poder dormir calentitos en las giras de invierno. Y comer bien, eso s\u00ed.<\/p>\n<p>P.- Para Manu.\u00bfDesde cuando tocas y d\u00f3nde aprendiste guitarra?<\/p>\n<p>R.- Empec\u00e9 a tocar la guitarra con 12 a\u00f1os y de manera autodidacta. Aprend\u00ed mucho tocando con amigos en parques de mi barrio y tambi\u00e9n en el Retiro.<\/p>\n<p>P.- Soy guitarrista y si no es indiscreci\u00f3n, Manuel e Ignacio, me gustar\u00eda saber que pedales utiliz\u00e1is pa las distrosiones y delays. Los amplis y guitarras ya te los he visto en directo jeje<\/p>\n<p>R.- Ignacio: Morley Deluxe Distortion, Electro Harmonix Bass Big Muff, Belcat DLY 303 Manuel: ProCo RAT original de los 80, Electro Harmonix Big Muff Pi, TC Electronics Nova Delay<\/p>\n<p>P.- 2\u00ba concierto que os veo en Coru\u00f1a, y cada vez salgo m\u00e1s contento. \u00bfNo os interesais por tocar en festivales?. Estoy seguro que si vais a festivales la gente os conoceria mas&#8230;. y tengo seguro que no ibais a defraudar.<\/p>\n<p>R.- Estamos en ello, no es porque no queramos, pero no depende \u00fanicamente de nosotros.<\/p>\n<p>P.- \u00bfEn qu\u00e9 comunidad os hab\u00e9is visto m\u00e1s arropados por el p\u00fablico?<\/p>\n<p>R.- En Madrid, pero hay muchos sitios con un p\u00fablico maravilloso y numeroso.<\/p>\n<p>P.- \u00bfSe repetir\u00e1 este a\u00f1o el concierto triple de siroco, con un d\u00eda y \u00e1lbum m\u00e1s?<\/p>\n<p>R.- No. Fue cosa del 10\u00ba aniversario.<\/p>\n<p>P.- \u00bfQu\u00e9 afinaciones sol\u00e9is utilizar en las guitarras?. \u00bfConsider\u00e1is que son parte de la esencia de la banda?<\/p>\n<p>R.- S\u00ed, son parte de la esencia de la banda. Las m\u00e1s frecuentes son (de la sexta a la primera cuerdas): CGCGCC BEADF#B DADGAD EGDGGD<\/p>\n<p>P.- \u00bfC\u00f3mo hac\u00e9is para componer los temas?, \u00bfCompon\u00e9is entre todos miembros de la banda?<\/p>\n<p>R.- Hay diferentes m\u00e9todos; en l\u00edneas generales, alguien la banda, normalmente Manuel o Ignacio, trae una idea o boceto sobre el que luego trabajamos en el local de ensayo. Las letras las escribimos entre Manuel e Ignacio, y en algunos casos contamos con la colaboraci\u00f3n estelar de Walter Bistec.<\/p>\n<p>P.- Hola, el 8 de Noviembre os tendremos en M\u00e1laga en ac\u00fastico&#8230; \u00bfc\u00f3mo se acopla &#8220;H&#8221; a ese formato? \u00bfqu\u00e9 nos vamos a encontrar? Como sea.. \u00a1ganas de teneros por aqu\u00ed! Saludos.<\/p>\n<p>R.- A\u00fan no lo sabemos muy bien, aunque de los ac\u00fasticos que hicimos en la gira anterior guardamos un muy buen recuerdo; sol\u00edamos interpretar los temas con mucha libertad. Normalmente lo hacemos con un set de percusi\u00f3n bastante sencillito pero mol\u00f3n y un par de guitarras ac\u00fasticas, m\u00e1s un teclado o un carrill\u00f3n de cuando en cuando.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la celebraci\u00f3n de su d\u00e9cimo aniversario, la banda madrile\u00f1a presenta H, su cuarto \u00e1lbum \u00edntegramente en espa\u00f1ol. El grupo, que sigue de gira presentando sus nuevos temas, ha charlado con los oyentes. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-10981","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/10981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=10981"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/10981\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=10981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=10981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=10981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}