{"id":10954,"date":"2012-10-17T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=10954"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"Jostein_Gaarder10954","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/Jostein_Gaarder10954\/","title":{"rendered":"Jostein Gaarder"},"content":{"rendered":"<p>Pregunta.- Buenas tardes. Le\u00ed hace unos a\u00f1os &#8220;El Mundo de Sof\u00eda&#8221;, y fue el libro que me incit\u00f3 a explorar mejor el mundo de la filosof\u00eda (Tengo diecisiete a\u00f1os). Mi pregunta es, \u00bfsu nuevo libro resulta parecido a &#8220;El Mundo de Sof\u00eda&#8221; en el sentido de que puede aumentar la curiosidad por las grandes preguntas? \u00bfLo recomendar\u00eda para gente de mi edad? Muchas gracias.<\/p>\n<p>Respuesta.- Este es un libro peque\u00f1o sobre las grandes preguntas. En el Mundo de Sof\u00eda presento las respuestas de los fil\u00f3sofos a las grandes preguntas, pero ahora solo presento las preguntas, y lo hago de tal modo que son tanto para mayores y peque\u00f1os. De hecho, estas preguntas podr\u00edan discutirlas ni\u00f1os y mayores, expertos y no expertos. Los ni\u00f1os siempre est\u00e1n haciendo preguntas, pero muchos adultos se acostumbran al mundo y dejan de preguntar coas como \u00bfqu\u00e9 es el universo? \u00bfPor qu\u00e9 estamos aqu\u00ed? Muchas veces los ni\u00f1os hacen preguntas y los padres les mandan callar y marcharse a la cama, pero es parte de la naturaleza humana el hacer preguntas. Este libro no es solo las preguntas, sino las preguntas combinadas con las im\u00e1genes que las acompa\u00f1an, y en las que se puede leer una historia. Es un libro que hemos hecho con amor entre el artista y yo<\/p>\n<p>P.- \u00bfSi me pregunto, existo, y si existo entonces me pregunto, es la existencia una pregunta?<\/p>\n<p>R.- Esta es una buena reflexi\u00f3n. Fue Descartes quien dijo Pienso luego existo. Muchas veces yo le doy la vuelta y digo: Existo, luego pienso. La pregunta que haces es el mismo giro. Para mi es imposible existir sin hacerme preguntas. Para mi es m\u00e1s relevante decir existo, por tanto pienso. Para mi todo empez\u00f3 a los 11 a\u00f1os, me levant\u00e9 en mitad del d\u00eda y me di cuenta: \u00a1Existo! \u00a1El mundo existe! Y fui a donde mis padres y mis profesores y se lo dije, y ellos me dec\u00edan que era normal existir, y que no deber\u00eda preguntar cosas como esa. Cuando creci y empec\u00e9 a escribir, fue mi venganza, porque sab\u00eda que la vida es un misterio, el universo es enigmatico. Mi carrera como fil\u00f3sofo y como escritor empez\u00f3 aquel d\u00eda con 11 a\u00f1os, en el que tambi\u00e9n me promet\u00ed a mi mismo no hacerme nunca mayor<\/p>\n<p>P.- Se\u00f1or, Gaarder. La filosof\u00eda es algo importante y complicado. \u00bfSe puede contar como se cuenta un cuento sin despreciarla?<\/p>\n<p>R.- Eso es lo que intent\u00e9 con El mundo de Sof\u00eda. Aunque puedas acusarlo de ser demasiado simplicado. Lo comparo con que estuvieras en Copenhague y haces autostop para ir a Roma, y alquien te para y te duce que va a Mil\u00e1n: no deber\u00edas quejarte. Coge el tren a Mil\u00e1n y luego ir\u00e1s a Roma. Hay gente que se interesa en Freud, Hume o Marx, y a partir de ah\u00ed pueden empezar a leer m\u00e1s. Pero, tambi\u00e9n pienso que un pensamiento claro se pede comunicar de una manera simple y comprensible. Creo en el lenguaje simple. Las matem\u00e1ticas pueden ser tan complejas que casi no se pueden comunicar, pero la mayor parte de la filosof\u00eda se puede expresar de una manera clara y sencilla. Mucha parte de la filosof\u00eda tiene un lenguaje inaccesible, pero es una manera de los profesores para sentirse poderoso. Por ejemplo, si te preguntas \u00bfqu\u00e9 es la justicia? Es algo que se puede discutir con un ni\u00f1o: si a uno le das un trozo de tarta m\u00e1s grande que al otro, te dir\u00e1: no es justo, y a a partir de ah\u00ed puedes comenzar una conversaci\u00f3n filos\u00f3fica real. A veces es importante discutir estas cuestiones con los ni\u00f1os, que son m\u00e1s abiertos de mente<\/p>\n<p>P.- Le\u00ed &#8220;El mundo de Sofia&#8221; hace ya demasiados a\u00f1os (para mi desgracia.. jeje) Recuerdo que me ayud\u00f3 a entender ciertos pensamientos filos\u00f3ficos. \u00bfSe plantea Vd. poder escribir algo parecido en su planteamiento, esta vez sobre pol\u00edtica? Quiz\u00e1s tambi\u00e9n me ayudara a entender ciertas cosas que de momento no atino en absoluto.<\/p>\n<p>R.- No escribir\u00eda un libro as\u00ed, pero estoy terminando un libro parecido al mundo de Sof\u00eda, llamado Anna: una f\u00e1bula sobre el clima y el medio ambiente de la Tierra, que en parte tiene que ver con la pol\u00edtica. Escrib\u00ed El Mundo de Sof\u00eda en el 91, y muchas veces me preguntan que si lo escribiera hoy ser\u00eda diferente, y la respuesta es s\u00ed, por dos razones: uno, si supiera que el libro se iba a traduc ir a 60 lenguas hubiera incluido filosof\u00eda no europea, como la india o la china, y segundo, quiz\u00e1 la pregunta m\u00e1s profunda a d\u00eda de hoy sea esta_: c\u00f3mo puede la humanidad mantener un planeta sostenible para el futuro? Es importante porque tiene aspectos tanto pr\u00e1cticos como filoso\u00f3ficos. Me sorprende lo poco que se debate esta pregunta. Se ha convertido en una de las grandes preguntas, quiz\u00e1 la m\u00e1s importante en tiempos modernos, Hasta ahora, la declaraci\u00f3n universal de los derechos humanos de 1948 era el mayor logro de la literatura y la filosof\u00eda, porque aquellas palabras no salieron de la nada, sino que estaban basadas en la reflexi\u00f3n humana de miles de a\u00f1os. Pero, no solo podemos centrarnos en los derechos humanos. Tambi\u00e9n debemos enforcarnos en las responsabilidades y las obligaciones humanas. Espero que el siglo XXI nos traiga una declaraci\u00f3n universal de las obligaciones humanas. Adem\u00e1s, Fernando Savater ha escrito un libro parecido al Mundo de Sof\u00eda sobre pol\u00edtica, es un buen libro<\/p>\n<p>P.- Le agradecer\u00eda sobremanera me aclarese la siguiente pregunta:\u00bfQu\u00e9 educaci\u00f3n recibi\u00f3 Ud. en su infancia y adolescencia sobre cuestiones existenciales, filos\u00f3ficas o religiosas que estan presentes en su producci\u00f3n literaria de adulto?\u00bfQu\u00e9 queda de aquello?<\/p>\n<p>R.- Crec\u00ed en una familia con un mont\u00f3n de libros, pero yo no le\u00eda mucho. Viv\u00eda en una familia muy abierta y tolerante. Mis padres ten\u00edan buenos amigos con quienes estaban totalmente en contra. Esto eran los 60. Muchos de los amigos de mis padres eran comunistas, que en aquella \u00e9poca no era algo bueno de ser. Mi madre daba clases de catequesis, y yo participaba, pero mis padres no eran fan\u00e1ticos, eran muy liberales. Hay un dicho dan\u00e9s que dice Primero soy un ser humano y luego soy un cristiano. Esto me parece muy importante a d\u00eda de hoy: priemero somos humanos y luego somos cristianos, o mususlmanes o lo que sea. Para mi es irrelevante si eres comunista o musulman, cristiano o lo que seas, lo importante es que nos acerquemos desde un punto de vista secular. Es como el cuento del traje nuevo del emperador: cuando un ni\u00f1o dice \u00bfpor qu\u00e9 est\u00e1 el emperador desnudo? Es vergonzoso, pero muestra la importancia y los peligros de hacer preguntas. O como en una conferencia, en la que conoc\u00ed a una mujer de EE UU que pregunt\u00f3 a su madre: \u00bfPor qu\u00e9 el presidente dice siempre Que Dios bendiga Am\u00e9rica y no dice Qu\u00e9 Dios bendiga al mundo\u00bf Es un ejemplo claro de libertad a la hora de hacer preguntas. Y yo cuando era peque\u00f1o ten\u00eda ese permiso para hace preguntas sin sufrir intoleracia<\/p>\n<p>P.- Viendo el camino de caos que est\u00e1 alcanzando actualmente Occidente, \u00bfCrees que una pareja que decida tener un hijo hoy en d\u00eda, tiene motivos para preocuparse por su futuro y por el mundo en el que vivir\u00e1?<\/p>\n<p>R.- Hay gente que se dice pesimista sobre el futuro, pero yo no lo soy, porque creo que es otra manera de decir que uno es un vago. Es muy f\u00e1cil ser pesimista. Entre el optimismo y el pesimismo hay otra categor\u00eda llamada esperanza. Hay que luchar por un futuro mejor, y tener un hijo pertenece a esa categor\u00eda de la esperanza. As\u00ed que yo dir\u00eda: s\u00ed, que tengan hijos, y que se comprometa con el mundo. Pero no esperes demasiado. Yo fui un padre muy joven, y creo que es bueno no posponer la vida, aunque con esto no intento convencer a nadie, es solo mi experiencia<\/p>\n<p>P.- \u00bfPodr\u00eda explicar su idea de que Jes\u00fas y Buda son dos de los fil\u00f3sofos m\u00e1s influyentes?<\/p>\n<p>R.- A menudo me preguntan qui\u00e9n es mi fil\u00f3sofo favorito, pero no puedo dar una respuesta, porque investigan cosas diferentes, planearon sus ideas en distintos tiempos&#8230; Pero una vez me preguntaron que si muriera, con qu\u00e9 fil\u00f3sofo me gustar\u00eda hablar, y yo le dije que S\u00f3crates, porque es enigm\u00e1tico, porque no escribi\u00f3 ni una palabra, aunque la mayor parte de la filosof\u00eda occidental est\u00e1 basada en \u00e9l. Segundo, dir\u00eda a Jes\u00fas, porque es un importante fil\u00f3sofo moral y \u00e9tico. No necesito otro profesor de \u00e9tica m\u00e1s que Jes\u00fas, y \u00e9l adem\u00e1s tambi\u00e9n es enigm\u00e1tico, porque no escribi\u00f3 ni una palabra. El tercero: Buda, que no era solo un gran fil\u00f3sofo, sino tambi\u00e9n un gran psic\u00f3logo. Y lo mismo: es enigm\u00e1tico, porque no escribi\u00f3 nada y todo lo que dijo se conoce a trav\u00e9s de sus disc\u00edpulos. Ser\u00eda una gran charla con ellos tres, y adem\u00e1s creo que entre ellos se respetar\u00edan mucho<\/p>\n<p>P.- Jostein, \u00bfNo crees que la actual crisis social mundial se debe en gran parte al desinter\u00e9s demostrado por la politica en la ense\u00f1anza y practica de la filosof\u00eda? <\/p>\n<p>R.- Quiz\u00e1. Lo primero creo que es la falta de control pol\u00edtico del mundo financiero. Vivimos en democracias en las que la econom\u00eda ha vivido su propia vida, sin regulaciones, lo que ha dado lugar a negocios oscuros y especulaci\u00f3n. Necesitamos pensar filos\u00f3ficamente y necesitamos medios para controlar el sistema financiero. No me refiero a hacerlo en una manera sovi\u00e9tica, sino solucviones como la que se ha propuesto en Francia, de hacer pagar una pque\u00f1a tasa por cada transacci\u00f3n financiera. Tenemos un sistema econ\u00f3mico en el que la b\u00fasqueda de beneficios podr\u00eda da\u00f1ar a nuestro planeta como tal. Tenemos que pensar de manera diferente, y eso deber\u00eda comenzar a nivel pol\u00edtico. En Islandia dec\u00edan que los beneficios eran para los inversores privados, pero cuando hab\u00eda perdidas, eran de los que pagan los impuestos, y creo que tambi\u00e9n esto se puede aplicar a Espa\u00f1a: cuando los bancos van bien, los beneficios son de los bancos, y cuando no, el estado o la UE deben meterse para solucionerlo. Por eso creo que deber\u00eda haber m\u00e1s control <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El autor de El mundo de Sof\u00eda charlar\u00e1 con los lectores sobre su \u00faltima obra, el libro infantil Me pregunto&#8230; y sobre su discurso inaugural de la Casa del Lector de Madrid este mi\u00e9rcoles. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-10954","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/10954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=10954"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/10954\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=10954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=10954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=10954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}