{"id":10774,"date":"2010-06-30T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=10774"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"Carlos_Miquel10774","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/Carlos_Miquel10774\/","title":{"rendered":"Carlos Miquel"},"content":{"rendered":"<p>Pregunta.- Hola Carlos, \u00bfpiensas que si no cambian las normas, apartir de ahora, los ingenieros deberian echar cuentas sobre si interesa o no pasar al SC, teniendo en cuenta el beneficio Vs sanci\u00f3n, como si fuera una parte m\u00e1s de la estrategia en carrera. Gracias.<\/p>\n<p>Respuesta.- Hola, por supuesto que no. Si alguien quiere ganar el Mundial haciendo el tramposo, que lo haga. No es la forma como debe comportarse un piloto.<\/p>\n<p>P.- Eres un fen\u00f3meno.Creo que el F-Duct a sido una p\u00e9rdida de tiempo para Ferrari,pues ha perdido bastante agarre en curva,viendo como van los Red Bull sin \u00e9l.Opinas igual?<\/p>\n<p>R.- Graciassss y hola a todos. Creo que han perdido tiempo con \u00e9l, pero tambi\u00e9n porque han empleado mucho en los escapes bajos que, de momento, van bien.<\/p>\n<p>P.- Hola Carlos. Dejando aparte el Whitingato, \u00bfno crees que el Fernando Alonso del bicampeonato con Renault estar\u00eda m\u00e1s arriba en la clasificaci\u00f3n que el Fernando de este a\u00f1o? \u00bfPor qu\u00e9 gestiona ahora peor las carreras que entonces?. Un abrazo y muchas gracias. <\/p>\n<p>R.- Otro para ti. No creo que las gestione peor, pienso que lleva un coche un poco peor y que es un pel\u00ednmenos agresivo. Entonces daba la sensaci\u00f3n de que pod\u00eda salirle todo hiciera lo que hiciera. Y, adem\u00e1s, la fortuna no est\u00e1 tanto de su lado como en 2005 y 2006.<\/p>\n<p>P.- \u00bfPor qu\u00e9 los dirigentes de la Fia se quejan de que la gente cree que el ambiente que gira en torno a la Formula 1 es de todo menos deportivo\u00bf Pues el Domingo en Valencia tuvimos la respuesta&#8230;Una carrera hecha y manipulada para Mac laren desde el mismo momento en que ocurri\u00f3 el accidente de Weber.Esperpentica la posici\u00f3n en la que se coloc\u00f3 el Safety Car,y m\u00e1s esperpentica y vergonzosa la actuaci\u00f3n de Charlie Waiting a tenor de la infracci\u00f3n de Hamilton.Las sanciones fueron de risa y eso a las 20 vueltas de lo ocurrido y por las continuas quejas de F.Alonso.Carlos si la infracci\u00f3n la hubiera cometido Alonso en vez de un piloto Ingl\u00e9s ,se hubiera sancionado con bandera roja y rapidamente ,al igual que la rapicez que tuvo Charlie W. al sancionar a Alonso en el Gp de China.Estoy muy decepcionada,creo que el campeonato ya est\u00e1 decidido por adelantado o que me expliquen como en cuatro o cinco de las 9 carreras Hamilton ha cometido infracciones y en todas se ha ido de rositas.\u00bfDonde est\u00e1 la justicia ? Y explicame porque Ferrari ha obligado a que Alonso suavice sus declaraciones,cuando todo el mundo fuera de Inglaterra creemos que se qued\u00f3 corto?No est\u00e1 bien, esto se soluciona forzando una decisi\u00f3n para ya, antes de la siguiente carrera y no dejando pasar el tiempo.\u00bfPero que le pasa a Ferrari? Un fuerte abrazo Carlos y perdona por este correo tan largo,pero es que estoy muy indignada.Espero que me aclares algo de todo esto.<\/p>\n<p>R.- Hola Raquel, yo tembi\u00e9n estoy incendiaramente indignado. Creo que le quieren dar el trofeo antes de tiempo a Hamilton. En la mitad de las carreras ha vulnerado el reglamento y no le ha pasado nada. \u00c9l y seu equipo viven al margen de la ley y Charlie les deja. Si Ferrari ha obligado a Alonso a suavizar sus declaraciones supongo que ser\u00e1 porque ha llegado a alg\u00fan tipo de acuerdo con la FIA. Fernando ten\u00eda raz\u00f3n. A \u00e9l le sancionan en China por lo de la salida en cuatro vueltas, y con Hamilton tardaron 18. El domingo me entraron ganas de devolver el pase. <\/p>\n<p>P.- Carlos, \u00bfcuanto tiempo crees que pasar\u00e1 hasta que ferrari vuelva a alcanzar la supremacia de la disfruto en la primera parte de la decada? o \u00bfno se volver\u00e1 a repetir?<\/p>\n<p>R.- El problema tambi\u00e9n es que ha perdido la supremac\u00eda en los despachos que ten\u00eda con Max Mosley. Todt no es precisamente amigo de Montezemolo y a Bernie le interesa que Red Bull est\u00e9 arriba porque tiene dos escuder\u00edas.<\/p>\n<p>P.- \u00a1Hola carlos!Lo primero usted que opina de lo dicho por Hamilton(Alonso lo que tiene es envidia)Lo segundo que cree usted que le falta a Alonso para estar al mismo nivel que Hamilton&#8230;Y tercero quien cree usted que va a ganar el GP y el mundial(mojese)Gracias.<\/p>\n<p>R.- Hola Manu! A Alonso s\u00f3lo le falta coche, en lo dem\u00e1s est\u00e1 por encima. De lo de Lewis, creo que es una cortina de humo para tapar su propia desfachatez y sinvergonzoner\u00eda. El GP de Gran Breta\u00f1a lo ganar\u00e1 Vettel y, si no puede lograr el t\u00edtulo mundial Alonso, deseo con todas mis fuerzas que lo logre el alem\u00e1n, que no acostumbra a hacer trampas.<\/p>\n<p>P.- Con la congelacion de los motores, la aerodinamica se ha convertido en el valor principal de las escuderias. \u00bfcual es el &#8220;boom&#8221; en el que trabajan los equipos para 2011?<\/p>\n<p>R.- No lo s\u00e9, vuelve el difusor simple, as\u00ed que supongo que tendr\u00e1n que dar salida a los flujos de aire actuales por un agujero superior posterior como el de los Red Bull. Espero que ese difusor simple est\u00e9 bien definido y no como pas\u00f3 en 2009.<\/p>\n<p>P.- Buenas tardes Carlos. Sin entrar de nuevo en la pol\u00e9mica de Valencia \u00bfNo crees que estos hechos no deben ocultar que Ferrari no progresa y que este a\u00f1o, aunque de pena decirlo, Fernando no esta muy fino? Yo creo que no tienen el hambre de Lewis y Mclaren y tampoco est\u00e1n a la altura ni t\u00e9cnica ni estrat\u00e9gicamente hablando. \u00bfTienes alguna informaci\u00f3n que nos pueda dar algo de esperanza a los Ferraristas que no queremos que se vuelva a los a\u00f1os 80 y 90 en el equipo? Saludos de un Ferrarista antiguo y deprimido&#8230;<\/p>\n<p>R.- Ferrarista antiguo (como yo) y deprimido (casi yo), es cierto que el Ferrari no est\u00e1 tan fuerte como Red Bull y McLaren, pero ha progresado y necesita m\u00e1s. Creo que puede seguir mejorando, pero sin al menos una pole es imposible ser campe\u00f3n. Fernando tiene un hambre fuera de lo normal y, pese a alg\u00fan error impropio de su talento, como M\u00f3naco y China, sigue en buena forma. Hay que tener fe, especialmente si mejoran en calificaci\u00f3n, que es su gran h\u00e1ndicap.<\/p>\n<p>P.- Hola Carlos.En Valencia me pareci\u00f3 ver al Fernando Alonso m\u00e1s enfadado que nunca hab\u00eda visto. M\u00e1s all\u00e1 de la verguenza con la &#8220;sanci\u00f3n&#8221; a Hamilton no crees que Fernando percibe que ha perdido su suerte, su &#8220;baracca&#8221;, aquello que otros a\u00f1os le hac\u00eda conseguir cosas maravillosas,&#8230;? Y que ve c\u00f3mo se le escapa el mundial &#8220;a pesar de que \u00e9l sabe que es el mejor&#8221; y que podr\u00eda conseguirlo de no ser por toda una serie de infortunios que le est\u00e1n ocurriendo esta temporada&#8230;?<\/p>\n<p>R.- Completamente de acuerdo. Para ganar el t\u00edtulo hay que tener buena suerte y es verdad que Alonso no ha tenido ninguna buena fortuna en este medio a\u00f1o de Mundial. El enfado tiene tambi\u00e9n que ver con la concatenaci\u00f3n de sucesos negativos de este a\u00f1o. La pelota ha ca\u00eddo siempre de su lado cuando tocaba la red. <\/p>\n<p>P.- Me preocupa especialmente la pasada del Sauber de Kobayashi a Fernando uqe fue precedida de un fallo en la frenada. La concentracion siempre ha sido una de los grandes potenciales y sin embargo pareci\u00f3 perderla. \u00bfTienes algun dato que nos de confianza para pensar en que Alonso va a recuperar la concentraci\u00f3n y el control? <\/p>\n<p>R.- No ha perdido nada, s\u00f3lo hubo fases cuando ten\u00eda que atacar a Sutil, que gast\u00f3 mucho tiempo en hablar con boxes para que le creyeran sobre la barrabasada de <\/p>\n<p>P.- Hola Carlos, tengo unas dudas sobre el tema de Hamilton, \u00bfcrees que su comportameinto sobre sus actos de &#8220;ni\u00f1o peque\u00f1o&#8221; le va perjudicar con los demas pilotos?\u00bftemes que se quede aislado cada vez mas por tener esos privilegios?\u00bfpor qu\u00e9 no se unen los pilotos y hacen una protesta formal a los comisarios de la FIA atraves de su asociaci\u00f3n? \u00bfno tienes la sensacion al final del que parece que adelanto al sefty Car fue Alonso?<\/p>\n<p>R.- Hola Jesma. Hamilton es un piloto que no cae bien a sus compa\u00f1eros desde su debut. S\u00f3lo tiene un apoyo en la parrilla, Adrian Sutil, porque incluso Nico Rosberg le da poca bola. Y de las risitas con Button, s\u00f3lo decirte que son una pose. Desde que le ampara Ron Dennis ha sido un ni\u00f1o mimado. En la segunda mitad de 2008 y 2009 Mosley (en contra de McLaren) le quit\u00f3 sus prebendas, y ahora le han vuelto. Los pilotos no se unen en nada, y, desgraciadamente, es peor denunciar una injusticia que cometerla. <\/p>\n<p>P.- Hola Carlos. En un foro le\u00ed a alguien hablar sobre un plante que hicieron los pilotos para protestar por el trato de favor que recib\u00eda el Kaiser hace ya unos cuantos a\u00f1os cada vez que hac\u00eda alguna &#8220;pirula&#8221;. Como desconozco la historia, me gustar\u00eda que me la contases y si ves cerca que pase algo parecido con Hamilton. Me contestes o no, gracias. <\/p>\n<p>R.- No hubo tal plante, fue una leyenda urbana. Es cierto que, despu\u00e9s de saltarse sin cesar las chicanes de Hungr\u00eda con el permiso de Whiting, De la Rosa, Alonso, Trulli y Webber protestaron y discutieron con el Kaiser. Fue la primera vez en a\u00f1os que alguien tos\u00eda a Michael, por eso se habla de un plante, aunque no fuera tal. Veo imposible que pase algo igual con Hamilton, aunque a Kubica, Pertov, Webber o el propio Fernando no les importar\u00eda. El problema es que, como entonces, no creo que sirva de nada.<\/p>\n<p>P.- Hola crack, porque grandes marcas de competici\u00f3n (audi, porche, etc) no est\u00e1n interesadas en tener un equipo de f\u00f3rmula1. Muchas gracias.<\/p>\n<p>R.- POrque es muy costoso, pero s\u00ed quieren entrar en 2013 como suministradores de motores turbo. A ti.<\/p>\n<p>P.- Hola Carlos soy bulgaro y para mi eres el mejor pereodista de f1 actualmente. mi pregunta es: crees que en el accidente de webber el echo de que el coche a volado i se le a visto todo el fondo plano puede dar pistas a los demas sobre su gran rendimiento <\/p>\n<p>R.- Much\u00edsimas gracias, me has puesto colorado. Es una buena pregunts porque lo que para los mortales es invisible para unos ingenieros que lo analicen frame a frame podr\u00eda dar algunas pistas. En cualquier caso, se dice que el truco es que modifica su altura autom\u00e1ticamente entre calificaci\u00f3n y carrera, y no sabemos si eso se puede percibir as\u00ed.<\/p>\n<p>P.- Hola, Yo entiendo que se tarde en tomar decisiones porque debe pasar por varias cadenas de mando hasta que se llega una conclusi\u00f3n&#8230;.pero tengo la sensaci\u00f3n de que Hamilton se rie de todos, porque se ve bien en la repetci\u00f3n que Hamilton ve al sefty car cuando lo adelanta, frena y ve al coche de seguridad y duda unos segundos y lo vuelve adelantar, yo creo que eso es con premeditacion y alebosia, eso es reirse de las normas, \u00bfqu\u00e9 peinsas sobre esto? \u00bfAsi la imagen de los jeuces queda entre dicho<\/p>\n<p>R.- Es una bandera negra porque compite con la figura del Safety Car en pista y se comporta poco deportivamente con Alonso. Es esa premeditaci\u00f3n de la que t\u00fa hablas. Lo de las cadenas es una exageraci\u00f3n, esas mismas cadenas tardaron s\u00f3lo cuatro vueltas con el asturiano en China. ESta vez le dieron muchas vueltas para ver, y es mi opini\u00f3n, si mejor no le sancionaban. Y s\u00ed, a\u00fan se est\u00e1 riendo.<\/p>\n<p>P.- Hola Carlos: \u00bfD\u00f3nde est\u00e1 la asociaci\u00f3n de pilotos, esa que me suena que presid\u00eda De La Rosa o al menos era su portavoz, cuando surgen pol\u00e9micas como la del tratamiento de favor a Hamilton? \u00bfYa no existe o simplemente no les hace caso ni perry?<\/p>\n<p>R.- \u00a1Ni Perry! T\u00fa lo has dicho. Pero seguro que en Inglaterra se discute sobre la tardanza y la norma del Safety y el muro Whiting dir\u00e1 que todo est\u00e1 bien.<\/p>\n<p>P.- Buenos dias Carlos Me encantan tus comentarios en la SER. \u00bfporque Pedro de la Rosa no hizo la misma estrategia que kobasyashi para quedar en los puntos? GRACIAS<\/p>\n<p>R.- Prefiri\u00f3 salir con blandas para ir mejor en la salida por el lado sucio. Es curioso, la tarde de la calificaci\u00f3n le dije a Alonso que porque no calificacon con duras si eran m\u00e1s veloces en esas circunstancias y me respondi\u00f3 que no, porque ten\u00edan que hacer demasiadas con blandas. El tiempo demostr\u00f3 que era la mejor opci\u00f3n y, de arriesgarse con las duras, Fernando habr\u00eda ganado seguramente la carrera porque no paraba con el coche de seguridad. <\/p>\n<p>P.- Carlos Cuando sale el safety car,los pilotos no tocan el limitador de velocidad??no entiendo como se les pudo sancionar a los pilotos si eso existe<\/p>\n<p>R.- Pues ahora nos hemos enterado que no es as\u00ed, y que se les permite ir mucho m\u00e1s r\u00e1pido a los que est\u00e1n fuera del alcance del coche de seguridad. La FIA lo revisar\u00e1, porque puede cargarse un gran premio. <\/p>\n<p>P.- Hola Carlos, buenas tardes a todos, nos puedes explicar como le adelantaron a Fernando, But, Bar&#8230;.Kob, si tambien estaban detras de \u00e9l y del SF, ota cosa, no pensaste durante la carrera que la derecha era quedarse detras de SF y no cambiar ruedas hasta despues de su retirada. Gracias y saludos.<\/p>\n<p>R.- Os explico la secuencia porque todav\u00eda hay alguno que se agarra a eso para atizarle a Alonso. La orden de Safety en pista se da cuando la cabeza ya ha pasado, y a esos pilotos que citas, que va por detr\u00e1s, les de tiempo a parar despu\u00e9s de una vuelta a toda velocidad (por eso incumplieron las reglas). A continuaci\u00f3n, salen a pista y ya van m\u00e1s despacio. Vettel tuvo suerte porque el coche (algo que debe intentar evitarse, sali\u00f3 detr\u00e1s de \u00e9l), Hamilton fue un golfo. Los dos pudieron rodar 30 y 21 segundos m\u00e1s deprisa que los Ferrari, atrapados entre el Safety y el coche m\u00e9dico. Los de detr\u00e1s, que pod\u00edan dar la vuelta en 2:10 y no en 2:44 como Alonso compensaron as\u00ed su tiempo en boxes. Y, al detenerse los dos coches rojos, los rebasaron. Y s\u00ed, Chris Dyer cometi\u00f3 un error claro, con sus dos hombres perdiendo esa minutada, deber\u00eda haberlo mantenidos en pista (se habr\u00edan quedado detr\u00e1s de Hamilton) para que abrieran hueco con los de detr\u00e1s con la pista abierta. Con Kobayashi detr\u00e1s, en cinco vueltas habr\u00edan podido minimizar los da\u00f1os. <\/p>\n<p>P.- Hola Carlos. Ferrari va bien en Barhein, M\u00f3naco, Canad\u00e1, Hungr\u00eda, Valencia y pocos m\u00e1s y est\u00e1n teniendo muy mala suerte de momento. \u00bf Crees que Ferrari puede luchar por la victoria en otros circuitos? \u00bfCu\u00e1les? <\/p>\n<p>R.- Hey, que no me he ido. Disculpad. Pues s\u00ed, eso es lo malo que no ha ganado en pistas favorables como Monac\u00f3, Canad\u00e1 o Valencia. Silverstone en teor\u00eda es mala, pero puede luchar por ganar en Hockenheim e Hungr\u00eda.<\/p>\n<p>P.- Hola Carlos \u00bfque opinas de la sancion a alonso el dia de hungri cuando le sancionaron 5 puestos por salir mas tarde del pit stop despues de haber hecho pole?\u00bfCrees que sin esa sancion alonso habria sido campeon del mundo con mc-laren?<\/p>\n<p>R.- Est\u00e1 claro que habr\u00eda sido campe\u00f3n de no recibir esa sanci\u00f3n inventada en un despacho de par\u00eds. Medaia hora antes de conocerse se dio una clasificaci\u00f3n oficial en la que estaba en la pole. No se hizo referencia a ning\u00fan art\u00edculo y se invent\u00f3 la sanci\u00f3n. Yo tamb\u00ed\u00e9n me acord\u00e9 el otro d\u00eda de Hungr\u00eda. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pol\u00e9mica vuelve a protagonizar el mundial m\u00e1s igualado de los \u00faltimos a\u00f1os. La permisividad con Hamilton est\u00e1 empezando a cansar al resto de pilotos, que denuncian un trato de favoritismo hacia el piloto ingl\u00e9s. Carlos Miquel ha charlado con los internautas sobre este pol\u00e9mico asunto, as\u00ed como sobre el resto de lo sucedido en Valencia.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-10774","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/10774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=10774"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/10774\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=10774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=10774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=10774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}