{"id":10579,"date":"2010-06-09T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=10579"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"William_Boyd10579","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/William_Boyd10579\/","title":{"rendered":"William Boyd"},"content":{"rendered":"<p>Pregunta.- Estimado Mr. Boyd, Mi novia admira produndamente su obra, y me ha despertado un gran inter\u00e9s de leer sus novelas, \u00bfpor cu\u00e1l me recomendar\u00eda usted comenzar?<\/p>\n<p>Respuesta.- Si te gustan las novelas c\u00f3micas comienza con Armadillo, si te gustan las novelas m\u00e1s complejas comienza con La playa de Brazzaville. Si te gusta el espionaje lee Sin Respiro, pero siempre prefiero la \u00faltima, Tormentas Cotidianas. <\/p>\n<p>P.- Dr. Boyd: \u00bfMe podr\u00eda decir si el titulo &#8220;Bambu&#8221; de su obra, tiene que ver con que lo que sucede en ella se desarrolla en un lugar del Oriente? Muy agradecida.<\/p>\n<p>R.- No, es una met\u00e1fora sobre el periodismo (es una colecci\u00f3n de algunos de mis ensayos). El t\u00edtulo cita un proverbio chino que me inspir\u00f3: &#8220;Planta un brote de Bamb\u00fa, cortar\u00e1s bamb\u00faes el resto de tu vida&#8221;. <\/p>\n<p>P.- \u00bfCu\u00e1l ha sido la novela que te ha resultado m\u00e1s dif\u00edcil de escribir? <\/p>\n<p>R.- Quiz\u00e1 Las aventuras de un hombre cualquiera, porque cuenta la historia de una vida entera. La novela abarca un periodo que comienza en 1906-1991 y toma la forma de un diario \u00edntimo. Por supuesto un diario se escribe d\u00eda tras d\u00eda sin saber qu\u00e9 suceder\u00e1 al d\u00eda siguiente. Fue muy dif\u00edcil reproducir esta espontaneidad. Se necesita mucho arte para que parezca que no hay ninguno. <\/p>\n<p>P.- \u00bfPor qu\u00e9 le fascina tanto la Primera Guerra Mundial?<\/p>\n<p>R.- Creo que es un fen\u00f3meno brit\u00e1nico, todav\u00eda estamos obsesionados con la Primera Guerra Mundial, en mi caso, mi abuelo y mi tio abuelo estuvieron en las trincheras, ambos sobrevivieron, los dos fueron heridos. Forma parte de mi leyenda familiar. <\/p>\n<p>P.- \u00bfC\u00f3mo sobrevivir\u00eda William Boyd en Londres sin m\u00f3vil, sin tarjeta de cr\u00e9dito, sin dinero ni pasaporte?<\/p>\n<p>R.- Encontrar\u00eda un lugar seco para dormir, buscar comida alrededor de los restaurantes de comida r\u00e1pida, y despu\u00e9s, pedir limosna amablemente a la gente. <\/p>\n<p>P.- Su amor por la poes\u00eda \u00bfle allana el camino como novelista?<\/p>\n<p>R.- Es una pregunta muy interesante. Muchos novelistas leen poes\u00eda, a veces leen m\u00e1s poes\u00eda que novelas. Los poetas que m\u00e1s lees y relees sirven para inspirar no tanto las historias que cuentas sino el lenguaje que utilizas. <\/p>\n<p>P.- Sr. Boyd me gustaria saber que autores le han influido m\u00e1s en su obra literaria, gracias.<\/p>\n<p>R.- Es dif\u00edcil decirlo, porque ense\u00f1\u00e9 Literatura Inglesa durante 12 a\u00f1os en la universidad. He le\u00eddo todo, pero los autores que he rele\u00eddo son una extra\u00f1a mezcla; por ejemplo: dos rusos, Vladimir Nabokov, Anton Chejov; dos ingleses, Charles Dickens, Evelyn Waugh; una escocesa, Muriel Spark; dos norteamericanos, John Updike, Philip Roth. <\/p>\n<p>P.- Usted es un gran admirador de Francia, sino me equivoco usted tiene una mansi\u00f3n en el sur del pa\u00eds. A vuestro parecer, \u00bfcu\u00e1les son los autores m\u00e1s brillantes en la lengua de Moli\u00e8re?<\/p>\n<p>R.- Vamos a decir que no es una mansi\u00f3n, sino antigua casa de campo con unos vi\u00f1edos en donde fabricamos vino Le Pecachard. Los autores franceses que admiro son: Flaubert, Balzac, Camus, Michel Tournier, Alain Fournier. <\/p>\n<p>P.- Naci\u00f3 en Sud\u00e1frica, de origen familiar escoc\u00e9s y vive en Londres. \u00bfC\u00f3mo lleva esa mezcla? <\/p>\n<p>R.- Es el oeste de \u00c4frica, no Sur \u00c1frica. Lo llevo bastante bien, porque no puedes controlar de d\u00f3nde son tus padres, tampoco el lugar en donde naciste. Cuando alguien me pregunta de d\u00f3nde soy me toma algo de tiempo responder, creo que es por esta raz\u00f3n que me interesan las cuestiones sobre la identidad, y este es un tema central en mi nueva novela Tormentas Cotidianas (Duomo Ediciones).<\/p>\n<p>P.- Hola, nunca habia leido un libro suyo hasta ahora, con &#8220;Tormentas Cotidianas&#8221;, y debo decir que me ha encantado. \u00bfTiene pensado escribir una segunda parte? Muchas gracias<\/p>\n<p>R.- No, porque no me gustan las secuelas. Pero estamos en el proceso de transformarlo en un gui\u00f3n para el cine. Si la pel\u00edcula es exitosa estoy seguro de que habr\u00e1 una Tormentas Cotidianas 2. <\/p>\n<p>P.- \u00bfAlguna de tus obras ha resultado tan compleja de elaborar hasta el punto de querer renunciar a ella?<\/p>\n<p>R.- No, porque mi m\u00e9todo de trabajo es muy particular. Dedico el doble de tiempo a la preparaci\u00f3n y resoluci\u00f3n de la trama antes de escribir la novela. Nunca comienzo una novela hasta que no s\u00e9 c\u00f3mo finalizar\u00e1. As\u00ed que cometo todos los errores antes de si quiera escribir la primera palabra. <\/p>\n<p>P.- Se\u00f1or Boyd, \u00bfpodr\u00eda explicarnos qu\u00e9 papel tiene Londres en &#8220;Tormentas cotidianas&#8221;?<\/p>\n<p>R.- Londres y el r\u00edo T\u00e1mesis son casi como protagonistas de la novela. He vivido en Londres durante 27 a\u00f1os y creo que es la ciudad m\u00e1s fascinantes y complejas del planeta. Por eso quer\u00eda presentar un retrato de de esta extraordinaria ciudad en la novela. <\/p>\n<p>P.- Le\u00ed su ensayo sobre la escritura de diarios en su edici\u00f3n inglesa de Bamboo. D\u00edgame, \u00bfno cree que un diario, por muy veraz que se quiera ya que hay una relaci\u00f3n directa entre quien escribe y lo que dice que le ocurre, no deja de ser, en \u00faltimo t\u00e9rmino, una escritura tan ficcional como puede serlo la autobiograf\u00eda? Un saludo.<\/p>\n<p>R.- Hay un riesgo, digamos, de que un diario se pueda manipular, estos diarios est\u00e1n escritos con el prop\u00f3sito de una posible publicaci\u00f3n, incluso que \u00e9sta sea p\u00f3stuma, por ejemplo los diarios de Virginia Woolf. Los grandes diarios literarios han sido escritos sin ninguna expectativa de ser le\u00eddos. Algunos ejemplos son: los diarios de James Boswell y Samuel Pepys. Mi diario pertenece a la segunda categor\u00eda. <\/p>\n<p>P.- Respecto al reciente cambio pol\u00edtico en Reino Unido, \u00bfqu\u00e9 opini\u00f3n le merece el nuevo gobierno de Mr. Cameron? \u00bfSe moja usted en pol\u00edtica?<\/p>\n<p>R.- Si, ning\u00fan problema, me &#8220;mojo&#8221;. Sospecho mucho de Mr. Cameron porque \u00e9l viene de la vieja \u00e9lite priviilegiada que ha gobernado el Reino Unido por siglos. Pienso que esta sospecha es compartida por el pueblo ingl\u00e9s porque ellos no le dieron la mayor\u00eda y lo forzaron a formar una coalici\u00f3n con un partido que mantendr\u00e1 bajo control sus instintos elitistas.<\/p>\n<p>P.- \u00bfQue le aconsejar\u00eda a un principiante escritor? Gracias<\/p>\n<p>R.- Necesitas reunir tres cualidades para ser un buen novelista: 1. Por supuesto, tienes que escribir bien. Con esto quiero decir que debes ser capaz de comunicarte de una manera interesante y elegante. 2. Tiene que gustarte mucho observar el mundo pasar delante tuyo. Debes ser un observador obsesivo del &#8220;cine de la vida cotidiana&#8221;. Un retraso de seis horas en un aeropuerto deber\u00eda ser un verdadero placer. 3. Debes tener una imaginaci\u00f3n f\u00e9rtil. Debes ser capaz de imaginar cosas que nunca has vivido o que jam\u00e1s podr\u00edas experimentar. Si re\u00fanes estas tres habilidades est\u00e1s listo para empezar. S\u00f3lo puedes aprender la primera de las cualidades. Las otras dos son dones.<\/p>\n<p>P.- Anteriormente en una pregunta, ha contestado que &#8220;muchos novelistas leen poes\u00eda, a veces leen m\u00e1s poes\u00eda que novelas&#8221;. Si este es su caso, \u00bfEn que poetas se ha inspirado para sus novelas? Gracias<\/p>\n<p>R.- Los poetas que voy a citar son ingleses o americanos, y sin orden de preferencia; Elizabeth Bishop, Philip Larkin, Wallace Stevens, Seamus Heaney, Ted Hughes y Jamie McKendrick. <\/p>\n<p>P.- En una entrevista de tiempo atr\u00e1s, declar\u00f3 usted que el cuento es una especie de &#8220;campo de preparac\u00f3n&#8221; para llegar a la novela. \u00bfEso significa que considera a el cuento un genero menor?. Gracias.<\/p>\n<p>R.- No, creo que un cuento y una novela son sorprendentemente diferentes. Se escriben de diferente manera y se leen de diferente manera. No es una cuest\u00ed\u00f3n de extensi\u00f3n. Creo que las dos son formas de arte y tienen el mismo valor. Algunas personas describen el cuento como un cuarteto de cuerdas y lo comparan con la novela que ser\u00eda una orquesta sinf\u00f3nica. Esta es una met\u00e1fora fallida porque implica una diferencia en fuerza. Es mejor pensar que las dos son formas po\u00e9ticas: El poema l\u00edrico y el poema \u00e9pico, esta comparaci\u00f3n no implica que uno sea inferior al otro. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los Grandes nombres internacionales de la literatura es William Boyd, autor de libros como Bamb\u00fa y Tormentas cotidianas(Duomo). El escritor brit\u00e1nico ha charlado con los internautas sobre su obra coincidiendo con la Feria del Libro. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-10579","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/10579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=10579"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/10579\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=10579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=10579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=10579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}