{"id":10477,"date":"2010-06-02T00:00:00","date_gmt":"2006-11-06T00:00:00","guid":{"rendered":"https:\/\/intervius.com\/index.html\/?p=10477"},"modified":"2006-11-06T00:00:00","modified_gmt":"2006-11-06T00:00:00","slug":"Quico_Taronji10477","status":"publish","type":"post","link":"https:\/\/intervius.com\/index.html\/Quico_Taronji10477\/","title":{"rendered":"Quico Taronj\u00ed"},"content":{"rendered":"<p>Pregunta.- hola! me gustaria saber si despues del tiempo que a pasado en k los chicos han salido del refigio,como estan, la verdad que el programa me ha encantado,ya que tambien estoy estudiando trabajadora social para poder ayudar a personas con estos problemas,me siento muy identificada ya que lo he vivido con un hermano mio que gracias a Dios ya ha salido,me gustaria saber como estan los chicos, la verdad que pienso mucho en ellos y me gustaria saber como se encuentrar a dia de hoy,gracias.Cristi<\/p>\n<p>Respuesta.- Ver\u00e1s, Cristina, por las \u00faltimas noticias que tengo, de los 10 que comenzaron el tratamiento, 7 han dejado de consumir drogas. El dato representa un 70% de los pacientes que entr\u00f3 en El Refugio. De esos 7, casi todos contin\u00faan su tratamiento en distintos centros, o bien de forma permanente (los que m\u00e1s problemas tienen para dejar definitivamente la droga), o de manera ambulatoria. El camino para ellos es largo y no terminar\u00e1 hasta dentro de muchos meses. Espero que en ese tiempo no haya reca\u00eddas. Yo seguir\u00e9 en contacto con ellos. Para que te hagas una idea, el porcentaje medio de rehabilitaci\u00f3n, despu\u00e9s de largos programas en centros, se acerca a ese dato del 70%, y eso incluye los casos en los que hay periodos de reca\u00eddas durante el tratamiento. Sin reca\u00eddas (por ejemplo: que alguien entre en un centro con una adicci\u00f3n y se recupere sin volver a consumir m\u00e1s), el dato est\u00e1 alrededor de un 40-45% de casos con final feliz. Un abrazo, Cristina. <\/p>\n<p>P.- \u00bfQu\u00e9 ten\u00e9is en cuenta para coger a unos adictos y no a otros? Creo que lo m\u00e1s importante es que quieran quitarse y hacer una nueva vida, vosotros ve\u00edais a Gema con ganas de quitarse? En esos casos pod\u00edais tener &#8220;reservas&#8221; porque es una pena que otro pierda esa gran oportunidad. (aunque cierto es que en todas las ciudades hay centros&#8230;). Un Bso<\/p>\n<p>R.- Nos centramos, sobre todo, en que estuvieran representadas en el programa variedad de adiciones, para que todos pudi\u00e9semos ver las diferencias entre los pacientes de unas y otras. Por otro lado, dimos mucha importancia al hecho de que los pacientes estuvieran decididos a asumir el tratamiento y a que contaran con el apoyo familiar, porque nos parec\u00eda fundamental que una vez terminado el programa, continuaran su tratamiento en otros centros. Y eso siempre es m\u00e1s f\u00e1cil si en casa te animam a hacerlo. Gema ten\u00eda el apoyo de su madre, pero desgraciadamente la cosa no funcion\u00f3 para ella. Sab\u00edamos que pod\u00eda pasar, pero ten\u00edamos que intentarlo. No hubo pacientes \u201creserva\u201d, porque ingresar a nuevos pacientes durante el programa supon\u00eda hacer m\u00e1s lento el proceso para el resto, e incluso ponerlo en peligro, ya que, pasados los primeros d\u00edas, todos hab\u00edan asumido unas rutinas y estaban m\u00e1s centrados en el tratamiento. Por ejemplo, a partir de la primera semana, los pacientes tienen prohibido hablar de drogas y de consumo. Un nuevo paciente habr\u00eda entrado en El Refugio haci\u00e9ndolo. Es s\u00f3lo un ejemplo. Hay muchos m\u00e1s. Siempre hicimos lo que el equipo m\u00e9dico consider\u00f3 m\u00e1s oportuno para garantizar el \u00e9xito del tratamiento. Espero haber resuelto la duda. Un abrazo. <\/p>\n<p>P.- \u00bfque le dirias a un adicto a una droga y esta pidiendote ayuda ?? gracias x contestar<\/p>\n<p>R.- Hola, Jazmina. Mira, yo puedo hablar de mi experiencia y aprendizaje en El Refugio, pero soy periodista, no terapeuta, y podr\u00eda meter la pata si te sugiero pautas a seguir en ese sentido. Te aconsejo que acudas a un centro especializado, y que all\u00ed te indiquen qu\u00e9 hacer. Te garantizo que eso es lo que yo har\u00eda si estuviera en tu lugar. Abrazo, Jazmina. <\/p>\n<p>P.- quico volveremos a saber algo de los chicos alos que hemos seguido el programa nos encantaria saberlo gracias espero tu respuesta<\/p>\n<p>R.- Pues no lo s\u00e9. El programa ya ha terminado. Los especialistas seguir\u00e1n en contacto con ellos, y yo tambi\u00e9n lo intentar\u00e9, pero no s\u00e9 si con el paso del tiempo el espectador tendr\u00e1 noticias de ellos. No lo s\u00e9. No depende de m\u00ed. Esa es una decisi\u00f3n que corresponde tomar a la cadena, y yo ah\u00ed no puedo entrar. Espero que lo comprendas. Un abrazo. <\/p>\n<p>P.- Hola Quico, me gustar\u00eda saber cu\u00e1l ha sido tu sentimiento despu\u00e9s de hacer la edici\u00f3n de Soy adicto. \u00bfNo es muy dif\u00edcil no involucrarse emocionalmente en un proyecto con personas tan sensibles? Os felicito por lo que hab\u00e9is hecho. Un abrazo desde Catalu\u00f1a<\/p>\n<p>R.- Hola, Rosa. La verdad es que es casi imposible no implicarse en el proceso. Yo lo hice, y aprend\u00ed much\u00edsimo sobre el asunto de las drogas, y adem\u00e1s, comprend\u00ed muchos aspectos del consumo que no ten\u00eda tan claros antes de iniciar el rodaje de Soy Adicto. Sigo en contacto con los chicos, y supongo que no dejar\u00e9 de hacerlo. Al menos, seguir\u00e9 en contacto con algunos de ellos. Hacer un programa as\u00ed es emocionante y te hace part\u00edcipe de la esperanza en la rehabilitaci\u00f3n definitiva que tienen muchos adictos y sus familiares. El proyecto te abre los ojos y te recuerda que nadie est\u00e1 exento de caer en las drogas. Absolutamente nadie. Un abrazo, Rosa. <\/p>\n<p>P.- \u00bfCrees que pudo afectar al tratamiento la presencia de las c\u00e1maras? \u00bfQue por ese motivo hubo tantas peleas y mal rollo?<\/p>\n<p>R.- No, no. Las peleas y los roces y mal rollo, como dices, son habituales en todos los centros. Ten en cuenta que los pacientes est\u00e1n sometidos a una disciplina a la que no est\u00e1n acostumbrados, que viven con sus emociones a flor de piel, y que la convivencia no es f\u00e1cil. No hace falta m\u00e1s que echar un ojo a otros programas de la tele en los que los participantes conviven. Las broncas est\u00e1n a la orden del d\u00eda. Y, supuestamente, no son consumidores habituales de drogas. Las c\u00e1maras s\u00f3lo muestran lo que sin ellas tambi\u00e9n ocurre. La actitud de los participantes puede estar condicionada por las c\u00e1maras durante las primeras horas, despu\u00e9s todos nos mostramos como somos. La presencia de las c\u00e1maras se olvida inconscientemente. Est\u00e1 demostrado. Un abrazo. <\/p>\n<p>P.- La verdad es que tengo tantas preguntas que no s\u00e9 cual ser\u00eda la \u00fanica que te har\u00eda&#8230;,no s\u00e9, por que una vez que pruebas una sustancia, en mi caso la coca,bueno y muchas otras, pero \u00e9sta fu\u00e9 la que creo que jodi\u00f3 m\u00ed vida profesional, se te hace tan dif\u00edcil remontar la vida. Yo siempre pienso en darme un \u00faltimo viaje y dejar pasar todo, joder pero cuando me pego la fiesta digo: venga vamos a seguir, pero con trankilizantes y ese rollo.Parece que estoy metido en una espiral y que me es imposible salir, no s\u00e9 pero creo que \u00e9sta sustancia es tan fuerte que es casi por no decir imposible dejarla, a no ser que te cambie la vida por completo, y aun as\u00ed no s\u00e9, son todo dudas, creo que tendr\u00e9 que llevarla de equipaje toda m\u00ed vida quico, asi que ya v\u00e9s \u00a1. Hay gente que tenemos el destino marcado y s\u00f3lo podemos ir ganando las batallas pero n\u00fanca lograremos ganar la guerra por que creo que en realidad eso es para lo que estamos destinados y es nuestro presente y futuro, aunque nos joda. MEJOR NO HABERLA PROBADO NUNCA, ESO ES LA PU\u00d1ETERA VERDAD.<\/p>\n<p>R.- El \u00fanico consejo v\u00e1lido que puedo darte es que en un momento de lucidez como el que tienes al escribir estas lineas y decidirte a enviarnoslas, acudas a un centro especializado en rehabilitaci\u00f3n de adictos. S\u00f3lo all\u00ed podr\u00e1n ayudarte de verdad. Todas esas veces en las que piensas que t\u00fa solo podr\u00e1s resolver el problema, se\u00f1alan tus momentos de asunci\u00f3n del problema. Es decir, que cuando asumes que tienes un problema, est\u00e1s mostrando una lucidez que no disfrutas en momentos de consumo. Esos son los momentos en los que debes decidirte de una vez por todas a acudir a un centro. No tienes m\u00e1s opciones. No le des m\u00e1s vueltas y act\u00faa. Un abrazo muy fuerte. Te deseo suerte. \u00c1nimo. <\/p>\n<p>P.- hola quico , no se si te habra llegado la pregunta de antes porke me dio problemas la linea , me llamo juan antonio nu\u00f1ez , tengo 35 a\u00f1os , a principio de este mes prove la cocaina , y la verdad me e dado cuenta de lo malo ke es eso y de ke te arruina la vida , no me gustaria perder a la mujer ke tengo ahora , ya ke la kiero con lokura y estoy esperando un hijo de ella , tengo dos ni\u00f1os mas de mi exmujer , a los cuales no me deja ver , aunke es por diferentes motivos, necesito ke me heches un cable si puede ser , ya ke no me gustaria caer mas hondo y creo ke aun estoy a tiempo , un salududo muy grande y un abrazo a toda la gente del refugio para que sean fuertes y dejen ese mundo . un abrazo a todos.<\/p>\n<p>R.- Hola, Juan Antonio. Te deseo lo mejor, y te digo exactamente lo mismo que a kwakiutl en el p\u00e1rrafo anterior. El mismo consejo sirve para los dos. Est\u00e1is en la misma situaci\u00f3n. Mucha suerte, y \u00e1nimo de veras, Juan Antonio. <\/p>\n<p>P.- has hecho una buena labor pero lo sencillo es dexintoxicarse pero la lucha esta en mantenerse sin drogas el drogadicto siempre busca una escusa de algun problema para drogarse por que &#8230;<\/p>\n<p>R.- Para evitar que eso ocurra no queda m\u00e1s remedio que continuar con el tratamiento y con la ayuda de especialistas a\u00fan cuando uno piense que ya ha superado el problema. Esa es la clave. S\u00f3lo el que es consciente de que el peligro de la reca\u00edda est\u00e1 ah\u00ed, a la vuelta de la esquina, sabr\u00e1 evitarlo. El portero de un quipo de f\u00fatbol no puede perder de vista el bal\u00f3n en ning\u00fan momento del partido. El adicto no puede tener conciencia err\u00f3nea de lo que pasa a su alrededor. La pelota de la droga siempre est\u00e1 en juego, y la \u00fanica forma de evitar el gol en contra es seguirla en todo momento. Un abrazo.<\/p>\n<p>P.- lo mio mas que una pregunta es pedir consejo!!! mi novio yeva sin consumir cocaina casi un a\u00f1o!!bueno cuando yo lo conoci yevava tres meses sin consumir, esta en tratamiento, pero esta muy suscestible a todo, me grita sin motivo, se enfada sin motivo, no podemos salir a ningun lado por que en cuanto ve a dos chicos entrar juntos en el ba\u00f1o empieza a decir vamonos vamonos!!! estoy desesperada!! tanto que ya no somos novios!!!de un dia para otro me dejo sin mas, desconfia de mi continuamente,cuando le he demostrado que estoy a su lado para todo!!!he aguantado sus cambios de humor debido al proceso, he aguantado de todo!! y yo ahora lo que me siento es super decepcionada con el!!!tanto que yevamos dos meses sin hablar,yo en alicante y el en barcelona!!! lo he intentado todo para poder ayudarle y comprender que le paso para que todo saliese asi de mal entre los dos!! durante 4 mese que vivimos juntos mi vida se limito del trabajo a casa y de casa al trabajo, para que no se sientiese solo, ya que el lo dejo todo en barcelona para venir conmigo a alicante!!! y creo que el vio una buena escusa para romper con todo lo que havia vivido en barcelona , todo el tema de las drogas y las malas compa\u00f1ias!!!y yo creo que su cabeza se rayo demasiado aqui y lo pago todo conmigo!!! necesito ayuda para poder entender su comportamiento hacia ami!!! siempre me decia que yo havia estado en el proceso en el que el paso del monstruo a persona y creo que yo he pagado un precio muy caro por ello!!!! que hago? necesito un consejo, una respuesta?? necesito saber como me debo de comportar con el? que decirle? no se? estoy totalmente desesperada ya que solo quiero ayudar a la persona que mas quiero. muchas gracias.<\/p>\n<p>R.- Hola. Aqu\u00ed puedo opinar poco. Te aconsejo que hables con un psic\u00f3logo. Solamente un especialista podr\u00e1 ayudarte correctamente. Mis consejos no te valdr\u00edan demasiado, porque no os conozco personalmente a ninguno de los dos, y podr\u00eda confundirte en lugar de ayudarte. Te deseo toda la suerte del mundo. Abrazo. <\/p>\n<p>P.- Hola me llamo lilineth tengo 1 a\u00f1o de casada con fernando de 30 a\u00f1os somos de valencia y \u00e9l es adicto a la cocaina, marihuana , alcohol y tranquilizantes que puedo hacer para que el pueda dejarlo antes que mi paciencia se cabe. y mi preguntas seria \u00bfHabr\u00e1 otro edici\u00f3n de soy Adicto? para que tomen en cuenta mi petici\u00f3n que mi marido y yo miramos el programa todos los viernes y es momento que cuando el lo veo se identifica y comprende mi posici\u00f3n porque el quiere salir pero le cuenta muchisimo. Y si puedes darnos un consejo o decirnos donde podemos pedir ayuda para mi marido, Espero que aigan m\u00e1s personas como ustedes que quieran de coraz\u00f3n ayudar a personas con este problema.<\/p>\n<p>R.- Hola Lilineth. Te aconsejo que hables con un psic\u00f3logo. Te valdr\u00e1 el del centro especializado en desintoxicaci\u00f3n que haya en tu municipio. Si no sabes donde hay uno, acude a tu ayuntamiento y cuenta vuestro caso en Servicios Sociales. All\u00ed te dir\u00e1n qu\u00e9 hacer. En cuanto a lo de una segunda edici\u00f3n de Soy Adicto, pues no s\u00e9. No soy yo quien decide. Corresponde a la cadena tomar la decisi\u00f3n. Supongo que es pronto para saberlo. Abrazo, y mucho \u00e1nimo.<\/p>\n<p>P.- Hola.LLevo mas de 25 a\u00f1os consumiendo cannabis y aparte de ocasionarme problemas familiares tambien los tengo conmigo.Llevo 15 a\u00f1os iendo al psiquiatra del seguro pero es un autentico desatre ya que me ha servido para engancharme al trankimazin de 2 mg.Lo he intentado mil veces,he estado hasta 1 a\u00f1o sin fumar pero al final vuelvo a caer.Estube iendo al UCA pero no me sirvio de mucho ya que eren breves visitas cad 4 meses.Hace 4 a\u00f1os tuve un infarto y aunque hago algo de depore el fumar me lleva a no tener interes y dejarlo todo.\u00bfPor favor como podria dejar de consumir tanto el cannabis como los farmacos. Un saludo y enhorabuena por el programa<\/p>\n<p>R.- S\u00f3lo hay una forma: acudir a un centro y tomarse totalmente en serio el tratamiento. Dejar las drogas tambi\u00e9n es una cuesti\u00f3n de actitud. Ingresa en un centro y qu\u00e9date en \u00e9l el tiempo necesario. No puedo decirte mucho m\u00e1s. Te deseo mucha suerte. <\/p>\n<p>P.- \u00bfque puedo hacer con mi cu\u00f1ado que consume cocaina fumada en plata y no quiere ir a un centro por que niega estar enganchado?<\/p>\n<p>R.- Hola. Te aconsejo que acudas al centro al que le llev\u00e1rais y pregunt\u00e9is all\u00ed. Te dir\u00e1n que hacer. Yo no puedo deciros como se puede convencer a alguien de que est\u00e1 enganchado, porque no soy especialista y no s\u00e9 como hacerlo. Mucha suerte. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pregunta.- hola! me gustaria saber si despues del tiempo que a pasado en k los chicos han salido del refigio,como estan, la verdad que el programa me ha encantado,ya que tambien estoy estudiando trabajadora social<span class=\"theme-excerpt-more\"> [&#8230;] <a href=\"https:\/\/intervius.com\/index.html\/Quico_Taronji10477\/\" title=\"Quico Taronj\u00ed\">Read More<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-10477","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/10477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/comments?post=10477"}],"version-history":[{"count":0,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/posts\/10477\/revisions"}],"wp:attachment":[{"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/media?parent=10477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/categories?post=10477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervius.com\/index.html\/wp-json\/wp\/v2\/tags?post=10477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}